{"id":1205,"date":"2022-05-29T09:00:39","date_gmt":"2022-05-29T09:00:39","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=1205"},"modified":"2023-12-27T15:53:56","modified_gmt":"2023-12-27T14:53:56","slug":"bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten","title":{"rendered":"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten"},"content":{"rendered":"<p>Um erfolgreich zu g\u00e4rtnern, sollten Sie wissen, um welchen Bodentyp es sich handelt. Manche G\u00e4rten vereinen sogar unterschiedliche Bodentypen an einem Standort. Wissen Sie \u00fcber Ihren Bodentyp Bescheid, k\u00f6nnen Sie ihn mit N\u00e4hrstoffen auf die Bed\u00fcrfnisse verschiedener Pflanzen abstimmen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Verschiedene_Bodenarten_abhaengig_von_Bestandteilen_und_Korngroessen\"><\/span>Verschiedene Bodenarten: abh\u00e4ngig von Bestandteilen und Korngr\u00f6\u00dfen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4659 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_2579122.jpg\" alt=\"Bodenarten\" width=\"300\" height=\"200\" \/>Nicht nur von der Sonneneinstrahlung und -intensit\u00e4t, sondern auch von Ihrem Boden h\u00e4ngt es ab, welche Pflanzen sich in Ihrem Garten wohlf\u00fchlen. Der Boden gibt den Pflanzen Halt, versorgt sie mit N\u00e4hrstoffen und speichert Wasser. Die verschiedenen Pflanzen haben sich abh\u00e4ngig von ihrer Herkunft an unterschiedliche Bodenarten angepasst. Die Bodentypen sind im Laufe der Zeit durch Gew\u00e4sserbewegungen, Temperaturen, Niederschl\u00e4ge, Wind und den Eintrag von Gesteinsstaub entstanden. Die Bodentypen werden nach ihrer Zusammensetzung aus unterschiedlichen Korngr\u00f6\u00dfen in diese Arten eingeteilt:<\/p>\n<ul>\n<li>Sandboden<\/li>\n<li>Schluffboden<\/li>\n<li>Lehmboden<\/li>\n<li>Tonboden<\/li>\n<\/ul>\n<p>Die Bodentypen sind durch die vorherrschenden Korngr\u00f6\u00dfen bestimmt. Bei Sandboden ist die K\u00f6rnung am gr\u00f6bsten, w\u00e4hrend Tonboden die feinste K\u00f6rnung hat. Die Korngr\u00f6\u00dfe entscheidet dar\u00fcber, wie gut Boden Wasser speichern kann. Kennen Sie den Bodentyp Ihres Gartens, k\u00f6nnen Sie ihn mit gezielten Ma\u00dfnahmen verbessern und auf die Bed\u00fcrfnisse der verschiedenen Pflanzen abstimmen. Es gibt keinen guten oder schlechten Boden, da jeder Bodentyp seine Vor- und Nachteile hat. Im Idealfall ist der Boden durchl\u00e4ssig, aber auch reich an N\u00e4hrstoffen und Humus.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Bodentypen_Eigenschaften_und_gaertnerische_Nutzung\"><\/span>Bodentypen: Eigenschaften und g\u00e4rtnerische Nutzung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Bodentypen werden nicht nur nach Sandboden, Schluffboden, Lehmboden und Tonboden unterschieden. Aus g\u00e4rtnerischer Sicht erfolgt eine Unterscheidung auch in leichte und schwere B\u00f6den. Abh\u00e4ngig vom Humusgehalt werden humusarme und humusreiche B\u00f6den unterschieden. Eine Unterscheidung erfolgt auch nach pH-Wert oder Kalkanteil in saure (schwach kalkhaltige) und alkalische oder basische (stark kalkhaltige) B\u00f6den. Mit der Zugabe von Humus oder Kalk k\u00f6nnen Sie die Bodentypen verbessern, um die gew\u00fcnschten Pflanzen anbauen zu k\u00f6nnen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sandboden_grobe_Koernung_mit_starker_Wasserdurchlaessigkeit\"><\/span>Sandboden: grobe K\u00f6rnung mit starker Wasserdurchl\u00e4ssigkeit<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4662 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_114048379-300x200.jpeg\" alt=\"Sandboden Melone\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_114048379-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_114048379-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_114048379-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_114048379-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_114048379-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_114048379-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Sandboden weist eine grobe K\u00f6rnung auf, l\u00e4sst viel Wasser durch, kann kaum Wasser speichern und ist n\u00e4hrstoffarm. Staun\u00e4sse tritt so gut wie nie auf. Er ist gut durchl\u00fcftet, l\u00e4sst sich leicht bearbeiten und ist gut durchwurzelbar. Da Mikroorganismen sehr aktiv sind, bauen sie organische Reste schnell ab, sodass Humus kaum entstehen kann. Der pH-Wert von Sandboden ist instabil und l\u00e4sst sich leicht von Kalk und S\u00e4uren beeinflussen. D\u00fcngen und w\u00e4ssern Sie Sandboden regelm\u00e4\u00dfig, aber nur in kleinen Dosierungen. Verbessern l\u00e4sst sich Sandboden durch die Beimengung von Kalk, Humus, Lehm und Ton, aber auch durch Mulchen. Auf Sandb\u00f6den gedeihen beispielsweise<\/p>\n<ul>\n<li>Spargel,<\/li>\n<li>Karotten,<\/li>\n<li>Paprika,<\/li>\n<li>Melonen und<\/li>\n<li>Kr\u00e4uter.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Schluffboden_mittlere_Wasserfuehrung_und_gute_Speichereigenschaften\"><\/span>Schluffboden: mittlere Wasserf\u00fchrung und gute Speichereigenschaften<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4664 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_267744508-300x200.jpeg\" alt=\"Schluffboden Kartoffeln\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_267744508-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_267744508-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_267744508-768x513.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_267744508-2048x1367.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_267744508-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_267744508-1536x1025.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Schluffboden weist eine mittlere Korngr\u00f6\u00dfe auf und vereint die Eigenschaften von Sand und Ton. Die Korngr\u00f6\u00dfe gew\u00e4hrleistet eine mittlere Wasserf\u00fchrung und ein gutes Speicherverm\u00f6gen. Die Porengr\u00f6\u00dfe zwischen den einzelnen Bodenpartikeln ist g\u00fcnstig f\u00fcr das Pflanzenwachstum, da das Wasser zwar aufgesaugt, aber auch ohne Widerstand wieder abgegeben wird. Die Wurzeln der Pflanzen erzeugen einen Unterdruck zur Aufnahme von Wasser. Schluffboden ist locker, l\u00e4sst sich leicht bearbeiten und ist reich an N\u00e4hrstoffen, da die Mikroorganismen viel Humus produzieren. Schluffboden z\u00e4hlt zu den ertragreichsten B\u00f6den und weist eine gute Durchl\u00fcftung auf. Er ist aufgrund seiner guten Eigenschaften geeignet f\u00fcr<\/p>\n<ul>\n<li>Kartoffeln,<\/li>\n<li>H\u00fclsenfr\u00fcchte wie Bohnen und Erbsen,<\/li>\n<li>Starkzehrer wie Kohlpflanzen sowie f\u00fcr<\/li>\n<li>Gurken, Tomaten und K\u00fcrbis.<\/li>\n<\/ul>\n<p><strong>Tipp:<\/strong> Lassen Sie Schluffboden nie brach liegen, da er bei Trockenheit eine geringe Verklebung aufweist und vom Wind fortgetragen werden kann. Bauen Sie beispielsweise nach der Ernte eine Gr\u00fcnd\u00fcngung an.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Tonboden_kleinste_Koernung_und_schlechte_Wasserfuehrung\"><\/span>Tonboden: kleinste K\u00f6rnung und schlechte Wasserf\u00fchrung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4661 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_75073445-300x200.jpeg\" alt=\"Tonboden Mangold\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_75073445-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_75073445-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_75073445-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_75073445-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_75073445-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_75073445-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Tonboden hat die feinste K\u00f6rnung und daher zwischen den Partikeln nur winzige Poren, in denen sich viel Wasser bindet. Er ist die schwerste Bodenart und durch schlechte Durchl\u00fcftung, Bearbeitbarkeit und Wasserf\u00fchrung gekennzeichnet. Er ist reich an N\u00e4hrstoffen und hat eine hohe Speicherkapazit\u00e4t. Die Tonminerale k\u00f6nnen schrumpfen und quellen. Haben die Wasser aufgesaugt, ist die Bel\u00fcftung stark eingeschr\u00e4nkt, weshalb viele Pflanzen und Mikroorganismen Tonboden nicht gut vertragen. Da er kaum von Kalk und S\u00e4uren beeinflusst wird, ist der pH-Wert ziemlich stabil. Auf Tonboden f\u00fchlen sich nur wenige Pflanzen wohl, beispielsweise Zitronenmelisse, Minze und Mangold.<\/p>\n<p><strong>Tipp:<\/strong> Mischen Sie Tonboden mit Sand, um ihn durchl\u00e4ssiger f\u00fcr Wasser zu machen. Verbessern Sie die Bodenstruktur, indem Sie ihn mit Kompost anreichern. Die Bodenstruktur l\u00e4sst sich auch mit einer Gr\u00fcnd\u00fcngung verbessern.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Lehmboden_eine_gesunde_Mischung\"><\/span>Lehmboden: eine gesunde Mischung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4660 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_32105946-300x261.jpeg\" alt=\"Lehmboden Fenchel\" width=\"300\" height=\"261\" \/>Lehmboden weist eine gesunde Mischung aus Sand, Ton und Schluff auf. Da alles in ausreichender Menge vorhanden ist, eignet er sich f\u00fcr viele Pflanzenzarten. Lehmboden weist eine mittlere Speicherkapazit\u00e4t f\u00fcr Wasser auf, das von den Pflanzen gut genutzt werden kann. Lehmboden ist n\u00e4hrstoffreich, da er im Humus und im Ton viele N\u00e4hrstoffe speichern kann. Aufgrund des Sandanteils ist eine gute Bel\u00fcftung gew\u00e4hrleistet. Allerdings kann sich Lehmboden schwer bearbeiten lassen, wenn er viel Wasser gespeichert hat. Lehmboden eignet sich f\u00fcr den Anbau von<\/p>\n<ul>\n<li>Fenchel,<\/li>\n<li>Basilikum,<\/li>\n<li>Dill,<\/li>\n<li>Rosmarin,<\/li>\n<li>Liebst\u00f6ckel,<\/li>\n<li>Salbei und<\/li>\n<li>Schnittlauch.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Bodentyp_selbst_bestimmen_die_Fingerprobe\"><\/span>Bodentyp selbst bestimmen: die Fingerprobe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4665 size-full\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_331061510.jpg\" alt=\"Bodenarten bestimmen\" width=\"300\" height=\"128\" \/><\/p>\n<p>Mit einer Bodenanalyse erhalten Sie eine genaue Auskunft dar\u00fcber, welcher Boden sich in Ihrem Garten befindet und was er noch brauchen k\u00f6nnte, um beste Wachstumsbedingungen zu bieten. Von mehreren Stellen in Ihrem Garten nehmen Sie Bodenproben, die Sie mit dem Standort beschriften. Etwa alle drei bis f\u00fcnf Jahre sollten Sie eine Bodenanalyse vornehmen lassen.<\/p>\n<p>Alternativ zu einer Bodenanalyse k\u00f6nnen Sie mit einer Fingerprobe den Bodentyp selbst bestimmen. Entnehmen Sie Proben von verschiedenen Standorten in Ihrem Garten aus Tiefen von 5 bis 20 Zentimetern. Verwenden Sie die oberen f\u00fcnf Zentimeter nicht, da sie stark durchwurzelt und mit organischem Material versetzt sind. Feuchten Sie den Boden an. Er sollte weder nass noch trocken sein. Mit der Rollprobe kneten Sie einen walnussgro\u00dfen Teil des Bodens in Ihrer Hand und rollen ihn dann zu einer bleistiftstarken Walze:<\/p>\n<ul>\n<li>L\u00e4sst sich die Probe nicht ausrollen, handelt es sich um Sandboden. In der Hand f\u00fchlt er sich rau und kratzig an.<\/li>\n<li>L\u00e4sst sich die Probe ausrollen und zerbr\u00f6ckelt sie beim wiederholten Ausrollen, ist es Schluff. Er f\u00fchlt sich samtig und mehlig an und haftet zwischen denn Fingerrillen.<\/li>\n<li>Mit Ton haben Sie es zu tun, wenn sich die Probe wiederholt ausrollen und kneten l\u00e4sst. Er f\u00fchlt sich schmierig an und ist klebrig.<\/li>\n<li>F\u00fchlt sich der Boden undefinierbar an und weist er die Eigenschaften von Sand, Schluff und Ton auf, ist es Lehmboden.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Zeigerpflanzen_Hinweise_auf_die_Bodenart_erhalten\"><\/span>Zeigerpflanzen: Hinweise auf die Bodenart erhalten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4663 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Bodenbeschaffenheit_242591395-300x133.jpeg\" alt=\"Boden Zeigerpflanzen\" width=\"300\" height=\"133\" \/>H\u00e4ufig werden Bodenart und Bodentyp synonym verwendet. Als Bodenart wird nur der obere Teil des Bodens bezeichnet, der am st\u00e4rksten durchwurzelt ist. Der Bodentyp weist noch weitere Eigenschaften auf und betrifft auch die tieferen Schichten. Zeigerpflanzen informieren dar\u00fcber, welche Bodenart vorliegt:<\/p>\n<ul>\n<li><strong>Saurer Boden:<\/strong> Sauerampfer<\/li>\n<li><strong>Stickstoffarmer Boden:<\/strong> Scharfer Mauerpfeffer<\/li>\n<li><strong>Stickstoffreicher Boden:<\/strong> Vogelmiere, Melde, L\u00f6wenzahn, Brennnessel<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Um erfolgreich zu g\u00e4rtnern, sollten Sie wissen, um welchen Bodentyp es sich handelt. Manche G\u00e4rten vereinen sogar unterschiedliche Bodentypen an einem Standort. Wissen Sie \u00fcber Ihren Bodentyp Bescheid, k\u00f6nnen Sie ihn mit N\u00e4hrstoffen auf die Bed\u00fcrfnisse verschiedener Pflanzen abstimmen. Verschiedene Bodenarten: abh\u00e4ngig von Bestandteilen und Korngr\u00f6\u00dfen Nicht nur von der Sonneneinstrahlung und -intensit\u00e4t, sondern auch von Ihrem Boden h\u00e4ngt es ab, welche Pflanzen sich in Ihrem Garten wohlf\u00fchlen. Der Boden gibt den Pflanzen Halt, versorgt sie mit N\u00e4hrstoffen und speichert Wasser. Die verschiedenen Pflanzen haben sich abh\u00e4ngig von ihrer Herkunft an unterschiedliche Bodenarten angepasst. Die Bodentypen sind im Laufe der Zeit durch Gew\u00e4sserbewegungen, Temperaturen, Niederschl\u00e4ge, Wind und den Eintrag von Gesteinsstaub entstanden. Die Bodentypen werden nach ihrer Zusammensetzung aus unterschiedlichen Korngr\u00f6\u00dfen in diese Arten eingeteilt: Sandboden Schluffboden Lehmboden Tonboden Die Bodentypen sind durch die vorherrschenden Korngr\u00f6\u00dfen bestimmt. Bei Sandboden ist die K\u00f6rnung am gr\u00f6bsten, w\u00e4hrend Tonboden die feinste K\u00f6rnung hat. Die Korngr\u00f6\u00dfe entscheidet dar\u00fcber, wie gut Boden Wasser speichern kann. Kennen Sie den Bodentyp Ihres Gartens, k\u00f6nnen Sie ihn mit gezielten Ma\u00dfnahmen verbessern und auf die Bed\u00fcrfnisse der verschiedenen Pflanzen abstimmen. Es gibt keinen guten oder schlechten Boden, da jeder Bodentyp seine Vor- und Nachteile hat. Im Idealfall ist der [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"hersteller":[],"class_list":["post-1205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Boden ist nicht gleich Boden. Die Beschaffenheit des Gartenbodens ist f\u00fcr Ihren Erfolg beim Anbau wichtig. Erfahren Sie mehr \u00fcber die Bodentypen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Boden ist nicht gleich Boden. Die Beschaffenheit des Gartenbodens ist f\u00fcr Ihren Erfolg beim Anbau wichtig. Erfahren Sie mehr \u00fcber die Bodentypen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-29T09:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-27T14:53:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/09\/Bodenbeschaffenheit_353591886.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fritz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fritz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten\"},\"author\":{\"name\":\"Fritz\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/a0608c49bb909de7ed33e44abc853c6b\"},\"headline\":\"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten\",\"datePublished\":\"2022-05-29T09:00:39+00:00\",\"dateModified\":\"2023-12-27T14:53:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten\"},\"wordCount\":1177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Bodenbeschaffenheit_353591886.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten\",\"name\":\"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Bodenbeschaffenheit_353591886.jpg\",\"datePublished\":\"2022-05-29T09:00:39+00:00\",\"dateModified\":\"2023-12-27T14:53:56+00:00\",\"description\":\"Boden ist nicht gleich Boden. Die Beschaffenheit des Gartenbodens ist f\u00fcr Ihren Erfolg beim Anbau wichtig. Erfahren Sie mehr \u00fcber die Bodentypen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Bodenbeschaffenheit_353591886.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Bodenbeschaffenheit_353591886.jpg\",\"width\":1000,\"height\":563,\"caption\":\"verschiedene Arten von Bodenbeschaffenheit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/a0608c49bb909de7ed33e44abc853c6b\",\"name\":\"Fritz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Tobi-1-150x150.jpg\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Tobi-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Tobi-1-150x150.jpg\",\"caption\":\"Fritz\"},\"description\":\"Das ist Fritz. Er steht f\u00fcr all die erfahrenen G\u00e4rtner und Selbstversorger, die ihr Wissen und ihre Erfahrungen auf dem Gartenblog mit Ihnen teilen. Mit Tipps und Tricks f\u00fcr den Garten, den Balkon und die K\u00fcche steht Fritz Ihnen zur Seite.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/tobias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten - Samenhaus Gartenblog","description":"Boden ist nicht gleich Boden. Die Beschaffenheit des Gartenbodens ist f\u00fcr Ihren Erfolg beim Anbau wichtig. Erfahren Sie mehr \u00fcber die Bodentypen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten","og_locale":"de_DE","og_type":"article","og_title":"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten - Samenhaus Gartenblog","og_description":"Boden ist nicht gleich Boden. Die Beschaffenheit des Gartenbodens ist f\u00fcr Ihren Erfolg beim Anbau wichtig. Erfahren Sie mehr \u00fcber die Bodentypen.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2022-05-29T09:00:39+00:00","article_modified_time":"2023-12-27T14:53:56+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/09\/Bodenbeschaffenheit_353591886.jpg","type":"image\/jpeg"}],"author":"Fritz","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Fritz","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten"},"author":{"name":"Fritz","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/a0608c49bb909de7ed33e44abc853c6b"},"headline":"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten","datePublished":"2022-05-29T09:00:39+00:00","dateModified":"2023-12-27T14:53:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten"},"wordCount":1177,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/09\/Bodenbeschaffenheit_353591886.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten","url":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten","name":"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/09\/Bodenbeschaffenheit_353591886.jpg","datePublished":"2022-05-29T09:00:39+00:00","dateModified":"2023-12-27T14:53:56+00:00","description":"Boden ist nicht gleich Boden. Die Beschaffenheit des Gartenbodens ist f\u00fcr Ihren Erfolg beim Anbau wichtig. Erfahren Sie mehr \u00fcber die Bodentypen.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/09\/Bodenbeschaffenheit_353591886.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/09\/Bodenbeschaffenheit_353591886.jpg","width":1000,"height":563,"caption":"verschiedene Arten von Bodenbeschaffenheit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bodenbeschaffenheit-merkmale-der-verschiedenen-bodenarten#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Bodenbeschaffenheit: Merkmale der verschiedenen Bodenarten"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/a0608c49bb909de7ed33e44abc853c6b","name":"Fritz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/11\/Tobi-1-150x150.jpg","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/11\/Tobi-1-150x150.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/11\/Tobi-1-150x150.jpg","caption":"Fritz"},"description":"Das ist Fritz. Er steht f\u00fcr all die erfahrenen G\u00e4rtner und Selbstversorger, die ihr Wissen und ihre Erfahrungen auf dem Gartenblog mit Ihnen teilen. Mit Tipps und Tricks f\u00fcr den Garten, den Balkon und die K\u00fcche steht Fritz Ihnen zur Seite.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/tobias"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/1205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":20,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/1205\/revisions"}],"predecessor-version":[{"id":12610,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/1205\/revisions\/12610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/1278"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=1205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=1205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=1205"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}