{"id":12363,"date":"2024-02-28T09:00:37","date_gmt":"2024-02-28T08:00:37","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=12363"},"modified":"2024-02-28T13:56:02","modified_gmt":"2024-02-28T12:56:02","slug":"weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau","title":{"rendered":"Wei\u00df, gr\u00fcn &#038; violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau?"},"content":{"rendered":"<p>Spargel ist ein Edelgem\u00fcse, das nur \u00fcber relativ kurze Zeit verf\u00fcgbar ist. M\u00f6chten Sie selbst Spargel anbauen, k\u00f6nnen Sie aus vielen Sorten w\u00e4hlen. Dieser Beitrag stellt Ihnen die viele Varianten vor und bietet Ihnen eine Beratung zum Kauf.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Spargel_Sorten_edle_Stangen_in_verschiedenen_Farben\"><\/span>Spargel Sorten: edle Stangen in verschiedenen Farben<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>M\u00f6chten Sie Spargel selbst anbauen, k\u00f6nnen Sie vorgezogene Wurzelst\u00f6cke verwenden. Die Aussaat ist m\u00f6glich, erfordert aber Geduld. Beim Spargel werden wei\u00dfe, gr\u00fcne und violette Sorten unterschieden. Die wei\u00dfen Sorten sind am bekanntesten, doch gr\u00fcner Spargel tankt Sonne und ist daher noch reicher an Vitaminen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Weisser_Spargel_Anbau_in_Erddaemmen\"><\/span>Wei\u00dfer Spargel: Anbau in Erdd\u00e4mmen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16932 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_51047151.jpg\" alt=\"wei\u00dfer Spargel\" width=\"300\" height=\"200\" \/>Damit wei\u00dfer Spargel seine typische Farbe beh\u00e4lt, wird er in Erdd\u00e4mmen angebaut und unter der Erde gestochen. Wei\u00dfe Spargelsorten unterscheiden sich in ihren Ertr\u00e4gen und im Geschmack. Zur Auswahl stehen:<\/p>\n<ul>\n<li><strong>Huchels Alpha:<\/strong> Huchels Alpha ist eine altbew\u00e4hrte Sorte, die mittelfr\u00fch und samenfest ist. Die Sorte bringt unregelm\u00e4\u00dfig wachsende Stangen mit unregelm\u00e4\u00dfiger F\u00e4rbung hervor. Die Stangen haben jedoch ein feines, nussiges Aroma und eine zarte Konsistenz. Die Ertr\u00e4ge sind mittelm\u00e4\u00dfig. Im Garten l\u00e4sst sich die Sorte relativ einfach anbauen.<\/li>\n<li><strong><a href=\"https:\/\/www.samenhaus.de\/search?query=argenteuil+spargel\" target=\"_blank\" rel=\"noopener\">Argenteuil<\/a>:<\/strong> Argenteuil ist eine historische franz\u00f6sische Sorte, die bereits im 18. Jahrhundert angebaut wurde. Sie zeichnet sich durch eine fr\u00fche Ernte, einen guten Geschmack und hohe Ertr\u00e4ge aus.<\/li>\n<li><strong>Ramada:<\/strong> Ramada stammt aus Baden-W\u00fcrttemberg und ist eine neuere Sorte. Sie k\u00f6nnen schon fr\u00fch ernten. Die Sorte liefert hohe Ertr\u00e4ge, ist robust, hat einen guten Geschmack und bringt Stangen mit einer St\u00e4rke von 16 bis 26 Millimetern hervor.<\/li>\n<li><strong>Gijnlim:<\/strong> Gijnlim ist eine F1-Hybride, die aus den Niederlanden stammt und nur m\u00e4nnliche Pflanzen hervorbringt. Die mitteldicken Stangen wachsen gerade. Die Sorte ist robust, pflegeleicht und gut f\u00fcr den heimischen Garten geeignet. Sie eignet sich auch f\u00fcr den Anbau als Gr\u00fcnspargel und f\u00fcr den Fr\u00fchanbau unter Folie.<\/li>\n<li><strong>Backlim:<\/strong> Backlim ist eine sp\u00e4te, ertragreiche Sorte mit dicken Stangen. Sie eignet sich f\u00fcr jeden Bodentyp und kann auch unter Folie angebaut werden.<\/li>\n<li><strong>Ramires:<\/strong> Ramires ist eine F1-Hybride, die Sie schon fr\u00fch ernten k\u00f6nnen und die stattliche Ertr\u00e4ge bringt. Die Stangen erreichen einen Durchmesser von 16 bis 26 mm. Sie haben einen hervorragenden Geschmack und eignen sich gut f\u00fcr den Hausgarten.<\/li>\n<li><strong>Cumulus:<\/strong> Die F1-Hybride Cumulus ist eine neuere Z\u00fcchtung, die nur m\u00e4nnliche Pflanzen hervorbringt. Die gleichm\u00e4\u00dfig dicken, glatten Stangen schmecken aromatisch-s\u00fc\u00df. Die Sorte k\u00f6nnen Sie schon fr\u00fch ernten. Sie bringt gute Ertr\u00e4ge und ist robust gegen Spargelrost.<\/li>\n<li><strong>Viking:<\/strong> Viking bringt m\u00e4nnliche und weibliche Pflanzen hervor und ist ein Hybridsorte. Die robuste Sorte zeichnet sich durch hohe Ertr\u00e4ge aus und kann schon fr\u00fch geerntet werden.<\/li>\n<li><strong>Ravel:<\/strong> Ravel ist eine sehr fr\u00fche, ertragreiche Sorte, die gerade, gleichm\u00e4\u00dfige Stangen hervorbringt. Sie eignet sich gut f\u00fcr den heimischen Garten.<\/li>\n<li><strong>Rapsody:<\/strong> Rapsody ist eine neue Sorte, die schwere B\u00f6den toleriert, hohe Ertr\u00e4ge bringt und sich gut f\u00fcr den Hausgarten eignet. M\u00f6chten Sie die Erntezeit verl\u00e4ngern, bauen Sie eine fr\u00fche Sorte an und pflanzen Rapsody tiefer, um diese Sorte sp\u00e4ter zu ernten.<\/li>\n<li><strong>Steineo:<\/strong> Die Hybridsorte Steineo k\u00f6nnen Sie schon fr\u00fch ernten. Sie liefert gute Ertr\u00e4ge und bringt mitteldicke Stangen mit gutem Aroma hervor.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Gruene_Sorten_Anbau_ohne_Erddaemme\"><\/span>Gr\u00fcne Sorten: Anbau ohne Erdd\u00e4mme<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16933 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_190011630.jpg\" alt=\"gr\u00fcner Spargel\" width=\"300\" height=\"200\" \/>Gr\u00fcner Spargel erh\u00e4lt seine Farbe, da er ohne Erdd\u00e4mme angebaut wird und bei Sonneneinstrahlung den gr\u00fcnen Farbstoff Chlorophyll ausbildet. Er bekommt dadurch einen herb-aromatischen Geschmack. Auch bei gr\u00fcnem Spargel k\u00f6nnen Sie aus einigen Sorten w\u00e4hlen:<\/p>\n<ul>\n<li><strong>Huchels Schneewittchen:<\/strong> Huchels Schneewittchen ist eine klassische Sorte mit gleichm\u00e4\u00dfig gr\u00fcn gef\u00e4rbten Stangen, die zart und aromatisch sind. Die Sorte eignet sich auch f\u00fcr den Anbau als Bleichspargel. Sie liefert gute Ertr\u00e4ge und kann zwischen Ende Mai und Ende Juni geerntet werden.<\/li>\n<li><strong>Primaverde:<\/strong> Die F1-Hybride Primaverde bringt nur m\u00e4nnliche Pflanzen mit glatten, d\u00fcnnen Stangen hervor. Sie liefert gute Ertr\u00e4ge und erm\u00f6glicht eine fr\u00fche Ernte zwischen April und Juni.<\/li>\n<li><strong>Ariane:<\/strong> Ariane ist eine alte Sorte, die schon seit dem 17. Jahrhundert angebaut wird. Sie w\u00e4chst schnell, hat einen herzhaften Geschmack und eignet sich auch f\u00fcr den Anbau als Bleichspargel. Die schnellw\u00fcchsige Sorte k\u00f6nnen Sie zwischen Mai und Juni ernten.<\/li>\n<li><strong>Steinivia:<\/strong> Steinivia ist eine F1-Hybride, die Sie schon fr\u00fchzeitig ernten k\u00f6nnen. Die Erntezeit erstreckt sich auf den Zeitraum von April bis Juni. Die Sorte hat einen guten Geschmack, ist ertragreich und eignet sich gut f\u00fcr den heimischen Garten.<\/li>\n<li><strong>Mary Washington:<\/strong> Die Sorte Mary Washington ist in den USA beliebt, w\u00e4chst schnell, hat einen guten Geschmack und ist ertragreich. Die Ernte ist schon fr\u00fchzeitig ab April m\u00f6glich und kann sich bis in den Juni erstrecken.<\/li>\n<li><strong>Connover&#8217;s Colossal:<\/strong> Connover&#8217;s Colossal ist eine alte US-amerikanische Sorte mit dicken Stangen. Die Sorte ist sehr fr\u00fchreif und hat eine gute Qualit\u00e4t.<\/li>\n<li><strong>Xenolim:<\/strong> Die F1-Hybride Xenolim bringt nur m\u00e4nnliche Pflanzen hervor und ist eine neue niederl\u00e4ndische Z\u00fcchtung. Die Sorte ist mittelfr\u00fch, bringt gute Ertr\u00e4ge hervor und hat dicke, gleichm\u00e4\u00dfige Stangen.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Violette_Sorten_oberirdische_Ernte_und_aehnlicher_Geschmack_wie_Bleichspargel\"><\/span>Violette Sorten: oberirdische Ernte und \u00e4hnlicher Geschmack wie Bleichspargel<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16934 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_190583413.jpg\" alt=\"violetter Spargel\" width=\"300\" height=\"200\" \/>Violetter Spargel kann sich aus dem klassischen Bleichspargel entwickeln. Der Anbau erfolgt ohne D\u00e4mme, die Ernte oberirdisch. Die violette F\u00e4rbung entsteht durch den Pflanzenfarbstoff Anthocyan, der bei Sonnenlicht gebildet wird. Er macht den wei\u00dfen Spargel ges\u00fcnder als den gr\u00fcnen. Auch bei violettem Spargel gibt es verschiedene Sorten:<\/p>\n<ul>\n<li><strong>Violetta:<\/strong> Violetta ist eine F1-Hybride, die Sie schon fr\u00fch ernten k\u00f6nnen. Die Sorte zeichnet sich durch einen guten Geschmack aus und eignet sich gut f\u00fcr den Anbau im Garten.<\/li>\n<li><strong>Erasmus:<\/strong> Die F1-Hybride Erasmus ist eine rein m\u00e4nnliche, fr\u00fche Sorte, die sich durch hohe Ertr\u00e4ge auszeichnet und schmackhafte, dicke Stangen hervorbringt.<\/li>\n<li><strong>Jacquma Poupr\u00e9:<\/strong> Jacquma Poupr\u00e9 ist eine fr\u00fche Sorte, die Sie von April bis Juni ernten k\u00f6nnen. Die Sorte mit dem milden Geschmack eignet sich f\u00fcr unterschiedliche B\u00f6den.<\/li>\n<li><strong>Burgundine:<\/strong> Die F1-Hybride Burgundine ist eine neue Z\u00fcchtung aus Frankreich, die sich durch eine gleichm\u00e4\u00dfige violette F\u00e4rbung auszeichnet. Die Sorte liefert hohe Ertr\u00e4ge, kann schon fr\u00fch geerntet werden und erm\u00f6glicht eine Ernte bis zum Juni. Die Sorte ist auch roh genie\u00dfbar.<\/li>\n<li><strong>Pacific Purple:<\/strong> Pacific Purple ist eine F1-Hybride mit dicken, dunkelvioletten Stangen, die schon fr\u00fchzeitig erntereif ist. Die Sorte hat eine zarte Konsistenz und einen feinen Geschmack.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Kaufberatung_fuer_Spargelsamen_Geschmack_Ertraege_und_weitere_Kriterien\"><\/span>Kaufberatung f\u00fcr Spargelsamen: Geschmack, Ertr\u00e4ge und weitere Kriterien<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Welche Sorte von <a href=\"https:\/\/www.samenhaus.de\/spargelsamen\" target=\"_blank\" rel=\"noopener\">Spargelsamen<\/a> Sie kaufen, h\u00e4ngt davon ab, ob Sie wei\u00dfen, gr\u00fcnen oder violetten Spargel bevorzugen. Beim Kauf spielen aber noch weitere Kriterien wie Geschmack, Ertr\u00e4ge und Erntezeit eine wichtige Rolle. Je nachdem, was Ihnen wichtig ist, entscheiden Sie sich f\u00fcr diese Sorten:<\/p>\n<table class=\"custom-table-1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"4\">\n<tbody>\n<tr>\n<td width=\"154\"><strong>Kriterium<\/strong><\/td>\n<td width=\"154\"><strong>Wei\u00dfer Spargel<\/strong><\/td>\n<td width=\"154\"><strong>Gr\u00fcner Spargel<\/strong><\/td>\n<td width=\"154\"><strong>Violetter Spargel<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"154\">Zarte Konsistenz<\/td>\n<td width=\"154\">Huchels Alpha, Ramada<\/td>\n<td width=\"154\">Huchels Schneewittchen<\/td>\n<td width=\"154\">Pacific Purple<\/td>\n<\/tr>\n<tr>\n<td width=\"154\">Guter Geschmack<\/td>\n<td width=\"154\">Huchels Alpha, Argenteuil, Ramada, Ramires, Cumulus, Steineo<\/td>\n<td width=\"154\">Huchels Schneewittchen, Ariane, Steinivia, Mary Washington, Connover&#8217;s Colossal<\/td>\n<td width=\"154\">Violetta, Erasmus, Jacquma Poupr\u00e9, Pacific Purple<\/td>\n<\/tr>\n<tr>\n<td width=\"154\">Robust, einfacher Anbau<\/td>\n<td width=\"154\">Huchels Alpha, Ramada, Gijnlim, Ramires, Cumulus, Viking, Ravel, Rapsody<\/td>\n<td width=\"154\">Steinivia<\/td>\n<td width=\"154\">Violetta, Jacquma Poupr\u00e9<\/td>\n<\/tr>\n<tr>\n<td width=\"154\">Hohe Ertr\u00e4ge<\/td>\n<td width=\"154\">Argenteuil, Ramada, Backlim, Ramires, Cumulus, Viking, Ravel, Rapsody, Steineo<\/td>\n<td width=\"154\">Huchels Schneewittchen, Primaverde, Steinivia, Mary Washington<\/td>\n<td width=\"154\">Erasmus, Burgundine<\/td>\n<\/tr>\n<tr>\n<td width=\"154\">Fr\u00fche Ernte<\/td>\n<td width=\"154\">Argenteuil, Ramada, Ramires, Cumulus, Viking, Ravel, Steineo<\/td>\n<td width=\"154\">Primaverde, Steinivia, Mary Washington, Connover&#8217;s Colossal, Xenolim<\/p>\n<p>&nbsp;<\/td>\n<td width=\"154\">Violetta, Erasmus, Burgundine, Pacific Purple<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Spargel ist ein Edelgem\u00fcse, das nur \u00fcber relativ kurze Zeit verf\u00fcgbar ist. M\u00f6chten Sie selbst Spargel anbauen, k\u00f6nnen Sie aus vielen Sorten w\u00e4hlen. Dieser Beitrag stellt Ihnen die viele Varianten vor und bietet Ihnen eine Beratung zum Kauf. Spargel Sorten: edle Stangen in verschiedenen Farben M\u00f6chten Sie Spargel selbst anbauen, k\u00f6nnen Sie vorgezogene Wurzelst\u00f6cke verwenden. Die Aussaat ist m\u00f6glich, erfordert aber Geduld. Beim Spargel werden wei\u00dfe, gr\u00fcne und violette Sorten unterschieden. Die wei\u00dfen Sorten sind am bekanntesten, doch gr\u00fcner Spargel tankt Sonne und ist daher noch reicher an Vitaminen. Wei\u00dfer Spargel: Anbau in Erdd\u00e4mmen Damit wei\u00dfer Spargel seine typische Farbe beh\u00e4lt, wird er in Erdd\u00e4mmen angebaut und unter der Erde gestochen. Wei\u00dfe Spargelsorten unterscheiden sich in ihren Ertr\u00e4gen und im Geschmack. Zur Auswahl stehen: Huchels Alpha: Huchels Alpha ist eine altbew\u00e4hrte Sorte, die mittelfr\u00fch und samenfest ist. Die Sorte bringt unregelm\u00e4\u00dfig wachsende Stangen mit unregelm\u00e4\u00dfiger F\u00e4rbung hervor. Die Stangen haben jedoch ein feines, nussiges Aroma und eine zarte Konsistenz. Die Ertr\u00e4ge sind mittelm\u00e4\u00dfig. Im Garten l\u00e4sst sich die Sorte relativ einfach anbauen. Argenteuil: Argenteuil ist eine historische franz\u00f6sische Sorte, die bereits im 18. Jahrhundert angebaut wurde. Sie zeichnet sich durch eine fr\u00fche Ernte, einen guten Geschmack und hohe Ertr\u00e4ge aus. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":16936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"hersteller":[],"class_list":["post-12363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gemuese"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wei\u00df, gr\u00fcn &amp; violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau? - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Spargel ist ein beliebtes Gem\u00fcse. Wer Spargel selber anbauen m\u00f6chte, hat die Wahl zwischen, wei\u00dfen, gr\u00fcnen und violetten Spargelsorten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wei\u00df, gr\u00fcn &amp; violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau? - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Spargel ist ein beliebtes Gem\u00fcse. Wer Spargel selber anbauen m\u00f6chte, hat die Wahl zwischen, wei\u00dfen, gr\u00fcnen und violetten Spargelsorten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T08:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T12:56:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_315643988.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau\"},\"author\":{\"name\":\"Sabine\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\"},\"headline\":\"Wei\u00df, gr\u00fcn &#038; violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau?\",\"datePublished\":\"2024-02-28T08:00:37+00:00\",\"dateModified\":\"2024-02-28T12:56:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau\"},\"wordCount\":1274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Spargel_315643988.jpg\",\"articleSection\":[\"Gem\u00fcse\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau\",\"name\":\"Wei\u00df, gr\u00fcn & violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau? - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Spargel_315643988.jpg\",\"datePublished\":\"2024-02-28T08:00:37+00:00\",\"dateModified\":\"2024-02-28T12:56:02+00:00\",\"description\":\"Spargel ist ein beliebtes Gem\u00fcse. Wer Spargel selber anbauen m\u00f6chte, hat die Wahl zwischen, wei\u00dfen, gr\u00fcnen und violetten Spargelsorten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Spargel_315643988.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Spargel_315643988.jpg\",\"width\":1000,\"height\":563,\"caption\":\"Spargelsorten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wei\u00df, gr\u00fcn &#038; violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\",\"name\":\"Sabine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"caption\":\"Sabine\"},\"description\":\"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/sabine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wei\u00df, gr\u00fcn & violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau? - Samenhaus Gartenblog","description":"Spargel ist ein beliebtes Gem\u00fcse. Wer Spargel selber anbauen m\u00f6chte, hat die Wahl zwischen, wei\u00dfen, gr\u00fcnen und violetten Spargelsorten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau","og_locale":"de_DE","og_type":"article","og_title":"Wei\u00df, gr\u00fcn & violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau? - Samenhaus Gartenblog","og_description":"Spargel ist ein beliebtes Gem\u00fcse. Wer Spargel selber anbauen m\u00f6chte, hat die Wahl zwischen, wei\u00dfen, gr\u00fcnen und violetten Spargelsorten.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2024-02-28T08:00:37+00:00","article_modified_time":"2024-02-28T12:56:02+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_315643988.jpg","type":"image\/jpeg"}],"author":"Sabine","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Sabine","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau"},"author":{"name":"Sabine","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5"},"headline":"Wei\u00df, gr\u00fcn &#038; violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau?","datePublished":"2024-02-28T08:00:37+00:00","dateModified":"2024-02-28T12:56:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau"},"wordCount":1274,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_315643988.jpg","articleSection":["Gem\u00fcse"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau","url":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau","name":"Wei\u00df, gr\u00fcn & violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau? - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_315643988.jpg","datePublished":"2024-02-28T08:00:37+00:00","dateModified":"2024-02-28T12:56:02+00:00","description":"Spargel ist ein beliebtes Gem\u00fcse. Wer Spargel selber anbauen m\u00f6chte, hat die Wahl zwischen, wei\u00dfen, gr\u00fcnen und violetten Spargelsorten.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_315643988.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/02\/Spargel_315643988.jpg","width":1000,"height":563,"caption":"Spargelsorten"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/weiss-gruen-violett-welche-spargelsorten-sind-die-besten-fuer-den-eigenanbau#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Wei\u00df, gr\u00fcn &#038; violett: Welche Spargelsorten sind die Besten f\u00fcr den Eigenanbau?"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5","name":"Sabine","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","caption":"Sabine"},"description":"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/sabine"}]}},"wp-worthy-pixel":{"ignored":false,"public":"043b94851b6b4c8691597337db78c474","server":"vg02.met.vgwort.de","url":"https:\/\/vg02.met.vgwort.de\/na\/043b94851b6b4c8691597337db78c474"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/12363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=12363"}],"version-history":[{"count":4,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/12363\/revisions"}],"predecessor-version":[{"id":16937,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/12363\/revisions\/16937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/16936"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=12363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=12363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=12363"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=12363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}