{"id":13384,"date":"2022-07-03T10:17:20","date_gmt":"2022-07-03T10:17:20","guid":{"rendered":"https:\/\/rasenhaus.de\/rasenblog\/?p=3940"},"modified":"2023-11-14T14:15:23","modified_gmt":"2023-11-14T13:15:23","slug":"rasenarten-fuer-jeden-zweck","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck","title":{"rendered":"Rasenarten f\u00fcr jeden Zweck"},"content":{"rendered":"<p>Rasen ist nicht gleich Rasen und es gibt f\u00fcr jeden Verwendungszweck die richtigen Rasensamen. Diese unterscheiden sich vor allem bei der Strapazierf\u00e4higkeit, der Pflege und auch der Zusammensetzung der verschiedenen Gr\u00e4ser. Aus diesem Grund ist es wichtig, schon vor dem Anlegen des Rasens genau zu wissen, f\u00fcr welchen Zweck der Rasen sein soll? Wer einen englischen Rasen bevorzugt, kann dann nicht die Samenmischung f\u00fcr einen Sportrasen nutzen. Damit jeder einen \u00dcberblick bekommt, haben wir hier die verschiedenen Rasenarten zusammengefasst.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Rasensamen_nach_Verwendungszweck_kaufen\"><\/span>Rasensamen nach Verwendungszweck kaufen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Es gibt viele verschiedenen Rasentypen, die genau auf die Bed\u00fcrfnisse der jeweiligen G\u00e4rten abgestimmt sind. Daher ist es wichtig, vorher zu entscheiden, welche Rasentypen in den Garten passen und f\u00fcr welchen Zweck sie bestimmt sind. Bei den unterschiedlichen Typen werden verschiedene Zuchtsorgen und Gr\u00e4serarten miteinander kombiniert, damit sie Trockenheit, Schatten oder auch starken Belastungen standhalten k\u00f6nnen. Daher haben alle Rasentypen verschiedene Eigenschaften.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Spiel-_und_Sportrasen\"><\/span>Spiel- und Sportrasen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p data-wp-editing=\"1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4003 size-thumbnail\" src=\"https:\/\/www.rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_392251592-150x150.jpeg\" alt=\"Spiel- und Sportrasen\" width=\"150\" height=\"150\" \/>Spiel- und Sportrasen ist eine Mischung, die aus Deutschem Weidelgras (Lolium perenne), Rotschwingel (Festuca rubra) und Wiesenrispe (Poa pratensis) besteht. Insbesondere dieser Rasentyp ist einer der am h\u00e4ufigsten verwendeten Sorten, da er sehr belastbar ist. Wer Kinder im Haushalt hat, sollte diese Sorte w\u00e4hlen, da er die Spiel- und Sportaktivit\u00e4ten sehr gut aush\u00e4lt. Spiel- und Sportrasen muss ab dem Fr\u00fchjahr einmal w\u00f6chentlich auf drei bis vier Zentimeter gem\u00e4ht werden. Im Sommer muss er au\u00dferdem gut bew\u00e4ssert und mit ausreichend N\u00e4hrstoffen versorgt werden.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Trockenrasen\"><\/span>Trockenrasen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4002 size-thumbnail\" src=\"https:\/\/www.rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_379425383-150x150.jpeg\" alt=\"Trockenrasen\" width=\"150\" height=\"150\" \/>Wie der Name schon sagt, ist der Trockenrasen f\u00fcr trockene Standorte sehr gut geeignet. Er ist sehr widerstandsf\u00e4hig gegen\u00fcber Hitze- und D\u00fcrreperioden, da die Wurzeln l\u00e4nger sind und somit auch an tiefere Wasservorr\u00e4te gelangen. Durch seine breitbl\u00e4ttrige Rasenstruktur erinnert er an die Rasenfl\u00e4chen im S\u00fcden von Europa und besteht aus den Sorten Wiesenrispe (Poa pratensis) und Rohrschwingel (Festuca arundinacea). Auch als Spielrasen ist dieser Rasentyp sehr gut geeignet, da er mittel bis hoch belastbar und somit sehr robust ist.<\/p>\n<p>Ab dem Fr\u00fchjahr wird der Rasen einmal pro Woche gem\u00e4ht. Die Schnitth\u00f6he betr\u00e4gt vier bis f\u00fcnf Zentimeter. Da dieser Rasen speziell f\u00fcr trockene Fl\u00e4chen ist, ben\u00f6tigt er auch deutlich weniger Wasser als andere Rasentypen. Er ist \u00e4hnlich wie der Mediterran-Rasen, der dicht und schnell w\u00e4chst und ebenfalls im Samenhaus erh\u00e4ltlich ist.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Schattenrasen\"><\/span>Schattenrasen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4006 size-thumbnail\" src=\"https:\/\/www.rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_513189328-150x150.jpeg\" alt=\"Schattengarten\" width=\"150\" height=\"150\" \/>Schattenrasen ist vor allem f\u00fcr schattige Fl\u00e4chen ideal. Dennoch ben\u00f6tigt auch Schattenrasen Sonnenlicht und ist daher nur f\u00fcr Fl\u00e4chen geeignet, die wenig Sonne abbekommen. Dies ist meist der Fall, wenn die Rasenfl\u00e4che im Schatten der Hauswand, von B\u00e4umen oder von Hecken liegt. Die Mischung des Schattenrasens besteht aus Deutschem Weidelgras (Lolium perenne), Wiesenrispe (Poa pratensis), Rotschwingel (Festuca rubra) und L\u00e4gerrispe (Poa supina).<\/p>\n<p>Durch die spezielle Mischung kann diese Rasenart auch als Strapazierrasen an sonnigen Fl\u00e4chen verwendet werden. Lediglich im Schatten ist die Belastbarkeit und Strapazierbarkeit niedriger. Geschnitten wird der Schattenrasen einmal die Woche mit einer Schnitth\u00f6he zwischen vier und f\u00fcnf Zentimetern. Auch bei Schattenrasen ist auf eine bedarfsgerechte N\u00e4hrstoff- und Wasserversorgung zu achten.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Zierrasen\"><\/span>Zierrasen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4004 size-thumbnail\" src=\"https:\/\/www.rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_464907847-150x150.jpeg\" alt=\"Zierrasen\" width=\"150\" height=\"150\" \/>Zierrasen ist auch unter den Namen \u201eEnglischer Rasen\u201c oder \u201eGolfrasen\u201c bekannt. Dieser Typ besteht aus feinbl\u00e4ttrigen Gr\u00e4sern, die eine sehr dichte Rasennarbe bilden. Wie es sich aus dem Namen schon ableiten l\u00e4sst, hat der Rasen nur einen Zweck. Er dient zur Zierde. Daher ist er f\u00fcr Familien mit Kindern nicht geeignet, da er sehr wenig belastbar ist.<\/p>\n<p>Der Zierrasen besteht aus (Festuca rubra), Wiesenrispe (Poa pratensis) und Strau\u00dfgr\u00e4sern (Agrostis). Allerdings ist der Anteil an Festuca ruba sehr hoch, was bedeutet, dass er zum Verfilzen neigt und f\u00fcr Krankheiten sehr anf\u00e4llig ist. Aus diesem Grund ist der Pflegeaufwand bei Zierrasen besonders hoch. Gem\u00e4ht werden muss der Englische Rasen zweimal die Woche und die optimale Schnitth\u00f6he betr\u00e4gt 1,5 bis 2 cm.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Kleintierrasen\"><\/span>Kleintierrasen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3999 size-thumbnail\" src=\"https:\/\/www.rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_196974309-150x150.jpeg\" alt=\"Kleintierrasen\" width=\"150\" height=\"150\" \/>Wer Meerschweinchen, Kaninchen oder andere Kleintiere im Haushalt hat, ist mit dem Kleintierrasen sehr gut bedient. Er kann speziell in die Ausl\u00e4ufe der Tiere ges\u00e4t werden, da die Gr\u00e4sermischung f\u00fcr eine gesunde Verdauung sorgt und bei den Tieren sehr beliebt ist. Die Mischung setzt sich aus Deutschem Weidelgras (Lolium perenne), Rotschwingel (Festuca rubra), Schafschwingel (Poaceae), Lieschgras (Phleum pratense), Wiesenrispe (Poa pratensis) und Wei\u00dfklee (Trifolium repens) zusammen und ist f\u00fcr alle Gartenb\u00f6den geeignet.<\/p>\n<p>Durch die vielen verschiedenen Gr\u00e4ser ist der Rasen Kleintierrasen sehr belastbar und robust. Zudem kann das Schnittgut als Tierfutter genutzt werden. Das Saatgut der \u201eKleintier-Wiese\u201c ist f\u00fcr Haustiere wie Kaninchen, Hasen, Meerschweinchen, G\u00e4nse, H\u00fchner sowie Schildkr\u00f6ten geeignet, da es aus Gr\u00e4sern und Klee besteht.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Kraeuterrasen\"><\/span>Kr\u00e4uterrasen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4005 size-thumbnail\" src=\"https:\/\/www.rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_503246820-150x150.jpeg\" alt=\"Kr\u00e4utergarten\" width=\"150\" height=\"150\" \/>Kr\u00e4uterrasen bieten sich f\u00fcr Dachg\u00e4rten und naturnahe G\u00e4rten an. Sie sind eine Mischung aus Gr\u00e4sern, Rot- und Schafschwingel sowie aus Wiesenrispe und verschiedenen Kr\u00e4utern. Allerdings ist der Kr\u00e4uterrasen nicht sehr belastbar. Wird er jedoch h\u00e4ufig genutzt, kommen die Gr\u00e4ser besser durch und die Kr\u00e4uter verschwinden mit der Zeit. Gleiches passiert auch bei einem sehr n\u00e4hrstoffreichen Boden.<\/p>\n<p>Damit sich die Kr\u00e4uter durchsetzen k\u00f6nnen, ist eine geringe Nutzung wie auch ein n\u00e4hrstoffarmer Boden von gro\u00dfer Bedeutung. Der Pflegeaufwand eines Kr\u00e4uterrasens ist \u00fcberschaubar. Er sollte j\u00e4hrlich sechs- bis zehnmal geschnitten werden und das Schnittgut muss aufgenommen werden. Verf\u00fcgt der Kr\u00e4uterrasen \u00fcber einen hohen Kleeanteil, muss die Kr\u00e4uterwiese nicht ged\u00fcngt werden.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Blumenwiese\"><\/span>Blumenwiese<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4000 size-thumbnail\" src=\"https:\/\/www.rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_281127160-150x150.jpeg\" alt=\"Blumenwiese\" width=\"150\" height=\"150\" \/>Bei der Blumenwiese ist vor allem der Bl\u00fcheffekt im Vordergrund und zieht unz\u00e4hlige Insekten an, weshalb diese f\u00fcr naturnahe G\u00e4rten sehr gut geeignet ist. Doch auch als Zierelemente kann diese Rasenart Akzente im Garten setzen. In der Blumenwiese sind beispielsweise Rot- und Schafschwingel wie auch verschiedene Blumen und Kr\u00e4uter enthalten. Dieser Rasentyp sollte nur ein- bis zweimal im Jahr gem\u00e4ht werden, da sich sonst die Gr\u00e4ser durchsetzen und die bl\u00fchenden Pflanzen immer weniger werden. Auch eine D\u00fcngung ist f\u00fcr die Blumenwiese nicht notwendig. Ein n\u00e4hrstoffarmer Boden ist von Vorteil, da n\u00e4hrstoffreiche B\u00f6den die Bl\u00fchpflanzen verdr\u00e4ngen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Tipps_zum_Nachsaehen_und_zur_Rasenerneuerung\"><\/span>Tipps zum Nachs\u00e4hen und zur Rasenerneuerung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4001 alignright\" src=\"https:\/\/rasenhaus.de\/rasenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_370744687-300x200.jpeg\" alt=\"Rasenarten Pflege\" width=\"300\" height=\"200\" \/>Durch einen harten Winter oder zu starke Belastung kommt der Rasen irgendwann an seine Grenzen. Dann ist es h\u00e4ufig notwendig, den Rasen zu reparieren. Bei stark vermoosten Fl\u00e4chen oder viel Unkraut ist es wichtig zu vertikutieren. Anschlie\u00dfend sollte der Boden gut gelockert werden, bevor dann ein Nachsaatrasen zum Einsatz kommt.<\/p>\n<p>Diese ist vor allem im Fr\u00fchjahr empfehlenswert, da zu dieser Zeit die Wachstumsphase der Gr\u00e4ser beginnt und so f\u00fcr den Sommer wieder ein saftig, gr\u00fcner Rasen entsteht.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Boden_fuer_die_Nachsaat_oder_Rasenerneuerung_vorbereiten\"><\/span>Boden f\u00fcr die Nachsaat oder Rasenerneuerung vorbereiten<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Zuerst sollte der Rasen sehr tief gem\u00e4ht werden, damit der Altbestand geschw\u00e4cht wird. Stark vermooster Rasen muss vertikutiert werden, damit die Wurzelunkr\u00e4uter und altes Gras beseitigt werden. Zudem wird durch den Vertikutierer der Boden leicht angeritzt, damit das Saatgut leichter keimen kann.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Rasen_saeen\"><\/span>Rasen s\u00e4en<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nachdem der Boden vorbereitet wurde, k\u00f6nnen die Rasensamen ges\u00e4t werden. Wichtig ist, dass das Nachs\u00e4en bei feuchtwarmer Witterung erfolgt. Damit das Saatgut gleichm\u00e4\u00dfig verteilt wird, sollte ein Saatwagen genutzt werden. Nach dem S\u00e4en ist das Saatgut mit einer Harke einzuarbeiten.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Rasenflaeche_waessern\"><\/span>Rasenfl\u00e4che w\u00e4ssern<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nach dem S\u00e4en der Rasensamen muss nat\u00fcrlich gew\u00e4ssert werden. Allerdings ist hier darauf zu achten, dass zum einen die Samen nicht wegschwimmen und sich zum anderen keine Pf\u00fctzen bilden. Bei sehr trockener Witterung sollte mehrmals t\u00e4glich ein wenig gew\u00e4ssert werden. In der Regel zeigen sich die ersten Grash\u00e4lmchen nach vier bis sieben Tagen.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Der_erste_Schnitt_und_die_Duengung\"><\/span>Der erste Schnitt und die D\u00fcngung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nach etwa vier Wochen hat der Rasen dann eine H\u00f6he von rund zehn Zentimetern erreicht. Nun ist der richtige Zeitpunkt f\u00fcr den ersten Schnitt. Der Rasen sollte dann auf eine H\u00f6he von f\u00fcnf bis sechs Zentimeter zur\u00fcckgeschnitten werden. Im Anschluss wird ein stickstoffbetonter Langzeitd\u00fcnger ausgebracht, der die Triebbildung f\u00f6rdert und die daf\u00fcr sorgt, dass die Gr\u00fcnfl\u00e4che dicht wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rasen ist nicht gleich Rasen und es gibt f\u00fcr jeden Verwendungszweck die richtigen Rasensamen. Diese unterscheiden sich vor allem bei der Strapazierf\u00e4higkeit, der Pflege und auch der Zusammensetzung der verschiedenen Gr\u00e4ser. Aus diesem Grund ist es wichtig, schon vor dem Anlegen des Rasens genau zu wissen, f\u00fcr welchen Zweck der Rasen sein soll? Wer einen englischen Rasen bevorzugt, kann dann nicht die Samenmischung f\u00fcr einen Sportrasen nutzen. Damit jeder einen \u00dcberblick bekommt, haben wir hier die verschiedenen Rasenarten zusammengefasst. Rasensamen nach Verwendungszweck kaufen Es gibt viele verschiedenen Rasentypen, die genau auf die Bed\u00fcrfnisse der jeweiligen G\u00e4rten abgestimmt sind. Daher ist es wichtig, vorher zu entscheiden, welche Rasentypen in den Garten passen und f\u00fcr welchen Zweck sie bestimmt sind. Bei den unterschiedlichen Typen werden verschiedene Zuchtsorgen und Gr\u00e4serarten miteinander kombiniert, damit sie Trockenheit, Schatten oder auch starken Belastungen standhalten k\u00f6nnen. Daher haben alle Rasentypen verschiedene Eigenschaften. Spiel- und Sportrasen Spiel- und Sportrasen ist eine Mischung, die aus Deutschem Weidelgras (Lolium perenne), Rotschwingel (Festuca rubra) und Wiesenrispe (Poa pratensis) besteht. Insbesondere dieser Rasentyp ist einer der am h\u00e4ufigsten verwendeten Sorten, da er sehr belastbar ist. Wer Kinder im Haushalt hat, sollte diese Sorte w\u00e4hlen, da er die Spiel- und Sportaktivit\u00e4ten sehr gut [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":13433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"hersteller":[],"class_list":["post-13384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rasen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rasenarten f\u00fcr jeden Zweck - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"F\u00fcr jeden Standort gibt es einen speziellen Rasen. Die Gr\u00e4ser der Rasenmischungen sind an die jeweiligen Bedingungen angepasst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rasenarten f\u00fcr jeden Zweck - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr jeden Standort gibt es einen speziellen Rasen. Die Gr\u00e4ser der Rasenmischungen sind an die jeweiligen Bedingungen angepasst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-03T10:17:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-14T13:15:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_31289336-scaled-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stephanie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stephanie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck\"},\"author\":{\"name\":\"Stephanie\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/97f059f6e72cec571c88cb48b4582118\"},\"headline\":\"Rasenarten f\u00fcr jeden Zweck\",\"datePublished\":\"2022-07-03T10:17:20+00:00\",\"dateModified\":\"2023-11-14T13:15:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck\"},\"wordCount\":1362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Rasenarten_31289336-scaled-1.jpeg\",\"articleSection\":[\"Rasen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck\",\"name\":\"Rasenarten f\u00fcr jeden Zweck - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Rasenarten_31289336-scaled-1.jpeg\",\"datePublished\":\"2022-07-03T10:17:20+00:00\",\"dateModified\":\"2023-11-14T13:15:23+00:00\",\"description\":\"F\u00fcr jeden Standort gibt es einen speziellen Rasen. Die Gr\u00e4ser der Rasenmischungen sind an die jeweiligen Bedingungen angepasst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Rasenarten_31289336-scaled-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Rasenarten_31289336-scaled-1.jpeg\",\"width\":2560,\"height\":1449,\"caption\":\"Rasenarten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/rasenarten-fuer-jeden-zweck#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rasenarten f\u00fcr jeden Zweck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/97f059f6e72cec571c88cb48b4582118\",\"name\":\"Stephanie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/stefanie-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/stefanie-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/stefanie-150x150.png\",\"caption\":\"Stephanie\"},\"description\":\"Garten und Pflanzen waren schon immer meine Leidenschaft. Wahrscheinlich deshalb, weil ich damit aufgewachsen bin. Ich verwerte in der Regel alles und mache Lik\u00f6re, Marmeladen und nutze Kr\u00e4uter auch als Heilpflanzen, indem ich \u00d6le und Tinkturen herstelle. Leider habe ich meinen gr\u00fcnen Daumen beim Auswandern nach Spanien in Deutschland vergessen. Langsam kehrt er aber wieder zur\u00fcck und die Anpassung an die neue Klimazone war gar nicht so einfach. Mittlerweile schaffe ich es sogar, dass gekaufter Basilikum \u00fcberlebt.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/stephanie\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rasenarten f\u00fcr jeden Zweck - Samenhaus Gartenblog","description":"F\u00fcr jeden Standort gibt es einen speziellen Rasen. Die Gr\u00e4ser der Rasenmischungen sind an die jeweiligen Bedingungen angepasst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck","og_locale":"de_DE","og_type":"article","og_title":"Rasenarten f\u00fcr jeden Zweck - Samenhaus Gartenblog","og_description":"F\u00fcr jeden Standort gibt es einen speziellen Rasen. Die Gr\u00e4ser der Rasenmischungen sind an die jeweiligen Bedingungen angepasst.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2022-07-03T10:17:20+00:00","article_modified_time":"2023-11-14T13:15:23+00:00","og_image":[{"width":2560,"height":1449,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_31289336-scaled-1.jpeg","type":"image\/jpeg"}],"author":"Stephanie","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Stephanie","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck"},"author":{"name":"Stephanie","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/97f059f6e72cec571c88cb48b4582118"},"headline":"Rasenarten f\u00fcr jeden Zweck","datePublished":"2022-07-03T10:17:20+00:00","dateModified":"2023-11-14T13:15:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck"},"wordCount":1362,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_31289336-scaled-1.jpeg","articleSection":["Rasen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck","url":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck","name":"Rasenarten f\u00fcr jeden Zweck - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_31289336-scaled-1.jpeg","datePublished":"2022-07-03T10:17:20+00:00","dateModified":"2023-11-14T13:15:23+00:00","description":"F\u00fcr jeden Standort gibt es einen speziellen Rasen. Die Gr\u00e4ser der Rasenmischungen sind an die jeweiligen Bedingungen angepasst.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_31289336-scaled-1.jpeg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Rasenarten_31289336-scaled-1.jpeg","width":2560,"height":1449,"caption":"Rasenarten"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/rasenarten-fuer-jeden-zweck#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Rasenarten f\u00fcr jeden Zweck"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/97f059f6e72cec571c88cb48b4582118","name":"Stephanie","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/stefanie-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/stefanie-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/stefanie-150x150.png","caption":"Stephanie"},"description":"Garten und Pflanzen waren schon immer meine Leidenschaft. Wahrscheinlich deshalb, weil ich damit aufgewachsen bin. Ich verwerte in der Regel alles und mache Lik\u00f6re, Marmeladen und nutze Kr\u00e4uter auch als Heilpflanzen, indem ich \u00d6le und Tinkturen herstelle. Leider habe ich meinen gr\u00fcnen Daumen beim Auswandern nach Spanien in Deutschland vergessen. Langsam kehrt er aber wieder zur\u00fcck und die Anpassung an die neue Klimazone war gar nicht so einfach. Mittlerweile schaffe ich es sogar, dass gekaufter Basilikum \u00fcberlebt.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/stephanie"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/13384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=13384"}],"version-history":[{"count":2,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/13384\/revisions"}],"predecessor-version":[{"id":14193,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/13384\/revisions\/14193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/13433"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=13384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=13384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=13384"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=13384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}