{"id":14008,"date":"2023-05-12T09:00:58","date_gmt":"2023-05-12T07:00:58","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=14008"},"modified":"2025-06-12T09:13:23","modified_gmt":"2025-06-12T07:13:23","slug":"bluetenendfaeule-hilfe-meine-tomaten-werden-braun","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun","title":{"rendered":"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun"},"content":{"rendered":"<p lang=\"de-DE\">Wenn sich die ersten Tomatenrispen bilden, ist die Freude gro\u00df, erst recht dann, wenn die Fr\u00fcchte immer gr\u00f6\u00dfer werden und so langsam ihre leuchtend rote Farbe annehmen. Doch pl\u00f6tzlich sehen Sie auf einer Frucht eine braune Stelle. Und auf einer weiteren Frucht ebenso. Und auch auf einer dritten. Der Schreck sitzt tief, denn die Tomatenernte scheint in Gefahr zu sein. Die braunen bis schwarzen Stellen deuten auf die Bl\u00fctenendf\u00e4ule hin. Diese l\u00e4sst sich zwar behandeln, Vorbeugung ist aber die bessere Wahl.<\/p>\n<h2 lang=\"de-DE\"><span class=\"ez-toc-section\" id=\"Bluetenendfaeule_%E2%80%93_wenn_Calcium_fehlt\"><\/span>Bl\u00fctenendf\u00e4ule \u2013 wenn Calcium fehlt<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p lang=\"de-DE\"><a href=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_449160375-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21715\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_449160375-600x400.jpeg\" alt=\"befallene Tomate\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_449160375-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_449160375-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_449160375-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_449160375-1536x1024.jpeg 1536w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_449160375-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Beim Namen Bl\u00fctenendf\u00e4ule k\u00f6nnte man meinen, dass die Bl\u00fcten betroffen w\u00e4ren. Die Krankheit breitet sich aber erst dann aus, wenn die Fr\u00fcchte bereits zu sehen sind. Beginnend vom Fruchtansatz aus, also dort, wo einst die Bl\u00fcte war, bilden sich besagte braune Stellen und werden immer gr\u00f6\u00dfer \u2013 somit Bl\u00fctenendf\u00e4ule.<\/p>\n<p lang=\"de-DE\">Oft sind Hobbyg\u00e4rtner der Meinung, bei der Bl\u00fctenendf\u00e4ule handele es sich um einen Pilz. Dem ist aber nicht so. Vielmehr ist es eine Krankheit, die auf einen Calciummangel zur\u00fcckzuf\u00fchren ist. Und dieser ist hausgemacht, denn er geht immer mit Versorgungs- und Pflegefehlern einher.<\/p>\n<p lang=\"de-DE\"><strong>\u00dcbrigens:<\/strong> Tomaten sind die Pflanzen, die am h\u00e4ufigsten von Bl\u00fctenendf\u00e4ule betroffen sind. Es k\u00f6nnen aber noch weitere Fr\u00fcchte davon befallen werden, wenn auch seltener:<\/p>\n<ul>\n<li lang=\"de-DE\">Paprika<\/li>\n<li lang=\"de-DE\">Chili<\/li>\n<li lang=\"de-DE\">Peperoni<\/li>\n<li lang=\"de-DE\">Zucchini<\/li>\n<li lang=\"de-DE\">Gurken<\/li>\n<li lang=\"de-DE\">Melonen<\/li>\n<li lang=\"de-DE\">Auberginen<\/li>\n<\/ul>\n<h2 lang=\"de-DE\"><span class=\"ez-toc-section\" id=\"Warum_Calcium_lebenswichtig_ist\"><\/span>Warum Calcium lebenswichtig ist<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p lang=\"de-DE\">Calcium wird von der Pflanze ben\u00f6tigt, um die Zellw\u00e4nde zu stabilisieren. Ist nicht gen\u00fcgend vorhanden, werden diese instabil und k\u00f6nnen aufweichen. Das Gewebe stirbt, wird dunkel und weich, zuweilen auch ledrig.<\/p>\n<p lang=\"de-DE\">Kommt es zur Bl\u00fctenendf\u00e4ule, dann fehlt eben dieses Calcium. Selbst wenn es ausreichend gegeben wird und der Boden damit gut angereichert ist, kommt es nicht dort an, wo es ben\u00f6tigt wird \u2013 die Ursachen daf\u00fcr erl\u00e4utern wir etwas weiter unten. Es ist somit nicht m\u00f6glich, \u00fcber D\u00fcngergaben den Calciummangel zu regulieren, denn die Pflanze kann es unter bestimmten Voraussetzungen schlicht und einfach nicht mehr aufnehmen.<\/p>\n<p lang=\"de-DE\">Es gibt zwei Gr\u00fcnde, warum die Fr\u00fcchte zuerst von der Bl\u00fctenendf\u00e4ule betroffen sind:<\/p>\n<ol>\n<li lang=\"de-DE\">Werden Wasser und N\u00e4hrstoffe \u00fcber den Boden aufgenommen, werden damit zuerst die Zweige und Bl\u00e4tter versorgt. Die Fr\u00fcchte sind zum Schluss dran, wodurch sich der Mangel an den Tomaten selbst zeigt.<\/li>\n<li lang=\"de-DE\">Die Pflanze verdunstet \u00fcber alle Pflanzenteile Wasser. Nicht nur \u00fcber die Bl\u00e4tter, sondern auch \u00fcber die Fr\u00fcchte. Bl\u00e4tter verdunsten jedoch weitaus mehr Fl\u00fcssigkeit, als die Tomaten, wodurch diese sp\u00e4ter mit N\u00e4hrstoffen versorgt werden.<\/li>\n<\/ol>\n<h2 lang=\"de-DE\"><span class=\"ez-toc-section\" id=\"Die_Symptome_der_Bluetenendfaeule\"><\/span>Die Symptome der Bl\u00fctenendf\u00e4ule<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p lang=\"de-DE\"><a href=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_898476720-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21718\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_898476720-600x400.jpeg\" alt=\"Tomate Bl\u00fctenf\u00e4ule\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_898476720-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_898476720-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_898476720-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_898476720-1536x1024.jpeg 1536w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_898476720-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Alles beginnt mit einem kleinen dunklen Punkt am Fruchtansatz. Anfangs noch unscheinbar, wird dieser Punkt gr\u00f6\u00dfer und gr\u00f6\u00dfer. Meist sind zuerst die unteren Fr\u00fcchte einer Pflanze bzw. einer Rispe betroffen. Auch kann der N\u00e4hrstoffmangel nur einzelne Fr\u00fcchte betreffen. W\u00e4hrend an einer Rispe ein, zwei Tomaten die charakteristischen Flecken zeigen, k\u00f6nnen andere Fr\u00fcchte kerngesund sein. Ein weiteres Symptom ist an den Bl\u00e4ttern zu erkennen, denn gerade die jungen Bl\u00e4tter wachsen nicht mehr weiter. In der Folge verkr\u00fcppeln diese und sterben ab.<\/p>\n<h2 lang=\"de-DE\"><span class=\"ez-toc-section\" id=\"Bluetenendfaeule_und_die_Ursachen\"><\/span>Bl\u00fctenendf\u00e4ule und die Ursachen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p lang=\"de-DE\">Nicht immer, aber sehr oft ist Bl\u00fctenendf\u00e4ule auf Pflegefehler zur\u00fcckzuf\u00fchren. Diese gilt es von Beginn an zu vermeiden. Und auch die weiteren Ursachen k\u00f6nnen mit etwas Vorausblick durchaus vermieden oder zumindest einged\u00e4mmt werden.<\/p>\n<ul>\n<li lang=\"de-DE\">Eine schlechte Bew\u00e4sserung: <a href=\"https:\/\/www.samenhaus.de\/tomatensamen\" target=\"_blank\" rel=\"noopener\">Tomaten<\/a> brauchen viel Wasser. Wird zu wenig gegeben und ist der Boden zu trocken, dann fehlt auch das ben\u00f6tigte Calcium. Ergo kommt es zum Mangel und kann in der Folge die Bl\u00fctenendf\u00e4ule ausl\u00f6sen.<\/li>\n<li lang=\"de-DE\">Zu hohe D\u00fcngergaben: Viel ist nicht immer besser! Besonders dann nicht, wenn es sich um zu hohe Konzentrationen an Kalium und Magnesium handelt, denn so kann die Pflanze Calcium ebenfalls schlecht oder gar nicht mehr aufnehmen.<\/li>\n<li lang=\"de-DE\">Zu hohe Luftfeuchtigkeit: Die Luftfeuchtigkeit im Garten kann niemand beeinflussen. Im Gew\u00e4chshaus dagegen schon. Daher betrifft dieser Punkt alle Pflanzen, die unter Glas gezogen werden. Bei zu hoher Luftfeuchtigkeit kann die Tomate weniger Wasser verdunsten, somit fehlen der Fl\u00fcssigkeits- und damit der N\u00e4hrstoffnachschub.<\/li>\n<li lang=\"de-DE\">Falscher Standort: Tomaten brauchen zwar die Sonne, manchmal kann dies aber auch zu viel sein. Vor allem dann, wenn im Sommer Hitzeperioden auftreten. Ist es \u00fcber einen l\u00e4ngeren Zeitraum zu hei\u00df, beginnt die Pflanze, sich selbst zu sch\u00fctzen. Um nicht auszutrocknen, werden die Spalt\u00f6ffnungen geschlossen, weswegen die Versorgung mit N\u00e4hrstoffen reduziert wird.<\/li>\n<li>Zu niedriger pH-Wert: Hierbei sind bestimmte N\u00e4hrstoffe in nicht ausreichender Form vorhanden, darunter besagtes Calcium.<\/li>\n<li lang=\"de-DE\">Zu hoher pH-Wert: Zwar ist Calcium bei einem h\u00f6heren pH-Wert ausreichend vorhanden, aber eben auch Stickstoff. Wenn die Konzentration von Stickstoff zu hoch ist, wird das Blattwachstum gef\u00f6rdert. Die Folge ist, dass das Calcium zuerst in die Bl\u00e4tter wandert und die Fr\u00fcchte wiederum unterversorgt werden. Der ideale pH-Wert f\u00fcr Tomaten liegt zwischen 5,5 und 7.<\/li>\n<\/ul>\n<h2 lang=\"de-DE\"><span class=\"ez-toc-section\" id=\"Die_Behandlung_von_Bluetenendfaeule\"><\/span>Die Behandlung von Bl\u00fctenendf\u00e4ule<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p lang=\"de-DE\"><a href=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_625996200-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21716\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_625996200-600x400.jpeg\" alt=\"Blattd\u00fcngung\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_625996200-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_625996200-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_625996200-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_625996200-1536x1024.jpeg 1536w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_625996200-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Eine direkte Behandlung betroffener Fr\u00fcchte gibt es nicht. Das hei\u00dft: Sind Fr\u00fcchte erst einmal befallen, kann das Schadbild nicht mehr r\u00fcckg\u00e4ngig gemacht werden. Allerdings k\u00f6nnen Sie aktiv werden, damit die Ursachen bek\u00e4mpft werden. So ist der Einsatz von Algenkalk, Gartenkalk oder Urgesteinsmehl anzuraten. Hier sollte Sie einmal pro Woche eine Anwendung vornehmen. Parallel dazu empfiehlt es sich, mit einer Blattd\u00fcngung die Pflanze direkt mit Calcium zu versorgen. So kann erreicht werden, dass die Pflanze wieder stabiler wird und die Bl\u00fctenendf\u00e4ule nicht weiter fortschreitet.<\/p>\n<p lang=\"de-DE\">Auch das Entfernen der unteren Triebe und der Geiztriebe ist sinnvoll. So k\u00f6nnen die N\u00e4hrstoffe direkt in h\u00f6here Regionen der Pflanze gelangen und versorgen nicht Triebe, die eigentlich gar nicht ben\u00f6tigt werden.<\/p>\n<p lang=\"de-DE\">Ein Hausmittel aus Eierschalen ist ebenfalls m\u00f6glich. Dazu k\u00f6nnen Sie Eierschalen zerkleinern und um die Pflanze auf der Erde verteilen. Alternativ geben Sie die Eierschalen f\u00fcr mindestens 2 Tage in Wasser und gie\u00dfen anschlie\u00dfend damit die Pflanzen.<\/p>\n<h2 lang=\"de-DE\"><span class=\"ez-toc-section\" id=\"Vorbeugende_Massnahmen_gegen_Bluetenendfaeule\"><\/span>Vorbeugende Ma\u00dfnahmen gegen Bl\u00fctenendf\u00e4ule<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p lang=\"de-DE\">Am besten ist die Prophylaxe, um Bl\u00fctenendf\u00e4ule erst gar nicht entstehen zu lassen.<\/p>\n<ol>\n<li lang=\"de-DE\">Bodenvorbereitung: Vor dem Pflanzen oder s\u00e4en sollte der Boden gut mit Calcium angereichert werden. Dazu sind Kompost oder entsprechender Tomatend\u00fcnger zu empfehlen. Um den genauen Calciumgehalt zu bestimmen, ist eine Bodenanalyse m\u00f6glich.<\/li>\n<li lang=\"de-DE\">Standort: W\u00e4hlen Sie einen sonnigen Standort aus, aber achten Sie darauf, dass bei l\u00e4ngeren Hitzeperioden die Pflanze auch mal durchschnaufen kann. Das hei\u00dft: 6 bis 7 Stunden Sonne sind gut, 12 Stunden dann doch zu viel.<\/li>\n<li lang=\"de-DE\">Bew\u00e4sserung: Regelm\u00e4\u00dfig Gie\u00dfgaben sind essenziell f\u00fcr Tomaten. Der Boden sollte gleichm\u00e4\u00dfig feucht sein, allerdings ohne Staun\u00e4sse. Sicherlich macht es nichts aus, wenn die Pflanzen mal einen Tag nicht gegossen werden, denn sie zeigen Wassermangel zuerst an h\u00e4ngenden Bl\u00e4ttern und Trieben. Ein gutes Mittelma\u00df ist entscheidend. Um den Boden l\u00e4ngere Zeit feucht zu halten, kann eine Mulchschicht helfen.<\/li>\n<li lang=\"de-DE\">pH-Wert: Zu niedrig ist genauso schlecht, wie zu hoch. Ideal ist ein Wert zwischen 5,5 und 7. Dann kann Calcium optimal aufgenommen werden.<\/li>\n<li lang=\"de-DE\">D\u00fcngen: Bei D\u00fcngergaben immer auf eine ausreichend Calciumzufuhr achten. Ged\u00fcngt werden kann \u00fcber den Boden ebenso, wie \u00fcber eine Blattd\u00fcngung.<\/li>\n<li>Luftfeuchtigkeit: Wenn sich Ihre Tomaten im Gew\u00e4chshaus befinden, dann ist eine Luftfeuchtigkeit zwischen 60 und maximal 80 % anzuraten. Sorgen Sie au\u00dferdem f\u00fcr eine gute Bel\u00fcftung. Tritt Bl\u00fctenendf\u00e4ule im Gew\u00e4chshaus auf, k\u00f6nnen Wei\u00dfe Fliegen zus\u00e4tzlichen Schaden anrichten.<\/li>\n<li lang=\"de-DE\">Sortenauswahl: Greifen Sie beim S\u00e4en und Pflanzen von Tomaten zu resistenten Sorten, die von vorneherein widerstandsf\u00e4higer sind.<\/li>\n<\/ol>\n<h2 lang=\"de-DE\"><span class=\"ez-toc-section\" id=\"Was_tun_mit_befallenen_Pflanzen_und_Fruechten\"><\/span>Was tun mit befallenen Pflanzen und Fr\u00fcchten?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p lang=\"de-DE\"><a href=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_217352873-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-21714\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_217352873-600x401.jpeg\" alt=\"kranke Tomate\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_217352873-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_217352873-1024x684.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_217352873-768x513.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_217352873-1536x1026.jpeg 1536w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_217352873-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ist eine Pflanze von der Bl\u00fctenendf\u00e4ule betroffen, m\u00fcssen nicht alle Fr\u00fcchte davon befallen sein. Intakte Fr\u00fcchte k\u00f6nnen Sie weiterhin genauso ernten und essen, wie gewohnt. Da es sich bei der Bl\u00fctenendf\u00e4ule nicht um eine Krankheit handelt, sondern um eine Mangelerscheinung, k\u00f6nnen Sie sogar leicht befallene Fr\u00fcchte noch konsumieren. Dazu einfach die befallenen Stellen ausschneiden. Geschmacklich werden Sie keinen Unterschied feststellen. Dennoch ist Vorsicht geboten, denn durch die Gewebesch\u00e4den k\u00f6nnen Pilze und Bakterien leichter in befallene Fr\u00fcchte eindringen.<\/p>\n<p lang=\"de-DE\">Sofern die Krankheit schon einen Gro\u00dfteil der Fr\u00fcchte befallen hat, ist die Entsorgung der Pflanze anzuraten, da gesunde Fr\u00fcchte kaum mehr entstehen werden. \u00dcbrigens: Tomaten mit Bl\u00fctenendf\u00e4ule k\u00f6nnen Sie bedenkenlos kompostieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn sich die ersten Tomatenrispen bilden, ist die Freude gro\u00df, erst recht dann, wenn die Fr\u00fcchte immer gr\u00f6\u00dfer werden und so langsam ihre leuchtend rote Farbe annehmen. Doch pl\u00f6tzlich sehen Sie auf einer Frucht eine braune Stelle. Und auf einer weiteren Frucht ebenso. Und auch auf einer dritten. Der Schreck sitzt tief, denn die Tomatenernte scheint in Gefahr zu sein. Die braunen bis schwarzen Stellen deuten auf die Bl\u00fctenendf\u00e4ule hin. Diese l\u00e4sst sich zwar behandeln, Vorbeugung ist aber die bessere Wahl. Bl\u00fctenendf\u00e4ule \u2013 wenn Calcium fehlt Beim Namen Bl\u00fctenendf\u00e4ule k\u00f6nnte man meinen, dass die Bl\u00fcten betroffen w\u00e4ren. Die Krankheit breitet sich aber erst dann aus, wenn die Fr\u00fcchte bereits zu sehen sind. Beginnend vom Fruchtansatz aus, also dort, wo einst die Bl\u00fcte war, bilden sich besagte braune Stellen und werden immer gr\u00f6\u00dfer \u2013 somit Bl\u00fctenendf\u00e4ule. Oft sind Hobbyg\u00e4rtner der Meinung, bei der Bl\u00fctenendf\u00e4ule handele es sich um einen Pilz. Dem ist aber nicht so. Vielmehr ist es eine Krankheit, die auf einen Calciummangel zur\u00fcckzuf\u00fchren ist. Und dieser ist hausgemacht, denn er geht immer mit Versorgungs- und Pflegefehlern einher. \u00dcbrigens: Tomaten sind die Pflanzen, die am h\u00e4ufigsten von Bl\u00fctenendf\u00e4ule betroffen sind. Es k\u00f6nnen aber noch weitere Fr\u00fcchte davon befallen werden, wenn [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":21717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"hersteller":[],"class_list":["post-14008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gemuese"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Bl\u00fctenendf\u00e4ule geh\u00f6rt zu den h\u00e4ufigsten Krankheiten beim Gem\u00fcse. Ursache ist ein Kalziummangel, der h\u00e4ufig durch falsches Gie\u00dfen entsteht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Bl\u00fctenendf\u00e4ule geh\u00f6rt zu den h\u00e4ufigsten Krankheiten beim Gem\u00fcse. Ursache ist ein Kalziummangel, der h\u00e4ufig durch falsches Gie\u00dfen entsteht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-12T07:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-12T07:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_677358881-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Holger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Holger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun\"},\"author\":{\"name\":\"Holger\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/de169769587431893823f62b2ce06c04\"},\"headline\":\"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun\",\"datePublished\":\"2023-05-12T07:00:58+00:00\",\"dateModified\":\"2025-06-12T07:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun\"},\"wordCount\":1417,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Tomaten-Braunfaeule_677358881-scaled.jpg\",\"articleSection\":[\"Gem\u00fcse\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun\",\"name\":\"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Tomaten-Braunfaeule_677358881-scaled.jpg\",\"datePublished\":\"2023-05-12T07:00:58+00:00\",\"dateModified\":\"2025-06-12T07:13:23+00:00\",\"description\":\"Bl\u00fctenendf\u00e4ule geh\u00f6rt zu den h\u00e4ufigsten Krankheiten beim Gem\u00fcse. Ursache ist ein Kalziummangel, der h\u00e4ufig durch falsches Gie\u00dfen entsteht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Tomaten-Braunfaeule_677358881-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Tomaten-Braunfaeule_677358881-scaled.jpg\",\"width\":2048,\"height\":1153,\"caption\":\"Bl\u00fctenf\u00e4ule Tomaten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/de169769587431893823f62b2ce06c04\",\"name\":\"Holger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Holger-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Holger-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Holger-150x150.png\",\"caption\":\"Holger\"},\"description\":\"6.000.000 W\u00f6rter \u2013 so viel k\u00f6nnen Sie in etwa von mir online lesen. Das F\u00fcllen des Internets entwickelte sich nach meiner Ausbildung zum TV-Redakteur und der langj\u00e4hrigen Arbeit bei SAT.1 zu einem Fulltime-Job. Trotzdem finde ich noch gen\u00fcgend Zeit, um in meinem Garten zu werkeln. Eine Staude hier, ein Bl\u00fcmchen dort und ein bisschen Gem\u00fcse darf auch nicht fehlen \u2013 einen Schnitzelbaum gibt es ja noch nicht \u2026 Die besten geistigen Erg\u00fcsse habe ich \u00fcbrigens, wenn ich IM Garten \u00dcBER den Garten schreiben kann. So vereinen sich Beruf und Hobby perfekt \u2013 was gibt es Sch\u00f6neres?\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/holger\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun - Samenhaus Gartenblog","description":"Bl\u00fctenendf\u00e4ule geh\u00f6rt zu den h\u00e4ufigsten Krankheiten beim Gem\u00fcse. Ursache ist ein Kalziummangel, der h\u00e4ufig durch falsches Gie\u00dfen entsteht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun","og_locale":"de_DE","og_type":"article","og_title":"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun - Samenhaus Gartenblog","og_description":"Bl\u00fctenendf\u00e4ule geh\u00f6rt zu den h\u00e4ufigsten Krankheiten beim Gem\u00fcse. Ursache ist ein Kalziummangel, der h\u00e4ufig durch falsches Gie\u00dfen entsteht.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2023-05-12T07:00:58+00:00","article_modified_time":"2025-06-12T07:13:23+00:00","og_image":[{"width":2048,"height":1153,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_677358881-scaled.jpg","type":"image\/jpeg"}],"author":"Holger","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Holger","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun"},"author":{"name":"Holger","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/de169769587431893823f62b2ce06c04"},"headline":"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun","datePublished":"2023-05-12T07:00:58+00:00","dateModified":"2025-06-12T07:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun"},"wordCount":1417,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_677358881-scaled.jpg","articleSection":["Gem\u00fcse"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun","url":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun","name":"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_677358881-scaled.jpg","datePublished":"2023-05-12T07:00:58+00:00","dateModified":"2025-06-12T07:13:23+00:00","description":"Bl\u00fctenendf\u00e4ule geh\u00f6rt zu den h\u00e4ufigsten Krankheiten beim Gem\u00fcse. Ursache ist ein Kalziummangel, der h\u00e4ufig durch falsches Gie\u00dfen entsteht.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_677358881-scaled.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/06\/Tomaten-Braunfaeule_677358881-scaled.jpg","width":2048,"height":1153,"caption":"Bl\u00fctenf\u00e4ule Tomaten"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/bluetenendfaeule-hilfe-meine-tomaten-werden-braun#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Bl\u00fctenendf\u00e4ule \u2013 Hilfe, meine Tomaten werden braun"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/de169769587431893823f62b2ce06c04","name":"Holger","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/Holger-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/Holger-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/Holger-150x150.png","caption":"Holger"},"description":"6.000.000 W\u00f6rter \u2013 so viel k\u00f6nnen Sie in etwa von mir online lesen. Das F\u00fcllen des Internets entwickelte sich nach meiner Ausbildung zum TV-Redakteur und der langj\u00e4hrigen Arbeit bei SAT.1 zu einem Fulltime-Job. Trotzdem finde ich noch gen\u00fcgend Zeit, um in meinem Garten zu werkeln. Eine Staude hier, ein Bl\u00fcmchen dort und ein bisschen Gem\u00fcse darf auch nicht fehlen \u2013 einen Schnitzelbaum gibt es ja noch nicht \u2026 Die besten geistigen Erg\u00fcsse habe ich \u00fcbrigens, wenn ich IM Garten \u00dcBER den Garten schreiben kann. So vereinen sich Beruf und Hobby perfekt \u2013 was gibt es Sch\u00f6neres?","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/holger"}]}},"wp-worthy-pixel":{"ignored":false,"public":"5e375693cc35457a957852a7b80578aa","server":"vg08.met.vgwort.de","url":"https:\/\/vg08.met.vgwort.de\/na\/5e375693cc35457a957852a7b80578aa"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/14008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=14008"}],"version-history":[{"count":7,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/14008\/revisions"}],"predecessor-version":[{"id":21719,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/14008\/revisions\/21719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/21717"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=14008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=14008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=14008"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=14008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}