{"id":19631,"date":"2025-08-03T09:00:06","date_gmt":"2025-08-03T07:00:06","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=19631"},"modified":"2025-07-25T11:25:17","modified_gmt":"2025-07-25T09:25:17","slug":"chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon","title":{"rendered":"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon"},"content":{"rendered":"<p>Sie lieben die Sch\u00e4rfe von Chili und verarbeiten deshalb frische Fr\u00fcchte aus Ihrem Garten? Sie haben so viel ernten k\u00f6nnen, dass Sie nicht wissen, wohin damit oder m\u00f6chten auch in der chilifreien Zeit etwas davon haben? Chili werden dabei in der Regel nicht als eigenst\u00e4ndiges Gem\u00fcse hergestellt, sondern kommen als Zutat zu Gem\u00fcse, Salat &amp; Co. Man kann die Fr\u00fcchte roh genauso essen, wie gekocht. Wir haben uns f\u00fcr Sie mal umgesehen, wie Sie Chili f\u00fcr viele Monate haltbar machen k\u00f6nnen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Chili_entschaerfen\"><\/span>Chili entsch\u00e4rfen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/www.samenhaus.de\/chilisamen\" target=\"_blank\" rel=\"noopener\">Chili<\/a> haben ganz unterschiedliche Sch\u00e4rfegrade. Die Stufen 0 bis 2 gelten mit bis zu 1.500 Scoville als mild, scharf wird es in den Stufen 3 bis 5, sehr scharf reicht bis Stufe 8 und stolzen 15.000 bis 100.000 Scoville. Danach wird es nicht nur extrem scharf, sondern beinahe unmenschlich \u2013 die sch\u00e4rfste Chili findet sich in der Kategorie 10+++, dabei handelt es sich um die Carolina Reaper mit einem Spitzenwert von 2,2 Millionen Scoville. Egal, wie scharf Sie gerne essen, m\u00f6chten Sie Ihre Chili etwas entsch\u00e4rfen, ist dies sehr einfach umzusetzen:<\/p>\n<p>Nehmen Sie die Chili und schneiden Sie diese klein. Bestreuen Sie die Fr\u00fcchte anschlie\u00dfend mit viel Salz und lassen alles mindestens 30 Minuten stehen. Gelegentlich umr\u00fchren! W\u00e4hrend dieser Zeit wird der Chili die Fl\u00fcssigkeit entzogen, in der die Sch\u00e4rfe geb\u00fcndelt vorkommt. Je l\u00e4nger Sie alles ziehen lassen, umso milder werden die Chili. Haben die Fr\u00fcchte den richtigen Sch\u00e4rfegrad f\u00fcr Sie erreicht, sp\u00fclen Sie alles in einem Sieb mit kaltem Wasser ab.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Chili_haltbar_machen_%E2%80%93_Glaeser_sterilisieren\"><\/span>Chili haltbar machen \u2013 Gl\u00e4ser sterilisieren<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sowohl beim Einlegen von Chili, aber auch beim Fermentieren oder beim Herstellen von Chilipaste oder Marmelade ben\u00f6tigen Sie <a href=\"https:\/\/www.samenhaus.de\/einmachglaeser\" target=\"_blank\" rel=\"noopener\">Einmachgl\u00e4ser<\/a>. Damit der Inhalt auch nach vielen Monaten nicht schlecht wird, m\u00fcssen diese Gl\u00e4ser inklusive der Deckel vor dem Einmachen sterilisiert werden. Stellen Sie die Gl\u00e4ser und die Deckel daf\u00fcr rund 15 Minuten in kochendes Wasser. Danach herausnehmen und an der Luft trocknen lassen. Danach k\u00f6nnen sie bef\u00fcllt werden.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Chili_konservieren_%E2%80%93_8_raffinierte_Moeglichkeiten\"><\/span>Chili konservieren \u2013 8 raffinierte M\u00f6glichkeiten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ob Chili zum Salat, zu Suppen oder Eint\u00f6pfen, um Gem\u00fcse aufzupeppen oder auch mal die s\u00fc\u00df-scharfe Variante als Marmelade \u2013 wir haben 8 M\u00f6glichkeiten f\u00fcr Sie ausgegraben, wie Sie Chili lange haltbar machen k\u00f6nnen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chili_trocknen\"><\/span>Chili trocknen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Chili k\u00f6nnen Sie im Backofen, im D\u00f6rrger\u00e4t oder an der Luft trocknen. Bevor es losgeht, sollten Sie die Fr\u00fcchte gut waschen und vollst\u00e4ndig trocknen lassen, um Schimmelbildung zu vermeiden. Wer m\u00f6chte, kann die Stiele entfernen, das ist aber nicht zwingend n\u00f6tig.<\/p>\n<p>Chili im Backofen trocknen \u2013 so wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Die Chilis gleichm\u00e4\u00dfig auf ein mit Backpapier ausgelegtes Backblech legen \u2013 darauf achten, dass sie nicht \u00fcbereinander liegen.<\/li>\n<li>Den Ofen auf 50 bis 60 Grad einstellen und das Backblech hineinschieben.<\/li>\n<li>Die Backofent\u00fcre einen Spalt ge\u00f6ffnet lassen, um den Luftaustausch zu gew\u00e4hrleisten.<\/li>\n<li>Bis die Chili trocken sind, kann es 6 bis 8 Stunden dauern, gelegentlich sollten die Chili gewendet werden.<\/li>\n<li>Die Chili sind fertig, wenn sie sich trocken und knusprig anf\u00fchlen, wenn sie sich noch biegen lassen, sind sie noch nicht fertig.<\/li>\n<\/ol>\n<p>Chili im D\u00f6rrger\u00e4t trocken \u2013 so wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili auf die Einsch\u00fcbe des D\u00f6rrger\u00e4ts legen, achten Sie darauf, dass sie nicht \u00fcbereinander liegen.<\/li>\n<li>Temperatur auf 50 bis 60 Grad einstellen.<\/li>\n<li>Abh\u00e4ngig von der Gr\u00f6\u00dfe und der Dicke der Chili dauert der Trockenvorgang 8 bis 12 Stunden.<\/li>\n<li>Die Chili sind fertig, wenn Sie sich trocken und knusprig anf\u00fchlen, wenn sie sich noch biegen lassen, sind sie noch nicht fertig.<\/li>\n<\/ol>\n<p>Chili an der Luft trocknen \u2013 so wird\u00b4s gemacht:<\/p>\n<ol>\n<li>F\u00e4deln Sie mit einer Nadel einen starken Faden durch die Stiele und h\u00e4ngen Sie die Fr\u00fcchte an einem warmen Ort mit guter Luftzirkulation auf. Direkte Sonne sollte vermieden werden, da diese den Geschmack beeintr\u00e4chtigen kann.<\/li>\n<li>Die Trocknungszeit liegt \u2013 je nach Dicke und St\u00e4rke der Chilis \u2013 zwischen 1 und 3 Wochen. Die Chilis sind fertig, wenn sie vollst\u00e4ndig trocken und br\u00fcchig sind, lassen sie sich noch biegen, brauchen sie noch etwas.<\/li>\n<\/ol>\n<p>Getrocknete Chili bewahren Sie am luftdicht und trocken in einem Beh\u00e4lter auf. Sie sind bis zu 2 Jahre haltbar.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chili_einfrieren\"><\/span>Chili einfrieren<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Am schnellsten geht das Einfrieren von Chili \u2013 Sie k\u00f6nnen sie im Ganzen einfrieren, aber auch in St\u00fccke oder Scheiben geschnitten.<\/p>\n<p>So wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili waschen und vollst\u00e4ndig trocknen lassen, damit sich anschlie\u00dfend keine Eiskristalle bilden.<\/li>\n<li>Wer Chili schneiden m\u00f6chte, entfernt die Stiele und schneidet sie in die entsprechenden St\u00fccke.<\/li>\n<li>Um zu verhindern, dass die Chilis zusammenklumpen, sollten Sie sie vor dem Einfrieren schockfrosten. Dazu werden sie in einer Schicht auf ein Backblech gelegt und f\u00fcr 1 bis 2 Stunden ins Gefrierfach gegeben.<\/li>\n<li>Nun werden die Fr\u00fcchte in Gefrierbeutel oder luftdichte Beh\u00e4lter verpackt und in den Gefrierschrank gelegt.<\/li>\n<\/ol>\n<p>Eingefrorene Chilis sind bis zu 1 Jahr haltbar. Je l\u00e4nger sie gelagert werden, umso mehr b\u00fc\u00dfen sie an Aroma und Sch\u00e4rfe ein.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chili_in_Essig_einlegen\"><\/span>Chili in Essig einlegen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Chilis in Essig geben den Fr\u00fcchten nicht nur ein ganz besonderes Aroma, der Essig konserviert sie auch f\u00fcr eine lange Zeit.<\/p>\n<p>Zutaten:<\/p>\n<ul>\n<li>500 ml Wasser<\/li>\n<li>500 ml Wei\u00dfwein- oder Apfelessig<\/li>\n<li>2-3 EL Zucker<\/li>\n<li>1-2 EL Salz<\/li>\n<li>Gew\u00fcrze nach Wahl (z. B. Lorbeerbl\u00e4tter, Senfk\u00f6rner, Pfefferk\u00f6rner, Knoblauchzehen, Thymian, Rosmarin etc.)<\/li>\n<\/ul>\n<p>So wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili waschen, trocken tupfen und nach Belieben schneiden \u2013 alternativ im Ganzen lassen.<\/li>\n<li>Den Essig mit dem Wasser mischen und in einem Topf erhitzen.<\/li>\n<li>Zucker und Salz zugeben und aufl\u00f6sen lassen.<\/li>\n<li>Gew\u00fcrze nach Wahl zugeben und alles ca. 5 Minuten leicht k\u00f6cheln lassen.<\/li>\n<li>Die Chilis nun in die Gl\u00e4ser f\u00fcllen. Lassen Sie zum Rand etwas Platz, damit am Schluss alles unter dem Essigsud liegt.<\/li>\n<li>Jetzt den noch hei\u00dfen Sud einf\u00fcllen und die Gl\u00e4ser verschlie\u00dfen.<\/li>\n<li>Um die Haltbarkeit noch zu verl\u00e4ngern, k\u00f6nnen Sie die Gl\u00e4ser zus\u00e4tzlich einkochen, indem Sie sie 15 Minuten in kochendes Wasser stellen.<\/li>\n<li>Vor Gebrauch 2 Wochen ziehen lassen. Lagern Sie die eigelegten Chili dunkel und k\u00fchl.<\/li>\n<\/ol>\n<p>Chili in Essig sind 1 Jahr und l\u00e4nger haltbar.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chili_in_Oel_einlegen\"><\/span>Chili in \u00d6l einlegen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Auch \u00d6l ist perfekt, um Gem\u00fcse lange zu konservieren. Wichtig ist, dass Sie hochwertiges \u00d6l wie Oliven\u00f6l oder Raps\u00f6l verwenden.<\/p>\n<p>Zutaten:<\/p>\n<ul>\n<li>Wasser<\/li>\n<li>Hochwertiges Speise\u00f6l<\/li>\n<li>Salz<\/li>\n<li>Gew\u00fcrze und Kr\u00e4uter nach Wahl (z. B. Lorbeerbl\u00e4tter, Pfefferk\u00f6rner, Knoblauchzehen, Senfk\u00f6rner, Thymian, Oregano, Rosmarin etc.)<\/li>\n<\/ul>\n<p>So wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili waschen und mit einem Tuch abtrocknen. Auf Wunsch klein schneiden.<\/li>\n<li>In einem Topf Wasser zum Kochen bringen und die Chilis f\u00fcr 2 bis 3 Minuten blanchieren. Danach mit Eiswasser abschrecken und gr\u00fcndlich abtrocknen.<\/li>\n<li>Optional k\u00f6nnen Sie die Chilis in einer Pfanne mit etwas Oliven\u00f6l 2 bis 3 Minuten anbraten.<\/li>\n<li>Das \u00d6l mit den Gew\u00fcrzen und Kr\u00e4utern nach Wahl erw\u00e4rmen, um so die Aromen zu intensivieren.<\/li>\n<li>Die Chilis in sterilisierte Gl\u00e4ser f\u00fcllen und den \u00d6l-Sud dar\u00fcber geben, sodass alles mit \u00d6l bedeckt ist.<\/li>\n<li>Gl\u00e4ser zuschrauben und an einem k\u00fchlen und dunklen Ort lagern.<\/li>\n<\/ol>\n<p>Chili in \u00d6l eingelegt sind 6 Monate und l\u00e4nger haltbar. Im K\u00fchlschrank gelagert, kann das \u00d6l fest werden. Vor Gebrauch daher auf Zimmertemperatur bringen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chilipaste_herstellen\"><\/span>Chilipaste herstellen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Mit einer selbst hergestellten Chilipaste k\u00f6nnen Sie viele Speisen verfeinern und ihnen eine angenehme Sch\u00e4rfe geben. Unsere Zutatenliste ist optional und kann nat\u00fcrlich jederzeit erweitert werden.<\/p>\n<p>Zutaten:<\/p>\n<ul>\n<li>250 g frische Chili<\/li>\n<li>3-4 Knoblauchzehen<\/li>\n<li>1 TL Salz<\/li>\n<li>2-3 EL Essig oder Zitronensaft<\/li>\n<li>2-3 EL Oliven\u00f6l oder ein anderes hochwertiges \u00d6l<\/li>\n<li>Gew\u00fcrze nach Wahl (z. B. Kreuzk\u00fcmmel, Koriander, Paprika, Pfeffer etc.)<\/li>\n<\/ul>\n<p>So wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili waschen, entstielen und entkernen und in grobe St\u00fccke schneiden.<\/li>\n<li>Knoblauch sch\u00e4len und in grobe St\u00fccke schneiden.<\/li>\n<li>Gew\u00fcrze in eine Pfanne ohne \u00d6l etwas anr\u00f6sten, um das Aroma zu intensivieren.<\/li>\n<li>Alle Zutaten in einen Mixer geben oder mit einem P\u00fcrierstab zu einer Paste verarbeiten.<\/li>\n<li>Paste mit Salz, Essig oder Zitronensaft abschmecken.<\/li>\n<li>Die Paste in sterilisierte Gl\u00e4ser f\u00fcllen und verschlie\u00dfen. Eine zus\u00e4tzliche \u00d6lschicht an der Oberfl\u00e4che erh\u00f6ht die Haltbarkeit. Gl\u00e4ser dunkel und k\u00fchl lagern.<\/li>\n<\/ol>\n<p>Chilipaste ist bis zu 3 Monate und l\u00e4nger haltbar.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chili_fermentieren\"><\/span>Chili fermentieren<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Neben Essig und \u00d6l ist Salz eine weitere M\u00f6glichkeit, Chili lange haltbar zu machen \u2013 und zwar durch Fermentation.<\/p>\n<p>Zutaten:<\/p>\n<ul>\n<li>500 g frische Chili<\/li>\n<li>1 l Wasser<\/li>\n<li>30-50 g Salz<\/li>\n<li>Kr\u00e4uter und Gew\u00fcrze nach Wahl (z. B. Knoblauch, Zwiebeln, Rosmarin, Oregano, Thymian etc.)<\/li>\n<\/ul>\n<p>So wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili waschen und auf Wunsch in St\u00fccke oder Scheiben schneiden \u2013 alternativ ganz lassen.<\/li>\n<li>Stellen Sie nun eine Salzl\u00f6sung her. Dazu werden 30 bis 50 g Salz auf 1 Liter Wasser einger\u00fchrt und vollst\u00e4ndig aufgel\u00f6st. Je h\u00f6her der Salzgehalt, umso langsamer verl\u00e4uft die Fermentation, aber umso besser ist die Haltbarkeit.<\/li>\n<li>Chili in sterilisierte Gl\u00e4ser f\u00fcllen und gut andr\u00fccken, dass so wenig Lufteinschl\u00fcsse wie m\u00f6glich vorhanden sind. Gleichzeitig kommen auch Kr\u00e4uter und Gew\u00fcrze mit in das Glas.<\/li>\n<li>Die Salzlake in die Gl\u00e4ser geben, dabei m\u00fcssen alle Chilis vollst\u00e4ndig bedeckt sein.<\/li>\n<li>Idealerweise verwenden Sie ein Fermentationsgewicht, um alles unter der Oberfl\u00e4che zu halten.<\/li>\n<li>Den Deckel lose auflegen oder einen Fermentationsdeckel mit Ventil benutzen. Wichtig ist, dass die entstehenden Gase entweichen k\u00f6nnen.<\/li>\n<li>Bei Zimmertemperatur (18 bis 22 Grad) mindestens 5 bis 10 Tage fermentieren, bis der gew\u00fcnschte Geschmack erreicht ist. Bei der Fermentation bilden sich Bl\u00e4schen, das bedeutet, dass alles in Ordnung ist. Bildet sich ein wei\u00dfer Belag, handelt es sich um Kahmhefe, die einfach abgesch\u00f6pft werden kann.<\/li>\n<li>Sobald der passende Geschmack erreicht wurde, die Deckel fest zuschrauben und im K\u00fchlschrank lagern.<\/li>\n<\/ol>\n<p>Fermentierte Chili sind bis zu 1 Jahr haltbar.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chili_raeuchern\"><\/span>Chili r\u00e4uchern<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>M\u00f6chten Sie Chili mal anders genie\u00dfen, dann probieren Sie das R\u00e4uchern aus. Ihre Suppen, Eint\u00f6pfe &amp; Co. werden eine ganz besondere Note erhalten.<\/p>\n<p>So wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili waschen und trocken tupfen. Auf Wunsch k\u00f6nnen Sie die Fr\u00fcchte auch in Scheiben oder St\u00fccke schneiden.<\/li>\n<li>Zum R\u00e4uchern ben\u00f6tigen wir R\u00e4ucherholz, das ca. 30 Minuten lang in Wasser eingeweicht wird. So brennt es langsamer und gleichm\u00e4\u00dfiger.<\/li>\n<li>R\u00e4uchern k\u00f6nnen Sie in einem Smoker, aber auch auf einem Grill. Haben Sie eine Temperaturanzeige, stellen Sie diese auf ca. 80 bis 90 Grad ein.<\/li>\n<li>Platzieren Sie das R\u00e4ucherholz, um einen gleichm\u00e4\u00dfigen Rauch zu produzieren.<\/li>\n<li>Legen Sie nun die Chilis auf das Gitter und achten Sie darauf, dass sie sich nicht \u00fcberlappen.<\/li>\n<li>Bei geschlossenem Deckel werden die Fr\u00fcchte f\u00fcr 4 bis 6 Stunden bei konstanter Temperatur ger\u00e4uchert. Kontrollieren Sie jede Stunde, damit die Chilis nicht verbrennen.<\/li>\n<li>Je nach gew\u00fcnschtem Geschmack kann die R\u00e4ucherzeit variieren, f\u00fcr eine tiefe Rauchnote kann das R\u00e4uchern auch mal 12 Stunden dauern.<\/li>\n<li>Nach dem R\u00e4uchern sollten Sie die Chili vollst\u00e4ndig im Backofen, im D\u00f6rrger\u00e4t (jeweils bei 50 bis 60 Grad) oder an der Luft trocknen.<\/li>\n<li>F\u00fcllen Sie die getrockneten Chili in luftdichte Beh\u00e4lter und lagern Sie diese k\u00fchl und dunkel.<\/li>\n<\/ol>\n<p>Ger\u00e4ucherte Chili sind 1 Jahr und l\u00e4nger haltbar.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chili-Marmelade_herstellen\"><\/span>Chili-Marmelade herstellen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Achtung, jetzt wird\u00b4s s\u00fc\u00df und scharf zugleich \u2013 wir stellen Chili-Marmelade her!<\/p>\n<p>Zutaten:<\/p>\n<ul>\n<li>500 g frische Chili<\/li>\n<li>500 g Gelierzucker (2:1)<\/li>\n<li>300 ml Apfel- oder Wei\u00dfweinessig<\/li>\n<li>2-3 Knoblauchzehen<\/li>\n<li>1-2 rote Paprika<\/li>\n<li>Salz<\/li>\n<li>Gew\u00fcrze nach Wahl (z. B. Ingwer, Zitronensaft, Rosmarin, Thymian etc.)<\/li>\n<\/ul>\n<p>So wird\u00b4s gemacht:<\/p>\n<ol>\n<li>Chili und Paprika waschen, entstielen und entkernen und klein schneiden.<\/li>\n<li>Knoblauch sch\u00e4len und klein schneiden.<\/li>\n<li>Chili, Paprika und Knoblauch in einen Topf geben, Essig zuf\u00fcgen, ebenso Gelierzucker, Salz und Gew\u00fcrze nach Wahl und alles zum Kochen bringen. Ca. 5 Minuten sprudelnd kochen lassen und regelm\u00e4\u00dfig umr\u00fchren, damit nichts anbrennt.<\/li>\n<li>Um zu \u00fcberpr\u00fcfen, ob die Marmelade die richtige Konsistenz hat, f\u00fchren Sie eine Gelierprobe durch. Daf\u00fcr geben Sie einen kleinen Tropfen der hei\u00dfen Marmelade auf einen kalten Teller, kurz abk\u00fchlen lassen und den Finger durch die Marmelade ziehen. Wenn sie nicht zusammenl\u00e4uft, ist sie fertig.<\/li>\n<li>Die hei\u00dfe Chili-Marmelade in sterilisierte Gl\u00e4ser f\u00fcllen und verschlie\u00dfen. Danach k\u00fchl und dunkel lagern.<\/li>\n<\/ol>\n<p>Chili-Marmelade ist 1 Jahr und l\u00e4nger haltbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie lieben die Sch\u00e4rfe von Chili und verarbeiten deshalb frische Fr\u00fcchte aus Ihrem Garten? Sie haben so viel ernten k\u00f6nnen, dass Sie nicht wissen, wohin damit oder m\u00f6chten auch in der chilifreien Zeit etwas davon haben? Chili werden dabei in der Regel nicht als eigenst\u00e4ndiges Gem\u00fcse hergestellt, sondern kommen als Zutat zu Gem\u00fcse, Salat &amp; Co. Man kann die Fr\u00fcchte roh genauso essen, wie gekocht. Wir haben uns f\u00fcr Sie mal umgesehen, wie Sie Chili f\u00fcr viele Monate haltbar machen k\u00f6nnen. Chili entsch\u00e4rfen Chili haben ganz unterschiedliche Sch\u00e4rfegrade. Die Stufen 0 bis 2 gelten mit bis zu 1.500 Scoville als mild, scharf wird es in den Stufen 3 bis 5, sehr scharf reicht bis Stufe 8 und stolzen 15.000 bis 100.000 Scoville. Danach wird es nicht nur extrem scharf, sondern beinahe unmenschlich \u2013 die sch\u00e4rfste Chili findet sich in der Kategorie 10+++, dabei handelt es sich um die Carolina Reaper mit einem Spitzenwert von 2,2 Millionen Scoville. Egal, wie scharf Sie gerne essen, m\u00f6chten Sie Ihre Chili etwas entsch\u00e4rfen, ist dies sehr einfach umzusetzen: Nehmen Sie die Chili und schneiden Sie diese klein. Bestreuen Sie die Fr\u00fcchte anschlie\u00dfend mit viel Salz und lassen alles mindestens 30 Minuten stehen. Gelegentlich umr\u00fchren! [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":21998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"hersteller":[],"class_list":["post-19631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gemuese"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Chili sind sonderbare Fr\u00fcchte, die es in sich haben. Die milden bis feurig-scharfen Schoten k\u00f6nnen gut konserviert werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Chili sind sonderbare Fr\u00fcchte, die es in sich haben. Die milden bis feurig-scharfen Schoten k\u00f6nnen gut konserviert werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-03T07:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/07\/Chilis-einlegen_1466522127-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Holger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Holger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon\"},\"author\":{\"name\":\"Holger\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/de169769587431893823f62b2ce06c04\"},\"headline\":\"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon\",\"datePublished\":\"2025-08-03T07:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon\"},\"wordCount\":2035,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Chilis-einlegen_1466522127-scaled.jpg\",\"articleSection\":[\"Gem\u00fcse\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon\",\"name\":\"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Chilis-einlegen_1466522127-scaled.jpg\",\"datePublished\":\"2025-08-03T07:00:06+00:00\",\"description\":\"Chili sind sonderbare Fr\u00fcchte, die es in sich haben. Die milden bis feurig-scharfen Schoten k\u00f6nnen gut konserviert werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Chilis-einlegen_1466522127-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Chilis-einlegen_1466522127-scaled.jpg\",\"width\":2048,\"height\":1153,\"caption\":\"eingelegte Chilis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/de169769587431893823f62b2ce06c04\",\"name\":\"Holger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Holger-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Holger-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Holger-150x150.png\",\"caption\":\"Holger\"},\"description\":\"6.000.000 W\u00f6rter \u2013 so viel k\u00f6nnen Sie in etwa von mir online lesen. Das F\u00fcllen des Internets entwickelte sich nach meiner Ausbildung zum TV-Redakteur und der langj\u00e4hrigen Arbeit bei SAT.1 zu einem Fulltime-Job. Trotzdem finde ich noch gen\u00fcgend Zeit, um in meinem Garten zu werkeln. Eine Staude hier, ein Bl\u00fcmchen dort und ein bisschen Gem\u00fcse darf auch nicht fehlen \u2013 einen Schnitzelbaum gibt es ja noch nicht \u2026 Die besten geistigen Erg\u00fcsse habe ich \u00fcbrigens, wenn ich IM Garten \u00dcBER den Garten schreiben kann. So vereinen sich Beruf und Hobby perfekt \u2013 was gibt es Sch\u00f6neres?\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/holger\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon - Samenhaus Gartenblog","description":"Chili sind sonderbare Fr\u00fcchte, die es in sich haben. Die milden bis feurig-scharfen Schoten k\u00f6nnen gut konserviert werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon","og_locale":"de_DE","og_type":"article","og_title":"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon - Samenhaus Gartenblog","og_description":"Chili sind sonderbare Fr\u00fcchte, die es in sich haben. Die milden bis feurig-scharfen Schoten k\u00f6nnen gut konserviert werden.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2025-08-03T07:00:06+00:00","og_image":[{"width":2048,"height":1153,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/07\/Chilis-einlegen_1466522127-scaled.jpg","type":"image\/jpeg"}],"author":"Holger","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Holger","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon"},"author":{"name":"Holger","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/de169769587431893823f62b2ce06c04"},"headline":"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon","datePublished":"2025-08-03T07:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon"},"wordCount":2035,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/07\/Chilis-einlegen_1466522127-scaled.jpg","articleSection":["Gem\u00fcse"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon","url":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon","name":"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/07\/Chilis-einlegen_1466522127-scaled.jpg","datePublished":"2025-08-03T07:00:06+00:00","description":"Chili sind sonderbare Fr\u00fcchte, die es in sich haben. Die milden bis feurig-scharfen Schoten k\u00f6nnen gut konserviert werden.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/07\/Chilis-einlegen_1466522127-scaled.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2025\/07\/Chilis-einlegen_1466522127-scaled.jpg","width":2048,"height":1153,"caption":"eingelegte Chilis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/chili-haltbar-machen-so-haben-sie-das-ganze-jahr-etwas-davon#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Chili haltbar machen \u2013 so haben Sie das ganze Jahr etwas davon"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/de169769587431893823f62b2ce06c04","name":"Holger","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/Holger-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/Holger-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/Holger-150x150.png","caption":"Holger"},"description":"6.000.000 W\u00f6rter \u2013 so viel k\u00f6nnen Sie in etwa von mir online lesen. Das F\u00fcllen des Internets entwickelte sich nach meiner Ausbildung zum TV-Redakteur und der langj\u00e4hrigen Arbeit bei SAT.1 zu einem Fulltime-Job. Trotzdem finde ich noch gen\u00fcgend Zeit, um in meinem Garten zu werkeln. Eine Staude hier, ein Bl\u00fcmchen dort und ein bisschen Gem\u00fcse darf auch nicht fehlen \u2013 einen Schnitzelbaum gibt es ja noch nicht \u2026 Die besten geistigen Erg\u00fcsse habe ich \u00fcbrigens, wenn ich IM Garten \u00dcBER den Garten schreiben kann. So vereinen sich Beruf und Hobby perfekt \u2013 was gibt es Sch\u00f6neres?","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/holger"}]}},"wp-worthy-pixel":{"ignored":false,"public":"29c06c1b07dc4aadadf972ca74a42536","server":"vg07.met.vgwort.de","url":"https:\/\/vg07.met.vgwort.de\/na\/29c06c1b07dc4aadadf972ca74a42536"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/19631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=19631"}],"version-history":[{"count":5,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/19631\/revisions"}],"predecessor-version":[{"id":22000,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/19631\/revisions\/22000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/21998"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=19631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=19631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=19631"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=19631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}