{"id":5283,"date":"2022-07-22T09:00:34","date_gmt":"2022-07-22T09:00:34","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=5283"},"modified":"2023-08-09T04:37:34","modified_gmt":"2023-08-09T04:37:34","slug":"blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen","title":{"rendered":"Bl\u00e4tter von Kohlrabi, M\u00f6hren &#038; Co.: zu schade zum Wegwerfen"},"content":{"rendered":"<p class=\"western\">H\u00e4ufig landen die Bl\u00e4tter von Kohlrabi, M\u00f6hren oder Radieschen achtlos im Abfall und werden bestenfalls noch kompostiert. Die Bl\u00e4tter sind jedoch viel zu schade zum Wegwerfen, da sie reich an Vitaminen und N\u00e4hrstoffen sind. Sie k\u00f6nnen in der K\u00fcche auf verschiedene Weise verwendet werden.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Gemueseblaetter_die_essbar_sind_viele_wertvolle_Inhaltsstoffe\"><\/span>Gem\u00fcsebl\u00e4tter, die essbar sind: viele wertvolle Inhaltsstoffe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"western\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5496 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._303345763-300x200.jpeg\" alt=\"essbare Gem\u00fcsebl\u00e4tter\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._303345763-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._303345763-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._303345763-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._303345763-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._303345763-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._303345763-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Nicht von allen Gem\u00fcsesorten k\u00f6nnen die Bl\u00e4tter verwendet werden, denn sie k\u00f6nnen Giftstoffe enthalten. Es gibt jedoch einige Sorten, von denen die Bl\u00e4tter gut verwendbar sind. Sie enthalten oft noch mehr Vitamine und Mineralstoffe als die Knolle und sollten daher auf keinen Fall weggeworfen werden. Die Bl\u00e4tter dieser Gem\u00fcsesorten sind essbar und wertvoll f\u00fcr die Ern\u00e4hrung:<\/p>\n<ul>\n<li class=\"western\"><strong>Kohlrabibl\u00e4tter<\/strong> haben einen \u00e4hnlichen Geschmack wie die Knolle, doch enthalten sie noch mehr Vitamin A und Vitamin C als die Knolle selbst. Sie sind auch reich an Kalzium. Junge Bl\u00e4tter k\u00f6nnen in Salaten roh verzehrt werden, w\u00e4hrend sich gr\u00f6\u00dfere Bl\u00e4tter zum Kochen eignen.<\/li>\n<li class=\"western\"><strong>M\u00f6hrenkraut<\/strong> erinnert in seinem Geschmack an Petersilie und hat eine leichte Bitternote, da es Bitter- und Ballaststoffe enth\u00e4lt. Es kann als Ersatz f\u00fcr Petersilie, aber auch f\u00fcr Smoothies und andere Speisen verwendet werden.<\/li>\n<li class=\"western\"><strong>Radieschenbl\u00e4tter<\/strong> enthalten viele Senf\u00f6le, die Bakterien und Viren abwehren k\u00f6nnen. Sie senken den Cholesterinspiegel und den Blutdruck, binden Fett und eignen sich f\u00fcr Salate sowie Smoothies. \u00c4hnlich wie Radieschenbl\u00e4tter k\u00f6nnen Bl\u00e4tter von Rettichen, Teltower R\u00fcbchen oder Mair\u00fcbchen verwendet werden.<\/li>\n<li class=\"western\"><strong>Rote-Bete-Bl\u00e4tter<\/strong> enthalten 200 Mal mehr Vitamin A, 2.000 Mal mehr Vitamin K und sieben Mal mehr Kalzium als die Knolle und sind daher noch deutlich ges\u00fcnder. Sie eignen sich f\u00fcr Smoothies und Salate.<\/li>\n<li><strong>Selleriebl\u00e4tter<\/strong> sind reich an \u00e4therischen \u00d6len und haben einen w\u00fcrzigen Geschmack. Sie eignen sich hervorragend zum W\u00fcrzen von Suppen, Eint\u00f6pfen, Fleisch- und Fischgerichten, aber auch f\u00fcr Salate und Smoothies.<\/li>\n<li class=\"western\"><strong>Fenchelgr\u00fcn<\/strong> sieht nicht nur aus wie Dill, sondern es ist auch eine gute Alternative dazu. Es schmeckt w\u00fcrzig und hat eine leichte Anisnote. Es enth\u00e4lt \u00e4therische \u00d6le und eignet sich f\u00fcr Suppen, Salate, Fleisch- und Fischgerichte.<\/li>\n<\/ul>\n<p class=\"western\">Verwenden Sie die Bl\u00e4tter von Gem\u00fcse aus Ihrem eigenen Garten, sind sie frei von Pestiziden und anderen Schadstoffen. Kaufen Sie jedoch Gem\u00fcse und m\u00f6chten Sie die Bl\u00e4tter verwenden, sollten Sie auf Bio-Qualit\u00e4t achten, da Sie dann sicher sein k\u00f6nnen, dass sie frei von Schadstoffen sind.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Gemueseblaetter_die_Sie_nicht_verwenden_sollten\"><\/span>Gem\u00fcsebl\u00e4tter, die Sie nicht verwenden sollten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"western\">W\u00e4hrend Bl\u00e4tter von einigen Gem\u00fcsesorten au\u00dferordentlich gesund sind und f\u00fcr die menschliche Ern\u00e4hrung empfohlen werden, d\u00fcrfen Sie Bl\u00e4tter anderer Gem\u00fcsesorten nicht verwenden. Diese Bl\u00e4tter k\u00f6nnen gef\u00e4hrliche Giftstoffe enthalten, vor allem Solanin, das zu schweren Vergiftungserscheinungen f\u00fchren kann. Solanin ist in Bl\u00e4ttern von Nachtschattenpflanzen enthalten, zu denen<\/p>\n<ul>\n<li class=\"western\">Auberginen,<\/li>\n<li class=\"western\">Paprika,<\/li>\n<li class=\"western\">Tomaten und<\/li>\n<li class=\"western\">Kartoffeln<\/li>\n<\/ul>\n<p class=\"western\">geh\u00f6ren. Auch die Bl\u00e4tter von Gurken, Bohnen und Rhabarber enthalten Giftstoffe.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Verwendungsmoeglichkeiten_fuer_Gemueseblaetter_Smoothies_Pestos_oder_Salate\"><\/span>Verwendungsm\u00f6glichkeiten f\u00fcr Gem\u00fcsebl\u00e4tter: Smoothies, Pestos oder Salate<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"western\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5497 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._304397612-300x200.jpeg\" alt=\"Gem\u00fcsebl\u00e4tter Smoothies\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._304397612-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._304397612-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._304397612-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._304397612-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._304397612-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._304397612-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Wof\u00fcr Sie die Bl\u00e4tter verwenden, h\u00e4ngt von der Gem\u00fcsesorte ab. Kohlrabibl\u00e4tter k\u00f6nnen Sie zusammen mit den Kohlrabiknollen im Eintopf oder als Gem\u00fcsebeilage verwenden. Zarte, junge Bl\u00e4tter werden fein geschnitten und bereichern Rohkostsalate. Die Bl\u00e4tter sind aber auch hervorragend f\u00fcr die Bereitung von Smoothies geeignet. Bl\u00e4tter und Stiele von Kohlrabi sollten Sie d\u00fcnsten, wenn die Stiele bereits etwas fester sind. F\u00fcr Salate eignen sich auch Bl\u00e4tter von Radieschen, Roter Bete, Rettich, Sellerie oder Fenchel. Viele Gem\u00fcsebl\u00e4tter sind eine Bereicherung von Suppen und Eint\u00f6pfen. Sie k\u00f6nnen teilweise auch kleingeschnitten und \u00e4hnlich wie Kr\u00e4uter zum W\u00fcrzen verwendet werden. Eine gute Idee f\u00fcr die Verwendung ist auch die Bereitung von Pesto. Wissen Sie nicht, wie Sie die Bl\u00e4tter verwenden sollen, und haben Sie Haustiere wie Kaninchen oder Meerschweinchen, freuen sich Ihre tierischen Mitbewohner \u00fcber die Bl\u00e4tter als Futter.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Richtiger_Umgang_mit_den_Gemueseblaettern_sofort_vom_Gemuese_entfernen\"><\/span>Richtiger Umgang mit den Gem\u00fcsebl\u00e4ttern: sofort vom Gem\u00fcse entfernen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"western\">Die Gem\u00fcsebl\u00e4tter halten sich l\u00e4nger, wenn Sie sie sofort nach der Ernte oder nach dem Kauf vom Gem\u00fcse entfernen. In einem Glas mit Wasser oder in einem feuchten Tuch halten Sie die Bl\u00e4tter frisch. Das gelingt ohne K\u00fchlung, doch ist auch die Aufbewahrung im K\u00fchlschrank zu empfehlen, wenn Sie die Bl\u00e4tter nicht gleich verarbeiten. M\u00f6chten Sie sie garen, entfernen Sie sie von den Stielen, da sie eine k\u00fcrzere Garzeit haben. Garen Sie zuerst die Stiele und geben Sie dann die Bl\u00e4tter dazu.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Rezepte_fuer_Gemueseblaetter_eine_kleine_Auswahl\"><\/span>Rezepte f\u00fcr Gem\u00fcsebl\u00e4tter: eine kleine Auswahl<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"western\">Die folgenden Rezepte geben Ihnen eine Anregung, wie sich die Gem\u00fcsebl\u00e4tter verwenden lassen. Die in den Rezepten angegebenen Mengen ver\u00e4ndern Sie entsprechend, wenn Sie eine geringere Menge an Bl\u00e4ttern zur Verf\u00fcgung haben. Mit noch anderen Gem\u00fcsebl\u00e4ttern oder verschiedenen Gew\u00fcrzen lassen sich die Rezepte abwandeln.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Kohlrabi-Blattgemuese_schmackhafte_Gemuesebeilage\"><\/span>Kohlrabi-Blattgem\u00fcse: schmackhafte Gem\u00fcsebeilage<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"western\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5498 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._424777596-300x200.jpeg\" alt=\"Kohlrabi-Blattgem\u00fcse\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._424777596-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._424777596-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._424777596-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._424777596-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._424777596-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._424777596-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>F\u00fcr Kohlrabi-Blattgem\u00fcse ben\u00f6tigen Sie<\/p>\n<ul>\n<li class=\"western\">4 bis 5 Kohlrabibl\u00e4tter<\/li>\n<li class=\"western\">2 Knoblauchzehen<\/li>\n<li class=\"western\">1 Zwiebel<\/li>\n<li class=\"western\">Salz, Pfeffer<\/li>\n<li class=\"western\">Oliven\u00f6l<\/li>\n<\/ul>\n<p class=\"western\">Waschen Sie die Bl\u00e4tter, entfernen Sie Stiele und dicke Blattadern und schneiden Sie die Bl\u00e4tter in Streifen. Sch\u00e4len Sie Zwiebeln und Knoblauch und schneiden Sie beides in W\u00fcrfel. Erhitzen Sie das \u00d6l in der Pfanne und d\u00fcnsten Sie Zwiebeln sowie Knoblauch darin an. Geben Sie die Bl\u00e4tter dazu und garen Sie sie ungef\u00e4hr 25 Minuten. Schmecken Sie alles mit Salz und Pfeffer ab.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Smoothie_mit_Mango_und_Moehrengruen_gut_als_Snack_zwischendurch\"><\/span>Smoothie mit Mango und M\u00f6hrengr\u00fcn: gut als Snack zwischendurch<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"western\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5493 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._56077392-300x200.jpeg\" alt=\"Smoothie mit Mango und M\u00f6hrengr\u00fcn\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._56077392-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._56077392-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._56077392-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._56077392-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._56077392-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._56077392-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Sie ben\u00f6tigen f\u00fcr diesen Smoothie<\/p>\n<ul>\n<li class=\"western\">1\/2 Mango<\/li>\n<li class=\"western\">1\/2 Orange<\/li>\n<li class=\"western\">1\/2 Banane<\/li>\n<li class=\"western\">Gr\u00fcn von 2 M\u00f6hren<\/li>\n<li class=\"western\">75 Gramm Babyspinat<\/li>\n<li class=\"western\">1 Essl\u00f6ffel Lein\u00f6l<\/li>\n<li class=\"western\">200 Milliliter Wasser<\/li>\n<\/ul>\n<p class=\"western\">Sch\u00e4len Sie Mango, Banane und Orange und l\u00f6sen Sie das Fruchtfleisch der Mango vom Kern. Waschen Sie Babyspinat und M\u00f6hrengr\u00fcn und sch\u00fctteln Sie alles trocken. Geben Sie alle Zutaten in den Mixer und p\u00fcrieren Sie sie.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Moehrengruen-Pesto_ein_koestliches_Gewuerz\"><\/span>M\u00f6hrengr\u00fcn-Pesto: ein k\u00f6stliches Gew\u00fcrz<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"western\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5494 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._89340462-300x200.jpeg\" alt=\"M\u00f6hrengr\u00fcn-Pesto\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._89340462-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._89340462-600x401.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._89340462-768x513.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._89340462-1024x684.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._89340462-1536x1025.jpeg 1536w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._89340462-2048x1367.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Um ein M\u00f6hrengr\u00fcn-Pesto zu bereiten, brauchen Sie<\/p>\n<ul>\n<li class=\"western\">M\u00f6hrengr\u00fcn von ungef\u00e4hr 8 M\u00f6hren<\/li>\n<li class=\"western\">1 Knoblauchzehe<\/li>\n<li class=\"western\">2 Essl\u00f6ffel Pinienkerne oder gehackte Waln\u00fcsse<\/li>\n<li class=\"western\">100 Milliliter Oliven\u00f6l<\/li>\n<li class=\"western\">60 Gramm geriebener Parmesan<\/li>\n<li class=\"western\">Salz und Pfeffer<\/li>\n<\/ul>\n<p class=\"western\">Waschen Sie das M\u00f6hrengr\u00fcn und sch\u00fctteln Sie es trocken. Sch\u00e4len Sie die Knoblauchzehe und schneiden Sie sie in feine W\u00fcrfel. R\u00f6sten Sie die Pinienkerne oder Waln\u00fcsse hellbraun an. Zerkleinern Sie das M\u00f6hrengr\u00fcn grob. P\u00fcrieren Sie alle Zutaten bis auf das Oliven\u00f6l im Stabmixer bis zur gew\u00fcnschten Konsistenz. Geben Sie das Pesto in Gl\u00e4ser, f\u00fcllen Sie das Oliven\u00f6l auf, damit alles bedeckt ist, und verschlie\u00dfen Sie die Gl\u00e4ser. Im K\u00fchlschrank h\u00e4lt sich das Pesto mehrere Monate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e4ufig landen die Bl\u00e4tter von Kohlrabi, M\u00f6hren oder Radieschen achtlos im Abfall und werden bestenfalls noch kompostiert. Die Bl\u00e4tter sind jedoch viel zu schade zum Wegwerfen, da sie reich an Vitaminen und N\u00e4hrstoffen sind. Sie k\u00f6nnen in der K\u00fcche auf verschiedene Weise verwendet werden. Gem\u00fcsebl\u00e4tter, die essbar sind: viele wertvolle Inhaltsstoffe Nicht von allen Gem\u00fcsesorten k\u00f6nnen die Bl\u00e4tter verwendet werden, denn sie k\u00f6nnen Giftstoffe enthalten. Es gibt jedoch einige Sorten, von denen die Bl\u00e4tter gut verwendbar sind. Sie enthalten oft noch mehr Vitamine und Mineralstoffe als die Knolle und sollten daher auf keinen Fall weggeworfen werden. Die Bl\u00e4tter dieser Gem\u00fcsesorten sind essbar und wertvoll f\u00fcr die Ern\u00e4hrung: Kohlrabibl\u00e4tter haben einen \u00e4hnlichen Geschmack wie die Knolle, doch enthalten sie noch mehr Vitamin A und Vitamin C als die Knolle selbst. Sie sind auch reich an Kalzium. Junge Bl\u00e4tter k\u00f6nnen in Salaten roh verzehrt werden, w\u00e4hrend sich gr\u00f6\u00dfere Bl\u00e4tter zum Kochen eignen. M\u00f6hrenkraut erinnert in seinem Geschmack an Petersilie und hat eine leichte Bitternote, da es Bitter- und Ballaststoffe enth\u00e4lt. Es kann als Ersatz f\u00fcr Petersilie, aber auch f\u00fcr Smoothies und andere Speisen verwendet werden. Radieschenbl\u00e4tter enthalten viele Senf\u00f6le, die Bakterien und Viren abwehren k\u00f6nnen. Sie senken den Cholesterinspiegel und den Blutdruck, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"hersteller":[],"class_list":["post-5283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gemuese"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bl\u00e4tter von Kohlrabi, M\u00f6hren &amp; Co.: zu schade zum Wegwerfen - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Viel zu oft werfen wir Gr\u00fcn und Schalen von Obst und Gem\u00fcse weg. Dabei lassen sich auch aus vielen Bl\u00e4ttern noch super tolle Gerichte zaubern. Versuchen Sie es mal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bl\u00e4tter von Kohlrabi, M\u00f6hren &amp; Co.: zu schade zum Wegwerfen - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Viel zu oft werfen wir Gr\u00fcn und Schalen von Obst und Gem\u00fcse weg. Dabei lassen sich auch aus vielen Bl\u00e4ttern noch super tolle Gerichte zaubern. Versuchen Sie es mal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-22T09:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-09T04:37:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen\"},\"author\":{\"name\":\"Sabine\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\"},\"headline\":\"Bl\u00e4tter von Kohlrabi, M\u00f6hren &#038; Co.: zu schade zum Wegwerfen\",\"datePublished\":\"2022-07-22T09:00:34+00:00\",\"dateModified\":\"2023-08-09T04:37:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen\"},\"wordCount\":1152,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg\",\"articleSection\":[\"Gem\u00fcse\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen\",\"name\":\"Bl\u00e4tter von Kohlrabi, M\u00f6hren & Co.: zu schade zum Wegwerfen - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg\",\"datePublished\":\"2022-07-22T09:00:34+00:00\",\"dateModified\":\"2023-08-09T04:37:34+00:00\",\"description\":\"Viel zu oft werfen wir Gr\u00fcn und Schalen von Obst und Gem\u00fcse weg. Dabei lassen sich auch aus vielen Bl\u00e4ttern noch super tolle Gerichte zaubern. Versuchen Sie es mal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg\",\"width\":2560,\"height\":1703,\"caption\":\"Gem\u00fcsebl\u00e4tter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bl\u00e4tter von Kohlrabi, M\u00f6hren &#038; Co.: zu schade zum Wegwerfen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\",\"name\":\"Sabine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"caption\":\"Sabine\"},\"description\":\"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/sabine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bl\u00e4tter von Kohlrabi, M\u00f6hren & Co.: zu schade zum Wegwerfen - Samenhaus Gartenblog","description":"Viel zu oft werfen wir Gr\u00fcn und Schalen von Obst und Gem\u00fcse weg. Dabei lassen sich auch aus vielen Bl\u00e4ttern noch super tolle Gerichte zaubern. Versuchen Sie es mal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen","og_locale":"de_DE","og_type":"article","og_title":"Bl\u00e4tter von Kohlrabi, M\u00f6hren & Co.: zu schade zum Wegwerfen - Samenhaus Gartenblog","og_description":"Viel zu oft werfen wir Gr\u00fcn und Schalen von Obst und Gem\u00fcse weg. Dabei lassen sich auch aus vielen Bl\u00e4ttern noch super tolle Gerichte zaubern. Versuchen Sie es mal.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2022-07-22T09:00:34+00:00","article_modified_time":"2023-08-09T04:37:34+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg","type":"image\/jpeg"}],"author":"Sabine","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Sabine","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen"},"author":{"name":"Sabine","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5"},"headline":"Bl\u00e4tter von Kohlrabi, M\u00f6hren &#038; Co.: zu schade zum Wegwerfen","datePublished":"2022-07-22T09:00:34+00:00","dateModified":"2023-08-09T04:37:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen"},"wordCount":1152,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg","articleSection":["Gem\u00fcse"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen","url":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen","name":"Bl\u00e4tter von Kohlrabi, M\u00f6hren & Co.: zu schade zum Wegwerfen - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg","datePublished":"2022-07-22T09:00:34+00:00","dateModified":"2023-08-09T04:37:34+00:00","description":"Viel zu oft werfen wir Gr\u00fcn und Schalen von Obst und Gem\u00fcse weg. Dabei lassen sich auch aus vielen Bl\u00e4ttern noch super tolle Gerichte zaubern. Versuchen Sie es mal.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/06\/Blaetter-von-Kohlrabi-Moehren-Co._278384147-scaled.jpeg","width":2560,"height":1703,"caption":"Gem\u00fcsebl\u00e4tter"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/blaetter-von-kohlrabi-moehren-co-zu-schade-zum-wegwerfen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Bl\u00e4tter von Kohlrabi, M\u00f6hren &#038; Co.: zu schade zum Wegwerfen"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5","name":"Sabine","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","caption":"Sabine"},"description":"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/sabine"}]}},"wp-worthy-pixel":{"ignored":false,"public":"378b1c3e7c424c9fa53f8f6419e9c232","server":"vg04.met.vgwort.de","url":"https:\/\/vg04.met.vgwort.de\/na\/378b1c3e7c424c9fa53f8f6419e9c232"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/5283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=5283"}],"version-history":[{"count":5,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/5283\/revisions"}],"predecessor-version":[{"id":12783,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/5283\/revisions\/12783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/5495"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=5283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=5283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=5283"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=5283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}