{"id":865,"date":"2021-06-22T12:12:17","date_gmt":"2021-06-22T12:12:17","guid":{"rendered":"https:\/\/samenhaus1.timmeserver.de\/?p=865"},"modified":"2023-06-26T09:37:57","modified_gmt":"2023-06-26T09:37:57","slug":"die-banane-als-zimmerpflanze","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze","title":{"rendered":"Die Banane als Zimmerpflanze"},"content":{"rendered":"<p>Mit einer Bananenpflanze holen Sie sich tropisches Flair ins Haus. Als Zimmerpflanzen sind Zwergbananen geeignet, denen Sie im Sommer einen Aufenthalt im Freien bieten k\u00f6nnen. Mit Bananensamen haben Sie die M\u00f6glichkeit, Ihre eigenen Bananen zu ziehen und deren Wachstum von Anfang an zu beobachten.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Standort_und_Pflege_von_Bananen_als_Zimmerpflanzen\"><\/span>Standort und Pflege von Bananen als Zimmerpflanzen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3849 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/04\/Zimmerpflanze-Banane_420397586-295x300.jpeg\" alt=\"Bananenpflanze\" width=\"295\" height=\"300\" \/>Der botanische Name der Bananen lautet <i>Musa<\/i>. Fr\u00fcher wurden sie als Paradiesfeigen bezeichnet. Sie geh\u00f6ren zur Familie der Bananengew\u00e4chse. Die rund 70 Arten sind in den tropischen und subtropischen Gebieten Asiens und im westlichen Pazifikraum beheimatet. Bananenpflanzen sind krautig wachsende, ausdauernde und immergr\u00fcne Pflanzen. Sie verf\u00fcgen \u00fcber ein Rhizom, aus dem Ausl\u00e4ufer treiben. Bis zur Bl\u00fctezeit bleibt die Sprossachse kurz. Der Stamm besteht aus Blattscheiden und Blattstielen. Er ist eigentlich ein nicht verholzender Scheinstamm, in dessen Mitte sich ein echter Stamm befindet.<\/p>\n<p>Die Bananenpflanze kann je nach Sorte auch als Zimmerpflanze Fr\u00fcchte bilden. Die Bananen reifen ohne Best\u00e4ubung, wobei es einige Jahre dauert, bis die Staude tr\u00e4gt. Dazu m\u00fcssen optimale Pflege- und Standortbedingungen vorherrschen. Was Sie ebenfalls bedenken m\u00fcssen: Nachdem die Pflanze Fr\u00fcchte entwickelt hat, stirbt sie ab.<\/p>\n<p>Bananenpflanzen werden als Zimmerpflanzen zunehmend beliebter. Sie sind recht pflegeleicht, ben\u00f6tigen jedoch einen gewissen Platz. Die tropischen Stauden werden selbst als Zimmerpflanze recht auslandend und gro\u00df. Mit dem passenden Standort und der richtigen Pflege wird die Banane viele Jahre alt. Wichtig ist, dass die Pflanze keine Zugluft abbekommt. Sie ben\u00f6tigt einen hellen Platz, am besten neben einem S\u00fcdfenster. Ein Platz am West- oder Ostfenster ist ebenfalls m\u00f6glich. Die Luftfeuchte im Raum sollte sich auf mindestens 50 Prozent belaufen. Stellen Sie einen Luftbefeuchter nahe der Bananenpflanze auf oder bespr\u00fchen Sie die Staude t\u00e4glich mit Wasser.<\/p>\n<p align=\"center\"><b>Die Bananenpflanze ben\u00f6tigt Licht. Im Winter ist es in einem Raum nicht hell genug f\u00fcr sie. Richten Sie eine Pflanzlampe auf die Staude, sodass sie gen\u00fcgend Licht erh\u00e4lt.<\/b><\/p>\n<p>Die Musa hat keine besonderen Anspr\u00fcche an den Boden. Er muss lediglich wasserdurchl\u00e4ssig sein, denn mit Staun\u00e4sse kommt sie nicht zurecht. Sie k\u00f6nnen normale Erde f\u00fcr K\u00fcbelpflanzen verwenden und \u00fcber dem Abflussloch des Topfes eine Drainage aus Bl\u00e4hton oder Tonscherben legen. Das Gie\u00dfen bedarf etwas Fingerspitzengef\u00fchl, das Sie im Laufe der Zeit entwickeln.<\/p>\n<p><a name=\"_GoBack\"><\/a> Die Banane darf weder zu wenig noch zu viel Wasser bekommen. Gie\u00dfen Sie mit kalkfreiem Wasser oder alternativ mit gefiltertem Leitungswasser. Machen Sie den Fingertest: Sp\u00fcren Sie, dass die Erde noch feucht ist, gie\u00dfen Sie zu einem sp\u00e4teren Zeitpunkt. Als Faustformel gilt: Die Musa ben\u00f6tigt umso mehr Wasser, je gr\u00f6\u00dfer ihre Bl\u00e4tter sind. Zeigen sich trockene Blattr\u00e4nder, deutet das auf einen Wassermangel hin.<\/p>\n<p><strong>Tipp:<\/strong> Besorgen Sie sich einen Feuchtigkeitsmesser. Mit dieser Hilfe f\u00e4llt es leichter, die richtige Dosierung des Gie\u00dfwassers und den geeigneten Gie\u00dfzeitpunkt herauszufinden.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Duenge_und_Schnitt_einer_Bananenpflanze\"><\/span>D\u00fcnge und Schnitt einer Bananenpflanze<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sie m\u00fcssen eine Musa als Zimmerpflanze ganzj\u00e4hrig mit N\u00e4hrstoffen versorgen. Von Fr\u00fchling bis Herbst geben Sie ihr jede Woche eine Gabe, w\u00e4hrend Sie im Winter nur noch einmal im Monat d\u00fcngen m\u00fcssen. Nutzen Sie einen Fl\u00fcssigd\u00fcnger f\u00fcr Bananenstauden.<\/p>\n<p>Die Bananenpflanze ben\u00f6tigt keinen Schnitt. Sollte sie jedoch zu gro\u00df werden, k\u00f6nnen Sie einzelne Bl\u00e4tter entfernen. Sollte die Staude bei Ihnen ihre Winterruhe in einem dunklen, k\u00fchlen Raum verbringen, m\u00fcssen Sie sie bis zur Basis zur\u00fcckschneiden. Im n\u00e4chsten Fr\u00fchling treibt sie neue Bl\u00e4tter aus. Ansonsten entfernen Sie Bl\u00e4tter mit braunen Stellen und gelbe Bl\u00e4tter. Schneiden Sie die Bl\u00e4tter mit einem Messer an der Basis ab. Das Messer muss scharf sein. Desinfizieren Sie es mit reinem Alkohol, den Sie in der Apotheke bekommen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Die_Winterruhe_der_Bananenpflanzen\"><\/span>Die Winterruhe der Bananenpflanzen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3847 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/04\/Zimmerpflanze-Banane_66671389-300x225.jpeg\" alt=\"Zimmerpflanze Banane\" width=\"300\" height=\"225\" \/>Obwohl die Bananenpflanze bei Ihnen als Zimmerpflanze lebt, ben\u00f6tigt sie ihre Winterruhe. Welche Ma\u00dfnahmen f\u00fcr die \u00dcberwinterung zu treffen sind, h\u00e4ngt von der Sorte ab. Alle Sorten sollten jedoch bei einer Temperatur von etwa 10 Grad Celsius und bei gen\u00fcgend Helligkeit und Licht \u00fcberwintern. Falls es in dem Raum zu dunkel ist, k\u00f6nnen Sie eine Pflanzlampe verwenden. Ideal f\u00fcr die Winterruhe ist ein unbeheizter Wintergarten oder ein Platz in einem hellen Treppenhaus. Je dunkler der \u00dcberwinterungsraum ist, desto k\u00fchler muss er sein. Die Temperatur darf jedoch \u00fcber l\u00e4ngere Zeit nicht unter 5 Grad Celsius fallen. Die Staude muss stets frostfrei stehen. Wie oben erw\u00e4hnt m\u00fcssen Sie die Pflanze zur\u00fcckschneiden, wenn sie an einem k\u00fchlen, dunklen Ort \u00fcberwintert.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Anzucht_von_Bananen\"><\/span>Anzucht von Bananen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sie k\u00f6nnen Ihre Bananenpflanzen ganz einfach selbst ziehen. Es dauert zwar l\u00e4nger, als w\u00fcrden Sie eine Pflanze im Laden kaufen. Daf\u00fcr kommen Sie in den Genuss, die Staude langsam heranwachsen zu sehen:<\/p>\n<ul>\n<li>Mischen Sie Torf mit Sand und f\u00fcllen Sie das Substrat in einen Topf.<\/li>\n<li>Stecken Sie die Samen leicht in die Erde.<\/li>\n<li>Halten Sie die Erde feucht und decken Sie das Pflanzgef\u00e4\u00df mit einer transparenten Folie ab.<\/li>\n<li>Stellen Sie den Topf an einen warmen, hellen Platz. Die Umgebungstemperatur sollte \u00fcber 25 Grad Celsius liegen.<\/li>\n<li>Falls der Raum k\u00fchler ist, k\u00f6nnen Sie mit einer Heizlampe nachhelfen.<\/li>\n<li>Sobald sich die ersten Keimlinge zeigen, nehmen Sie die Folie ab.<\/li>\n<li>Sind die Jungpflanzen etwas gr\u00f6\u00dfer, pikieren Sie sie in einzelne T\u00f6pfe.<\/li>\n<li>Stellen Sie die Einzelt\u00f6pfe wieder an einen warmen und hellen Standort.<\/li>\n<li>Bespr\u00fchen Sie die Bl\u00e4tter der Jungpflanzen regelm\u00e4\u00dfig mit Wasser.<\/li>\n<\/ul>\n<p align=\"center\"><b>Sie sollten Jungpflanzen nicht der direkten Sonne aussetzen.<\/b><\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Verschiedene_Sorten_von_Bananen\"><\/span>Verschiedene Sorten von Bananen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3848 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/04\/Zimmerpflanze-Banane_310609219-300x195.jpeg\" alt=\"Banane Zimmerpflanze\" width=\"300\" height=\"195\" \/>Bei der Sortenauswahl sollten Sie zu Zwergbananen greifen. Sie sind aufgrund der Gr\u00f6\u00dfe als Zimmerpflanzen geeignet. Die <b>Zwergbanane <\/b><b>Musa ensete<\/b> (<em>Ensete ventricosum<\/em>) ist mehrj\u00e4hrig und wird zwischen 100 und 150 Zentimeter hoch. Sie k\u00f6nnen die Zwergbanane ganzj\u00e4hrig unter Glas auss\u00e4en. Die Keimdauer betr\u00e4gt drei Monate.<\/p>\n<p>Die <b>Kenia-Banane<\/b> (<em>Musa velutina<\/em>) ist als Zwergbanane mit einer maximalen Wuchsh\u00f6he von zwei Metern gut im Haus zu halten. Sie bl\u00fcht ab dem dritten Jahr und bildet essbare, s\u00fc\u00dfe, rote Bananen aus. Die Aussaat ist das ganze Jahr \u00fcber m\u00f6glich. Rauen Sie die Samen mittels Feile oder Sandpapier an und legen Sie sie f\u00fcr 12 Stunden in Wasser. Damit erh\u00f6hen Sie die Keimf\u00e4higkeit. Bei einer Umgebungstemperatur zwischen 25 und 30 Grad Celsius dauert es bis zur Keimung nur drei Wochen. In einer k\u00e4lteren Umgebung kann es bis zu zehn Wochen dauern, bis sich die Keimlinge zeigen.<\/p>\n<p>Der <b>Bananenbaum<\/b> ist mehrj\u00e4hrig und wird bis 200 Zentimeter hoch. Er kann zun\u00e4chst in allen Zimmern gehalten werden und muss sp\u00e4ter in einen Wintergarten oder in einen luftigen, gro\u00dfen Raum umziehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit einer Bananenpflanze holen Sie sich tropisches Flair ins Haus. Als Zimmerpflanzen sind Zwergbananen geeignet, denen Sie im Sommer einen Aufenthalt im Freien bieten k\u00f6nnen. Mit Bananensamen haben Sie die M\u00f6glichkeit, Ihre eigenen Bananen zu ziehen und deren Wachstum von Anfang an zu beobachten. Standort und Pflege von Bananen als Zimmerpflanzen Der botanische Name der Bananen lautet Musa. Fr\u00fcher wurden sie als Paradiesfeigen bezeichnet. Sie geh\u00f6ren zur Familie der Bananengew\u00e4chse. Die rund 70 Arten sind in den tropischen und subtropischen Gebieten Asiens und im westlichen Pazifikraum beheimatet. Bananenpflanzen sind krautig wachsende, ausdauernde und immergr\u00fcne Pflanzen. Sie verf\u00fcgen \u00fcber ein Rhizom, aus dem Ausl\u00e4ufer treiben. Bis zur Bl\u00fctezeit bleibt die Sprossachse kurz. Der Stamm besteht aus Blattscheiden und Blattstielen. Er ist eigentlich ein nicht verholzender Scheinstamm, in dessen Mitte sich ein echter Stamm befindet. Die Bananenpflanze kann je nach Sorte auch als Zimmerpflanze Fr\u00fcchte bilden. Die Bananen reifen ohne Best\u00e4ubung, wobei es einige Jahre dauert, bis die Staude tr\u00e4gt. Dazu m\u00fcssen optimale Pflege- und Standortbedingungen vorherrschen. Was Sie ebenfalls bedenken m\u00fcssen: Nachdem die Pflanze Fr\u00fcchte entwickelt hat, stirbt sie ab. Bananenpflanzen werden als Zimmerpflanzen zunehmend beliebter. Sie sind recht pflegeleicht, ben\u00f6tigen jedoch einen gewissen Platz. Die tropischen Stauden werden selbst als [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"hersteller":[],"class_list":["post-865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zimmerpflanzen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Banane als Zimmerpflanze - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Bananen als Zimmerpflanzen zaubern ein tropisches Flair. Mit ihren m\u00e4chtigen Bl\u00e4ttern wirkt die Banane gigantisch. Und mit etwas Gl\u00fcck k\u00f6nnen Sie irgendwann ernten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Banane als Zimmerpflanze - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Bananen als Zimmerpflanzen zaubern ein tropisches Flair. Mit ihren m\u00e4chtigen Bl\u00e4ttern wirkt die Banane gigantisch. Und mit etwas Gl\u00fcck k\u00f6nnen Sie irgendwann ernten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T12:12:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T09:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/05\/AdobeStock_302107693.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fritz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fritz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze\"},\"author\":{\"name\":\"Fritz\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/a0608c49bb909de7ed33e44abc853c6b\"},\"headline\":\"Die Banane als Zimmerpflanze\",\"datePublished\":\"2021-06-22T12:12:17+00:00\",\"dateModified\":\"2023-06-26T09:37:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze\"},\"wordCount\":1115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/AdobeStock_302107693.jpg\",\"articleSection\":[\"Zimmerpflanzen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze\",\"name\":\"Die Banane als Zimmerpflanze - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/AdobeStock_302107693.jpg\",\"datePublished\":\"2021-06-22T12:12:17+00:00\",\"dateModified\":\"2023-06-26T09:37:57+00:00\",\"description\":\"Bananen als Zimmerpflanzen zaubern ein tropisches Flair. Mit ihren m\u00e4chtigen Bl\u00e4ttern wirkt die Banane gigantisch. Und mit etwas Gl\u00fcck k\u00f6nnen Sie irgendwann ernten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/AdobeStock_302107693.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/AdobeStock_302107693.jpg\",\"width\":1000,\"height\":563,\"caption\":\"Bananen Stauden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/die-banane-als-zimmerpflanze#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Banane als Zimmerpflanze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/a0608c49bb909de7ed33e44abc853c6b\",\"name\":\"Fritz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Tobi-1-150x150.jpg\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Tobi-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Tobi-1-150x150.jpg\",\"caption\":\"Fritz\"},\"description\":\"Das ist Fritz. Er steht f\u00fcr all die erfahrenen G\u00e4rtner und Selbstversorger, die ihr Wissen und ihre Erfahrungen auf dem Gartenblog mit Ihnen teilen. Mit Tipps und Tricks f\u00fcr den Garten, den Balkon und die K\u00fcche steht Fritz Ihnen zur Seite.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/tobias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Banane als Zimmerpflanze - Samenhaus Gartenblog","description":"Bananen als Zimmerpflanzen zaubern ein tropisches Flair. Mit ihren m\u00e4chtigen Bl\u00e4ttern wirkt die Banane gigantisch. Und mit etwas Gl\u00fcck k\u00f6nnen Sie irgendwann ernten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze","og_locale":"de_DE","og_type":"article","og_title":"Die Banane als Zimmerpflanze - Samenhaus Gartenblog","og_description":"Bananen als Zimmerpflanzen zaubern ein tropisches Flair. Mit ihren m\u00e4chtigen Bl\u00e4ttern wirkt die Banane gigantisch. Und mit etwas Gl\u00fcck k\u00f6nnen Sie irgendwann ernten.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2021-06-22T12:12:17+00:00","article_modified_time":"2023-06-26T09:37:57+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/05\/AdobeStock_302107693.jpg","type":"image\/jpeg"}],"author":"Fritz","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Fritz","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze"},"author":{"name":"Fritz","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/a0608c49bb909de7ed33e44abc853c6b"},"headline":"Die Banane als Zimmerpflanze","datePublished":"2021-06-22T12:12:17+00:00","dateModified":"2023-06-26T09:37:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze"},"wordCount":1115,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/05\/AdobeStock_302107693.jpg","articleSection":["Zimmerpflanzen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze","url":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze","name":"Die Banane als Zimmerpflanze - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/05\/AdobeStock_302107693.jpg","datePublished":"2021-06-22T12:12:17+00:00","dateModified":"2023-06-26T09:37:57+00:00","description":"Bananen als Zimmerpflanzen zaubern ein tropisches Flair. Mit ihren m\u00e4chtigen Bl\u00e4ttern wirkt die Banane gigantisch. Und mit etwas Gl\u00fcck k\u00f6nnen Sie irgendwann ernten.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/05\/AdobeStock_302107693.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/05\/AdobeStock_302107693.jpg","width":1000,"height":563,"caption":"Bananen Stauden"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/die-banane-als-zimmerpflanze#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Die Banane als Zimmerpflanze"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/a0608c49bb909de7ed33e44abc853c6b","name":"Fritz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/11\/Tobi-1-150x150.jpg","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/11\/Tobi-1-150x150.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2024\/11\/Tobi-1-150x150.jpg","caption":"Fritz"},"description":"Das ist Fritz. Er steht f\u00fcr all die erfahrenen G\u00e4rtner und Selbstversorger, die ihr Wissen und ihre Erfahrungen auf dem Gartenblog mit Ihnen teilen. Mit Tipps und Tricks f\u00fcr den Garten, den Balkon und die K\u00fcche steht Fritz Ihnen zur Seite.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/tobias"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=865"}],"version-history":[{"count":7,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/865\/revisions"}],"predecessor-version":[{"id":11930,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/865\/revisions\/11930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/890"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=865"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}