{"id":902,"date":"2021-08-27T11:58:38","date_gmt":"2021-08-27T11:58:38","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=902"},"modified":"2023-06-26T11:27:00","modified_gmt":"2023-06-26T11:27:00","slug":"gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen","title":{"rendered":"Gew\u00e4chshaus Anbau: Vorkultur und Platz f\u00fcr empfindliche Pflanzen"},"content":{"rendered":"<p>W\u00e4hrend der Rest Ihres Gartens noch im Winterschlaf ruht und andere Gartenbesitzer darauf warten, endlich in die neue Saison starten zu k\u00f6nnen, werden Sie im Gew\u00e4chshaus bereits aktiv. Sie ziehen Pflanzen vor, um sie zeitig auszupflanzen, und sch\u00fctzen empfindliche Pflanzen vor Witterungseinfl\u00fcssen. Noch mehr M\u00f6glichkeiten ergeben sich in einem beheizten Gew\u00e4chshaus.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Gewaechshaustypen_Das_sind_die_Unterschiede_und_Besonderheiten\"><\/span>Gew\u00e4chshaustypen: Das sind die Unterschiede und Besonderheiten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4800 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_272126953-300x200.jpeg\" alt=\"Gew\u00e4chshaus\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_272126953-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_272126953-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_272126953-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_272126953-768x513.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_272126953-1536x1025.jpeg 1536w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_272126953-2048x1367.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>M\u00f6chten Sie in Ihrem Garten ein Gew\u00e4chshaus bauen, kommt es auf den richtigen Standort an. Wie gro\u00df Sie das Gew\u00e4chshaus bauen, h\u00e4ngt vom vorhandenen Platz und von Ihren pers\u00f6nlichen Bed\u00fcrfnissen ab. \u00dcberlegen Sie, welche Pflanzen Sie anbauen m\u00f6chten, bevor Sie sich f\u00fcr das passende Gew\u00e4chshaus entscheiden:<\/p>\n<ul>\n<li><strong>Foliengew\u00e4chshaus:<\/strong> Das Foliengew\u00e4chshaus ist die einfachste Form des Gew\u00e4chshauses. Es ist preiswert, l\u00e4sst sich schnell zusammenbauen, doch ist es auch empfindlich gegen Besch\u00e4digungen und Witterungseinfl\u00fcsse. Kleine Foliengew\u00e4chsh\u00e4user eignen sich f\u00fcr Tomaten. Das Foliengew\u00e4chshaus ist immer ein Kaltgew\u00e4chshaus, da es nicht beheizt werden kann.<\/li>\n<li><strong>Gew\u00e4chshaus aus Kunststoff:<\/strong> F\u00fcr Gew\u00e4chsh\u00e4user unterschiedlicher Gr\u00f6\u00dfe ist Kunststoff das g\u00e4ngige Material. Meistens handelt es sich um Stegdoppelplatten, die \u00fcber isolierte Hohlr\u00e4ume verf\u00fcgen. Solche Gew\u00e4chsh\u00e4user aus Polycarbonat oder Plexiglas zeichnen sich durch eine gute W\u00e4rmed\u00e4mmung aus und k\u00f6nnen zus\u00e4tzlich mit einer Heizung ausgestattet werden.<\/li>\n<li><strong>Gew\u00e4chshaus aus Glas:<\/strong> Aus Glas werden vorrangig gro\u00dfe Gew\u00e4chsh\u00e4user gefertigt, die sich durch eine lange Lebensdauer auszeichnen. Diese Gew\u00e4chsh\u00e4user k\u00f6nnen mit einer Heizung ausgestattet werden. Bei Gew\u00e4chsh\u00e4usern aus Fensterglas besteht aufgrund der durchsichtigen Scheiben die Gefahr von Verbrennungen der Pflanzen. Scheiben aus gen\u00f6rpeltem Glas erm\u00f6glichen eine diffuse Streuung des Lichts.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Gewaechshausheizung_nicht_immer_erforderlich\"><\/span>Gew\u00e4chshausheizung: nicht immer erforderlich<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ein unbeheiztes Gew\u00e4chshaus, das sogenannte Kalt-Gew\u00e4chshaus, wird f\u00fcr die Nord-S\u00fcd-Ausrichtung empfohlen, w\u00e4hrend f\u00fcr die West-Ost-Ausrichtung ein Warmgew\u00e4chshaus geeignet ist. Nicht immer ist f\u00fcr ein Warmgew\u00e4chshaus tats\u00e4chlich eine Gew\u00e4chshausheizung erforderlich. Abh\u00e4ngig vom Material und vom Standort eignet sich eine passive Solarheizung. Thermisch getrennte Profile oder W\u00e4rmeschutzglas sorgen f\u00fcr eine gute W\u00e4rmed\u00e4mmung. Mit ausreichender Sonneneinstrahlung herrschen auch im Winter bereits hohe Temperaturen.<\/p>\n<p>F\u00fcr die Gew\u00e4chshausheizung gibt es verschiedene M\u00f6glichkeiten, die Sie abh\u00e4ngig von der Gr\u00f6\u00dfe Ihres Gew\u00e4chshauses w\u00e4hlen:<\/p>\n<ul>\n<li>Frostw\u00e4chter, um das Gew\u00e4chshaus lediglich frostfrei zu halten<\/li>\n<li>Infrarotstrahler f\u00fcr kleinere Gew\u00e4chsh\u00e4user<\/li>\n<li>Elektroheizung mit und ohne Gebl\u00e4se mit unterschiedlicher Heizleistung<\/li>\n<li>Gas-Gew\u00e4chshausheizung f\u00fcr gr\u00f6\u00dfere Gew\u00e4chsh\u00e4user<\/li>\n<li>Petroleum-Gew\u00e4chshausheizung f\u00fcr kleinere Gew\u00e4chsh\u00e4user<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Ueberhitzung_vermeiden_auf_gute_Belueftung_achten\"><\/span>\u00dcberhitzung vermeiden: auf gute Bel\u00fcftung achten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4801 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_395943521-300x200.jpeg\" alt=\"Gew\u00e4chshaus bel\u00fcftung\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_395943521-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_395943521-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_395943521-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_395943521-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_395943521-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_395943521-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Das Wachstum der Pflanzen wird im Gew\u00e4chshaus beschleunigt, da Sonnenenergie in W\u00e4rme umgewandelt wird. An sonnenreichen Tagen kann es schnell zu einer \u00dcberhitzung oder einem Hitzestau kommen, was schlimmstenfalls das Ende Ihrer Pflanzen bedeutet. Es gibt mehrere M\u00f6glichkeiten, eine \u00dcberhitzung zu vermeiden:<\/p>\n<ul>\n<li>Schattiernetz, um die Sonneneinstrahlung zu reduzieren, haupts\u00e4chlich bei kleineren Gew\u00e4chsh\u00e4usern geeignet<\/li>\n<li>automatischer Fenster\u00f6ffner, der mit einem speziellen Wachs oder \u00d6l funktioniert und das Fenster bei Bedarf anhebt<\/li>\n<li>Bel\u00fcftung durch T\u00fcr und manuell zu \u00f6ffnende Dachfenster<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Kaltgewaechshaus_frueher_Start_in_die_Saison_und_Schutz_fuer_empfindliche_Pflanzen\"><\/span>Kaltgew\u00e4chshaus: fr\u00fcher Start in die Saison und Schutz f\u00fcr empfindliche Pflanzen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ihr Gew\u00e4chshaus muss nicht immer beheizt sein, um fr\u00fchzeitig in die Gartensaison zu starten, empfindliche Pflanzen zu sch\u00fctzen oder die Kulturzeit zu verl\u00e4ngern. Ein frostfreies Kaltgew\u00e4chshaus eignet sich f\u00fcr die fr\u00fche Aussaat von Salat, Kresse, Radieschen oder Sommerblumen wie Begonien oder Tagetes.<\/p>\n<p>Mit einfachen Mitteln halten Sie das Gew\u00e4chshaus frostfrei. Geeignet ist ein Frostw\u00e4chter, f\u00fcr den jedoch eine Steckdose erforderlich ist. Er h\u00e4lt die Temperatur lediglich \u00fcber dem Gefrierpunkt. Ein Schmelzfeuer mit Wachs brennt mehrere Stunden und h\u00e4lt kleinere Gew\u00e4chsh\u00e4user frostfrei. Eine Noppenfolie an den Scheiben sorgt f\u00fcr eine gute Isolierung und l\u00e4sst trotzdem gen\u00fcgend Licht hinein.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Kaltgewaechshaus_optimale_Nutzung_mit_der_Folge_der_Kulturen\"><\/span>Kaltgew\u00e4chshaus: optimale Nutzung mit der Folge der Kulturen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4799 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_230338500-300x200.jpeg\" alt=\"Gew\u00e4chshaus Pflanzen\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_230338500-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_230338500-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_230338500-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_230338500-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_230338500-1536x1024.jpeg 1536w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_230338500-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Ihr Kaltgew\u00e4chshaus nutzen Sie optimal aus, indem Sie Fr\u00fchjahrs-, Sommer- und Herbstkulturen darin anbauen.<\/p>\n<p>Die richtige Zeit f\u00fcr Fr\u00fchjahrskulturen ist im ungeheizten Gew\u00e4chshaus ab Ende Februar oder Anfang M\u00e4rz. Bei tieferen Nachttemperaturen sch\u00fctzen Sie Ihre frostempfindlichen Pflanzen mit einer Lage Vlies. Ist das Gew\u00e4chshaus frostfrei, k\u00f6nnen Sie bereits zwei Wochen vorher mit der Fr\u00fchjahrskultur starten. Als Fr\u00fchjahrskultur eignen sich<\/p>\n<ul>\n<li>Radieschen,<\/li>\n<li>Rettich,<\/li>\n<li>Salat und<\/li>\n<li>Kohlrabi.<\/li>\n<\/ul>\n<p>Sommerkulturen pflanzen Sie von Ende April bis Ende Mai ins Gew\u00e4chshaus, etwa<\/p>\n<ul>\n<li>Gurken,<\/li>\n<li>Paprika,<\/li>\n<li>Auberginen,<\/li>\n<li>Tomaten oder<\/li>\n<li>Bohnen.<\/li>\n<\/ul>\n<p>Pflanzen, die viel W\u00e4rme brauchen und denen es im Garten oft zu kalt ist, eignen sich ebenso wie empfindliche Pflanzen, die vor Regen gesch\u00fctzt werden m\u00fcssen.<\/p>\n<p>Ist die Sommerkultur abgeerntet, wird es Zeit f\u00fcr die Herbstkultur. Daf\u00fcr eignen sich<\/p>\n<ul>\n<li>Spinat,<\/li>\n<li>Feldsalat,<\/li>\n<li>Endiviensalat und<\/li>\n<li>Radieschen.<\/li>\n<\/ul>\n<p>\u00dcber den Winter k\u00f6nnen Feldsalat und Spinat im Gew\u00e4chshaus bleiben. An frostfreien Tagen ernten Sie.<\/p>\n<p>Das gesamte Jahr \u00fcber bietet ein Kaltgew\u00e4chshaus optimalen Schutz vor Frost und Sch\u00e4dlingen, wenn Sie darin Kr\u00e4uter wie Rosmarin, Petersilie, Schnittlauch oder Thymian anbauen. Bei nicht winterharten Kr\u00e4utern verl\u00e4ngern Sie die Erntedauer.<\/p>\n<p><strong>Tipp:<\/strong> Das Kaltgew\u00e4chshaus eignet sich auch, um Bohnen, Erbsen, Kohlpflanzen und verschiedene Zierpflanzen bereits ab Ende Februar vorzukultivieren. Die Pflanzen k\u00f6nnen dann fr\u00fcher ins Freiland.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Anbau_im_Warmgewaechshaus_noch_mehr_Moeglichkeiten_fuer_die_Nutzung\"><\/span>Anbau im Warmgew\u00e4chshaus: noch mehr M\u00f6glichkeiten f\u00fcr die Nutzung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>In einem beheizten Warmgew\u00e4chshaus herrschen im Winter Temperaturen von mehr als 12 Grad. Liegt die Temperatur im Winter schon \u00fcber 18 Grad, handelt es sich um ein Tropengew\u00e4chshaus. Mit der geeigneten Heizung bekommen Sie Ihr Gew\u00e4chshaus warm. Auch im Winter ziehen Sie im Warmgew\u00e4chshaus empfindliche Pflanzen oder kultivieren Pflanzen mit einer hohen Keimtemperatur vor. Ein Tropengew\u00e4chshaus eignet sich f\u00fcr exotische Pflanzen, die viel W\u00e4rme brauchen.<\/p>\n<p>Tomaten, Paprika und Auberginen lassen sich bei der entsprechenden Beleuchtung schon im Januar im Warmgew\u00e4chshaus vorkultivieren. Das Warmgew\u00e4chshaus eignet sich auch, um K\u00fcbelpflanzen wie Engelstrompete, Zitronenb\u00e4umchen, Oleander und andere empfindliche Pflanzen zu \u00fcberwintern.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Anzucht_von_Jungpflanzen_im_Gewaechshaus_die_richtige_Keimtemperatur\"><\/span>Anzucht von Jungpflanzen im Gew\u00e4chshaus: die richtige Keimtemperatur<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4798 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2022\/05\/Gewaechshaus-Anbau_21744116-300x199.jpeg\" alt=\"Gew\u00e4chshaus jungpflanzen\" width=\"300\" height=\"199\" \/>Ein Warmgew\u00e4chshaus eignet sich hervorragend f\u00fcr die Anzucht von Jungpflanzen. Bei Bohnen, Erbsen, Tomaten, Gurken und Paprika liegt die Keimtemperatur bei ungef\u00e4hr 20 Grad. Kopfsalat ben\u00f6tigt eine Keimtemperatur von 15 bis 18 Grad. Die Pflanzen keimen bei der entsprechenden Temperatur im Warmgew\u00e4chshaus schneller und sind fr\u00fcher erntereif.<\/p>\n<p>Zeigen sich nach den Keimbl\u00e4ttern die ersten Blattpaare der Jungpflanzen, pikieren Sie die S\u00e4mlinge, indem Sie sie vereinzeln, die Wurzel k\u00fcrzen und in kleine T\u00f6pfchen oder andere geeignete Gef\u00e4\u00dfe pflanzen. Achten Sie darauf, dass die Jungpflanzen gen\u00fcgend Licht bekommen.<\/p>\n<p>F\u00fcr die Aussaat kommt es auf den richtigen Zeitpunkt an:<\/p>\n<ul>\n<li>Paprika: Mitte Februar<\/li>\n<li>Tomaten: sp\u00e4testens Mitte M\u00e4rz<\/li>\n<li>Gurken: Anfang April, wenn sie Mitte Mai ins Freiland kommen.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Bewaesserung_im_Gewaechshaus_Troepfchenbewaesserung_schont_die_Pflanzen\"><\/span>Bew\u00e4sserung im Gew\u00e4chshaus: Tr\u00f6pfchenbew\u00e4sserung schont die Pflanzen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Bei empfindlichen Pflanzen wie Tomaten m\u00fcssen Sie darauf achten, dass die Bl\u00e4tter nicht nass werden. Schnell kann es zu Pilzerkrankungen oder Braunf\u00e4ule kommen. Mit einer Tr\u00f6pfchenbew\u00e4sserung werden die Pflanzen direkt an den Wurzeln mit Wasser versorgt, w\u00e4hrend die Bl\u00e4tter trocken bleiben. Eine optimale Wasserversorgung ist gew\u00e4hrleistet, da nur wenig Wasser verdunsten kann. In Gartenm\u00e4rkten oder Onlineshops bekommen Sie eine automatische Tr\u00f6pfchenbew\u00e4sserung, bei der Sie die Wasserabgabe abh\u00e4ngig vom Bedarf der Pflanzen einstellen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend der Rest Ihres Gartens noch im Winterschlaf ruht und andere Gartenbesitzer darauf warten, endlich in die neue Saison starten zu k\u00f6nnen, werden Sie im Gew\u00e4chshaus bereits aktiv. Sie ziehen Pflanzen vor, um sie zeitig auszupflanzen, und sch\u00fctzen empfindliche Pflanzen vor Witterungseinfl\u00fcssen. Noch mehr M\u00f6glichkeiten ergeben sich in einem beheizten Gew\u00e4chshaus. Gew\u00e4chshaustypen: Das sind die Unterschiede und Besonderheiten M\u00f6chten Sie in Ihrem Garten ein Gew\u00e4chshaus bauen, kommt es auf den richtigen Standort an. Wie gro\u00df Sie das Gew\u00e4chshaus bauen, h\u00e4ngt vom vorhandenen Platz und von Ihren pers\u00f6nlichen Bed\u00fcrfnissen ab. \u00dcberlegen Sie, welche Pflanzen Sie anbauen m\u00f6chten, bevor Sie sich f\u00fcr das passende Gew\u00e4chshaus entscheiden: Foliengew\u00e4chshaus: Das Foliengew\u00e4chshaus ist die einfachste Form des Gew\u00e4chshauses. Es ist preiswert, l\u00e4sst sich schnell zusammenbauen, doch ist es auch empfindlich gegen Besch\u00e4digungen und Witterungseinfl\u00fcsse. Kleine Foliengew\u00e4chsh\u00e4user eignen sich f\u00fcr Tomaten. Das Foliengew\u00e4chshaus ist immer ein Kaltgew\u00e4chshaus, da es nicht beheizt werden kann. Gew\u00e4chshaus aus Kunststoff: F\u00fcr Gew\u00e4chsh\u00e4user unterschiedlicher Gr\u00f6\u00dfe ist Kunststoff das g\u00e4ngige Material. Meistens handelt es sich um Stegdoppelplatten, die \u00fcber isolierte Hohlr\u00e4ume verf\u00fcgen. Solche Gew\u00e4chsh\u00e4user aus Polycarbonat oder Plexiglas zeichnen sich durch eine gute W\u00e4rmed\u00e4mmung aus und k\u00f6nnen zus\u00e4tzlich mit einer Heizung ausgestattet werden. Gew\u00e4chshaus aus Glas: Aus Glas werden vorrangig gro\u00dfe Gew\u00e4chsh\u00e4user [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":1113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"hersteller":[],"class_list":["post-902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selbstversorger-garten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anbau im Gew\u00e4chshaus: Vorkultur und lange Ernte - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Das Gew\u00e4chshaus bietet Ihnen viel Platz f\u00fcr die Anzucht von Pflanzen aber auch f\u00fcr den Anbau von empfindlichen Gem\u00fcsesorten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anbau im Gew\u00e4chshaus: Vorkultur und lange Ernte - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Das Gew\u00e4chshaus bietet Ihnen viel Platz f\u00fcr die Anzucht von Pflanzen aber auch f\u00fcr den Anbau von empfindlichen Gem\u00fcsesorten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-27T11:58:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:27:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/06\/AdobeStock_182810433.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen\"},\"author\":{\"name\":\"Sabine\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\"},\"headline\":\"Gew\u00e4chshaus Anbau: Vorkultur und Platz f\u00fcr empfindliche Pflanzen\",\"datePublished\":\"2021-08-27T11:58:38+00:00\",\"dateModified\":\"2023-06-26T11:27:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen\"},\"wordCount\":1254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AdobeStock_182810433.jpg\",\"articleSection\":[\"Selbstversorger-Garten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen\",\"name\":\"Anbau im Gew\u00e4chshaus: Vorkultur und lange Ernte - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AdobeStock_182810433.jpg\",\"datePublished\":\"2021-08-27T11:58:38+00:00\",\"dateModified\":\"2023-06-26T11:27:00+00:00\",\"description\":\"Das Gew\u00e4chshaus bietet Ihnen viel Platz f\u00fcr die Anzucht von Pflanzen aber auch f\u00fcr den Anbau von empfindlichen Gem\u00fcsesorten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AdobeStock_182810433.jpg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AdobeStock_182810433.jpg\",\"width\":1000,\"height\":563,\"caption\":\"Gew\u00e4chshaus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gew\u00e4chshaus Anbau: Vorkultur und Platz f\u00fcr empfindliche Pflanzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\",\"name\":\"Sabine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"caption\":\"Sabine\"},\"description\":\"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/sabine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anbau im Gew\u00e4chshaus: Vorkultur und lange Ernte - Samenhaus Gartenblog","description":"Das Gew\u00e4chshaus bietet Ihnen viel Platz f\u00fcr die Anzucht von Pflanzen aber auch f\u00fcr den Anbau von empfindlichen Gem\u00fcsesorten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen","og_locale":"de_DE","og_type":"article","og_title":"Anbau im Gew\u00e4chshaus: Vorkultur und lange Ernte - Samenhaus Gartenblog","og_description":"Das Gew\u00e4chshaus bietet Ihnen viel Platz f\u00fcr die Anzucht von Pflanzen aber auch f\u00fcr den Anbau von empfindlichen Gem\u00fcsesorten.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2021-08-27T11:58:38+00:00","article_modified_time":"2023-06-26T11:27:00+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/06\/AdobeStock_182810433.jpg","type":"image\/jpeg"}],"author":"Sabine","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Sabine","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen"},"author":{"name":"Sabine","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5"},"headline":"Gew\u00e4chshaus Anbau: Vorkultur und Platz f\u00fcr empfindliche Pflanzen","datePublished":"2021-08-27T11:58:38+00:00","dateModified":"2023-06-26T11:27:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen"},"wordCount":1254,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/06\/AdobeStock_182810433.jpg","articleSection":["Selbstversorger-Garten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen","url":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen","name":"Anbau im Gew\u00e4chshaus: Vorkultur und lange Ernte - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/06\/AdobeStock_182810433.jpg","datePublished":"2021-08-27T11:58:38+00:00","dateModified":"2023-06-26T11:27:00+00:00","description":"Das Gew\u00e4chshaus bietet Ihnen viel Platz f\u00fcr die Anzucht von Pflanzen aber auch f\u00fcr den Anbau von empfindlichen Gem\u00fcsesorten.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/06\/AdobeStock_182810433.jpg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2021\/06\/AdobeStock_182810433.jpg","width":1000,"height":563,"caption":"Gew\u00e4chshaus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/gewaechshaus-anbau-vorkultur-und-platz-fuer-empfindliche-pflanzen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Gew\u00e4chshaus Anbau: Vorkultur und Platz f\u00fcr empfindliche Pflanzen"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5","name":"Sabine","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","caption":"Sabine"},"description":"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/sabine"}]}},"wp-worthy-pixel":{"ignored":false,"public":"329feff482994dd7a91f3f490eba396e","server":"vg05.met.vgwort.de","url":"https:\/\/vg05.met.vgwort.de\/na\/329feff482994dd7a91f3f490eba396e"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=902"}],"version-history":[{"count":6,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/902\/revisions"}],"predecessor-version":[{"id":11948,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/902\/revisions\/11948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/1113"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=902"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}