{"id":9314,"date":"2023-03-08T09:00:16","date_gmt":"2023-03-08T09:00:16","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=9314"},"modified":"2023-08-30T15:13:22","modified_gmt":"2023-08-30T15:13:22","slug":"buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick","title":{"rendered":"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick"},"content":{"rendered":"<p>Haben Sie Buchsbaum als Hecke oder Strauch in Ihrem Garten, kann Ihnen der Buchsbaumz\u00fcnsler das Leben schwer machen. Der unscheinbare Schmetterling kann schwere Sch\u00e4den anrichten und den Buchsbaum zum Absterben bringen. Es gibt aber einige M\u00f6glichkeiten, ihn wirksam zu bek\u00e4mpfen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Befall_mit_Buchsbaumzuensler_erkennen_auf_unteren_Bereich_der_Pflanzen_achten\"><\/span>Befall mit Buchsbaumz\u00fcnsler erkennen: auf unteren Bereich der Pflanzen achten<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10290 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_353099588-300x169.jpeg\" alt=\"Buchsbaumz\u00fcnslerbefall\" width=\"300\" height=\"169\" \/>Der Buchsbaumz\u00fcnsler ist erst seit einigen Jahren in deutschen G\u00e4rten verbreitet, wo er sich am Buchsbaum zu schaffen macht. Er wurde wahrscheinlich aus Ostasien auf Containerschiffen eingeschleppt. Im Fr\u00fchjahr paart sich der Buchsbaumz\u00fcnsler und legt im unteren Bereich der Wirtspflanze ungef\u00e4hr 150 Eier ab.<\/p>\n<p>Die Larven schl\u00fcpfen bei einer Temperatur von mehr als sieben Grad Celsius schon nach drei Tagen. Die Entwicklung zum fertigen Insekt verl\u00e4uft in sieben Stadien und vollzieht sich bei einer Umgebungstemperatur von mehr als 15 Grad Celsius innerhalb von zehn Wochen. Die Entwicklung von der Larve zur Raupe dauert bei 20 Grad Celsius ungef\u00e4hr drei Wochen.<\/p>\n<p>Sie sehen die Eier und die Larven zumeist nicht, doch sind die ungef\u00e4hr f\u00fcnf Zentimeter langen gr\u00fcnen Raupen leicht zu erkennen. Verpuppen sich die Raupen, schl\u00fcpfen ungef\u00e4hr eine Woche sp\u00e4ter die fertigen Falter. Da sie nur eine kurze Lebenserwartung haben, m\u00fcssen sie sich innerhalb kurzer Zeit vermehren. Von Fr\u00fchjahr bis Sp\u00e4tsommer kann der Buchsbaumz\u00fcnsler bei guten Bedingungen in vier Generationen auftreten. Am Ende einer Saison \u00fcberwintern die Raupen in Kokons aus Spinnf\u00e4den und Bl\u00e4ttern, um sich im Folgejahr zu Faltern zu entwickeln.<\/p>\n<h3 class=\"western\"><span class=\"ez-toc-section\" id=\"Schadbild_des_Buchsbaumzuenslers_Blattgerippe_und_vertrocknete_Triebe\"><\/span>Schadbild des Buchsbaumz\u00fcnslers: Blattgerippe und vertrocknete Triebe<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nachdem der Buchsbaumz\u00fcnsler seine Eier abgelegt hat, erkennen Sie von einem Befall noch nichts. Die Raupen fressen sich vom Inneren der Pflanze nach au\u00dfen und machen sich nicht nur an den Bl\u00e4ttern zu schaffen, sondern sie fressen auch die Rinde der jungen Triebe. Einen Befall erkennen Sie an den Raupen, am Blattgerippe und an absterbenden, trockenen Trieben. H\u00e4ufig wird ein Befall erst dann entdeckt, wenn er bereits weit fortgeschritten ist. Die befallenen Pflanzen sind dann oft nicht mehr zu retten. Achten Sie vor allem auf den unteren Bereich der Buchsbaumpflanzen, da dort die Raupen zuerst ihr Unwesen treiben. Sichere Anzeichen f\u00fcr einen Befall sind:<\/p>\n<ul>\n<li>abgefressene Bl\u00e4tter und Blattgerippe<\/li>\n<li>angefressene Triebe<\/li>\n<li>Fra\u00dfspuren an der Rinde<\/li>\n<li>Gespinste an den Pflanzen<\/li>\n<li>br\u00e4unlich verf\u00e4rbte Bl\u00e4tter<\/li>\n<li>Kotkr\u00fcmel als gr\u00fcnliche Ablagerungen an den Gespinsten<\/li>\n<\/ul>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Erste_Hilfe_leisten_Raupen_absammeln_und_Rueckschnitt\"><\/span>Erste Hilfe leisten: Raupen absammeln und R\u00fcckschnitt<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Um den Buchsbaumz\u00fcnsler wirksam zu bek\u00e4mpfen und Ihren Buchsbaum zu retten, gilt es, einen Befall fr\u00fchzeitig zu erkennen. Kontrollieren Sie Ihren Buchsbaum bereits im April, wenn die Raupen aktiv sind, auf einen Befall. Sammeln Sie die Raupen akribisch ab und tragen Sie dabei Handschuhe. Entsorgen Sie die Raupen im Restm\u00fcll, damit sie sich nicht mehr ausbreiten k\u00f6nnen. Legen Sie unter die Buchsbaumpflanzen ein helles Tuch, damit Sie auch herabgefallene Raupen finden und entsorgen k\u00f6nnen.<\/p>\n<p>Weitere Kontrollen nehmen Sie im Juli und im September vor, wenn die n\u00e4chsten Generationen auftreten. Ist der Buchsbaum kr\u00e4ftig genug, schneiden Sie ihn zur\u00fcck. Das Schnittgut verpacken Sie, um es im Hausm\u00fcll zu entsorgen, damit sich der Sch\u00e4dling nicht weiter ausbreitet. Mit einem Hochdruckreiniger k\u00f6nnen Sie auch Sch\u00e4dlinge im Inneren der Pflanze entfernen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Stark_befallene_Pflanzen_entsorgen_gut_verpackt_im_Hausmuell\"><\/span>Stark befallene Pflanzen entsorgen: gut verpackt im Hausm\u00fcll<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10288 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_145178288-300x200.jpeg\" alt=\"Buchsbaumz\u00fcnslerraupen\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_145178288-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_145178288-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_145178288-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_145178288-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_145178288-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_145178288-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Sind die Pflanzen stark betroffen, sterben sie ab. Sie k\u00f6nnen die betroffenen Pflanzen dann nur noch ausgraben und entsorgen, damit sich der Sch\u00e4dling nicht auf andere Pflanzen ausbreitet. Verpacken Sie die betroffenen Pflanzen gut und entsorgen Sie sie im Hausm\u00fcll. Sind die Buchsbaumpflanzen bereits gr\u00f6\u00dfer, wenden Sie sich an die Kompostierungsanlage in Ihrer N\u00e4he. Die Pflanzen werden nicht kompostiert, doch k\u00f6nnen Ihnen die Mitarbeiter der Kompostierungsanlage sagen, wo Sie die Pflanzen zur Entsorgung abgeben k\u00f6nnen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Tod_durch_Ersticken_abdecken_mit_dunkler_Folie\"><\/span>Tod durch Ersticken: abdecken mit dunkler Folie<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Larven des Buchsbaumz\u00fcnslers vertragen Hitze nicht gut und k\u00f6nnen mit einem einfachen Trick bek\u00e4mpft werden. Einzelpflanzen und kleinere Einfassungen mit Buchsbaum decken Sie an einem warmen, sonnigen Tag mit dunkler Folie ab. Die Temperaturen steigen unter der Folie schnell an und f\u00fchren zum Absterben der Larven und Raupen. Sorgen Sie daf\u00fcr, dass der Buchsbaum am Vortag gut gew\u00e4ssert wird. So macht ihm die Hitze nichts aus. Am Abend entfernen Sie die Folie wieder. Den Eiern des Sch\u00e4dlings macht die Hitze nichts aus. Wiederholen Sie daher den Vorgang nach zwei Wochen, um weitere Larven zu bek\u00e4mpfen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Buchsbaumzuensler_biologisch_bekaempfen_Bakterien_Neem-Oel_und_Pheromonfallen\"><\/span>Buchsbaumz\u00fcnsler biologisch bek\u00e4mpfen: Bakterien, Neem-\u00d6l und Pheromonfallen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10289 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_267120389-300x200.jpeg\" alt=\"Biologisches Mittel Buchsbaumz\u00fcnsler\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_267120389-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_267120389-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_267120389-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_267120389-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_267120389-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_267120389-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Um den Buchsbaumz\u00fcnsler zu bek\u00e4mpfen, ben\u00f6tigen Sie nicht die chemische Keule, da es wirksame biologische Mittel gibt. So besteht die Chance, den Sch\u00e4dling komplett loszuwerden, ohne die Umwelt zu sch\u00e4digen. Spritzmittel mit dem Bakterium Bacillus thuringiensis bringen Sie bei trockener Witterung und Temperaturen \u00fcber 15 Grad Celsius aus. Spr\u00fchen Sie das Mittel mit hohem Druck auch in das Innere der Pflanze und wiederholen Sie den Vorgang nach 10 bis 14 Tagen. Das Bakterium wird von den Raupen gefressen und t\u00f6tet sie ab, da es sich in deren K\u00f6rpern vermehrt.<\/p>\n<p>Zus\u00e4tzlich zu den Bakterien wenden Sie Pheromonfallen an, die weibliche Sexuallockstoffe enthalten und die m\u00e4nnlichen Falter anlocken. Sie hindern die Falter nicht nur an der Vermehrung und dezimieren den Bestand, sondern die Fallen dienen auch der Kontrolle des Befalls.<\/p>\n<p>Neem\u00f6l spritzen Sie bis in das Innere der Pflanze. Es wird von den Sch\u00e4dlingen aufgenommen, verdirbt ihnen den Appetit und l\u00e4sst sie verhungern. Wiederholen Sie die Spritzung nach 10 bis 14 Tagen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Hausmittel_gegen_den_Buchsbaumzuensler_Essig_und_Schmierseife\"><\/span>Hausmittel gegen den Buchsbaumz\u00fcnsler: Essig und Schmierseife<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Eine preiswerte und umweltfreundliche Bek\u00e4mpfung des Buchsbaumz\u00fcnslers gelingt Ihnen mit Hausmitteln. Essig ist gut geeignet, wenn er mit \u00d6l kombiniert wird. Er wirkt nur gegen die Raupen. Bereiten Sie eine L\u00f6sung aus einem Liter Wasser, acht Essl\u00f6ffeln Essig und sechs Essl\u00f6ffeln Speise\u00f6l, mit der Sie den Buchsbaum bis in das Innere einspr\u00fchen.<\/p>\n<p>Geben Sie etwas Sp\u00fclmittel dazu, damit sich die Fl\u00fcssigkeiten besser vermischen. Bedecken Sie die Erde unter dem Buchsbaum unbedingt mit einer Folie, damit die L\u00f6sung nicht in den Boden gelangt und zu einer \u00dcbers\u00e4uerung f\u00fchrt. Schon nach einer halben Stunde sterben die Raupen ab. Wiederholen Sie den Vorgang nach ungef\u00e4hr zwei Wochen.<\/p>\n<p>Ebenfalls wirksam ist eine Seifenlauge aus einem Liter Wasser und 30 Millilitern Schmierseife, mit der Sie die Pflanzen einspr\u00fchen. Die Seife bringt die Raupen zum Absterben, da sie in die Atemwege gelangt. Spritzen Sie nach 10 bis 14 Tagen erneut, um die Raupen komplett zu bek\u00e4mpfen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Ansiedlung_von_Nuetzlingen_foerdern_Voegel_und_Wespen\"><\/span>Ansiedlung von N\u00fctzlingen f\u00f6rdern: V\u00f6gel und Wespen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10292 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_503513259-300x200.jpeg\" alt=\"Raupen Buchsbaumz\u00fcnsler\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_503513259-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_503513259-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_503513259-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_503513259-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_503513259-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_503513259-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Den Buchsbaumz\u00fcnsler k\u00f6nnen Sie dezimieren, indem Sie die Ansiedlung von V\u00f6geln und Wespen in Ihrem Garten f\u00f6rdern. Sperlinge, aber auch andere V\u00f6gel fressen die Raupen des Falters. Stellen Sie Nisthilfen in Ihrem Garten bereit und achten Sie auf naturnahe Bedingungen im Garten. Dulden Sie auch Wespen in Ihrem Garten, wenn sich die Nester nicht an ung\u00fcnstigen Orten befinden. Wespen sind gesch\u00fctzt und schaden nicht nur dem Buchsbaumz\u00fcnsler, sondern auch anderen Sch\u00e4dlingen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Ersatzpflanzen_fuer_Buchsbaum_wenn_Sie_den_Schaedling_nicht_loswerden\"><\/span>Ersatzpflanzen f\u00fcr Buchsbaum: wenn Sie den Sch\u00e4dling nicht loswerden<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>K\u00f6nnen Sie Ihren Buchsbaum nicht mehr retten und werden Sie den Buchsbaumz\u00fcnsler nicht los, hilft nur noch das radikale Entfernen des Buchsbaums aus Ihrem Garten. Als Alternativen zu Buchsbaum eignen sich die Japanische Stechpalme und der Bloombux als eine Art von Rhododendron. Gut geeignet sind auch Portugiesischer Lorbeer, Scheinzypresse oder Heckenmyrte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haben Sie Buchsbaum als Hecke oder Strauch in Ihrem Garten, kann Ihnen der Buchsbaumz\u00fcnsler das Leben schwer machen. Der unscheinbare Schmetterling kann schwere Sch\u00e4den anrichten und den Buchsbaum zum Absterben bringen. Es gibt aber einige M\u00f6glichkeiten, ihn wirksam zu bek\u00e4mpfen. Befall mit Buchsbaumz\u00fcnsler erkennen: auf unteren Bereich der Pflanzen achten Der Buchsbaumz\u00fcnsler ist erst seit einigen Jahren in deutschen G\u00e4rten verbreitet, wo er sich am Buchsbaum zu schaffen macht. Er wurde wahrscheinlich aus Ostasien auf Containerschiffen eingeschleppt. Im Fr\u00fchjahr paart sich der Buchsbaumz\u00fcnsler und legt im unteren Bereich der Wirtspflanze ungef\u00e4hr 150 Eier ab. Die Larven schl\u00fcpfen bei einer Temperatur von mehr als sieben Grad Celsius schon nach drei Tagen. Die Entwicklung zum fertigen Insekt verl\u00e4uft in sieben Stadien und vollzieht sich bei einer Umgebungstemperatur von mehr als 15 Grad Celsius innerhalb von zehn Wochen. Die Entwicklung von der Larve zur Raupe dauert bei 20 Grad Celsius ungef\u00e4hr drei Wochen. Sie sehen die Eier und die Larven zumeist nicht, doch sind die ungef\u00e4hr f\u00fcnf Zentimeter langen gr\u00fcnen Raupen leicht zu erkennen. Verpuppen sich die Raupen, schl\u00fcpfen ungef\u00e4hr eine Woche sp\u00e4ter die fertigen Falter. Da sie nur eine kurze Lebenserwartung haben, m\u00fcssen sie sich innerhalb kurzer Zeit vermehren. Von Fr\u00fchjahr bis [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":10291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"hersteller":[],"class_list":["post-9314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Der Buchsbaum hat den Buchsbaumz\u00fcnsler als Fein. Der Schmetterling kann erheblichen Schaden anrichten. Neem-\u00d6l kann unter anderem Abhilfe schaffen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Der Buchsbaum hat den Buchsbaumz\u00fcnsler als Fein. Der Schmetterling kann erheblichen Schaden anrichten. Neem-\u00d6l kann unter anderem Abhilfe schaffen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-08T09:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T15:13:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_460365389-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick\"},\"author\":{\"name\":\"Sabine\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\"},\"headline\":\"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick\",\"datePublished\":\"2023-03-08T09:00:16+00:00\",\"dateModified\":\"2023-08-30T15:13:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick\"},\"wordCount\":1262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Buchsbaumzuendler_460365389-scaled.jpeg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick\",\"name\":\"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Buchsbaumzuendler_460365389-scaled.jpeg\",\"datePublished\":\"2023-03-08T09:00:16+00:00\",\"dateModified\":\"2023-08-30T15:13:22+00:00\",\"description\":\"Der Buchsbaum hat den Buchsbaumz\u00fcnsler als Fein. Der Schmetterling kann erheblichen Schaden anrichten. Neem-\u00d6l kann unter anderem Abhilfe schaffen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Buchsbaumzuendler_460365389-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Buchsbaumzuendler_460365389-scaled.jpeg\",\"width\":2560,\"height\":1710,\"caption\":\"Buchsbaumz\u00fcnsler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\",\"name\":\"Sabine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"caption\":\"Sabine\"},\"description\":\"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/sabine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick - Samenhaus Gartenblog","description":"Der Buchsbaum hat den Buchsbaumz\u00fcnsler als Fein. Der Schmetterling kann erheblichen Schaden anrichten. Neem-\u00d6l kann unter anderem Abhilfe schaffen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick","og_locale":"de_DE","og_type":"article","og_title":"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick - Samenhaus Gartenblog","og_description":"Der Buchsbaum hat den Buchsbaumz\u00fcnsler als Fein. Der Schmetterling kann erheblichen Schaden anrichten. Neem-\u00d6l kann unter anderem Abhilfe schaffen.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2023-03-08T09:00:16+00:00","article_modified_time":"2023-08-30T15:13:22+00:00","og_image":[{"width":2560,"height":1710,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_460365389-scaled.jpeg","type":"image\/jpeg"}],"author":"Sabine","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Sabine","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick"},"author":{"name":"Sabine","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5"},"headline":"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick","datePublished":"2023-03-08T09:00:16+00:00","dateModified":"2023-08-30T15:13:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick"},"wordCount":1262,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_460365389-scaled.jpeg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick","url":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick","name":"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_460365389-scaled.jpeg","datePublished":"2023-03-08T09:00:16+00:00","dateModified":"2023-08-30T15:13:22+00:00","description":"Der Buchsbaum hat den Buchsbaumz\u00fcnsler als Fein. Der Schmetterling kann erheblichen Schaden anrichten. Neem-\u00d6l kann unter anderem Abhilfe schaffen.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_460365389-scaled.jpeg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Buchsbaumzuendler_460365389-scaled.jpeg","width":2560,"height":1710,"caption":"Buchsbaumz\u00fcnsler"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/buchsbaumzuensler-schadbild-und-bekaempfung-im-ueberblick#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Buchsbaumz\u00fcnsler: Schadbild und Bek\u00e4mpfung im \u00dcberblick"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5","name":"Sabine","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","caption":"Sabine"},"description":"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/sabine"}]}},"wp-worthy-pixel":{"ignored":false,"public":"fad690d4f6f54eec8175192674b79f72","server":"vg07.met.vgwort.de","url":"https:\/\/vg07.met.vgwort.de\/na\/fad690d4f6f54eec8175192674b79f72"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/9314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=9314"}],"version-history":[{"count":6,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/9314\/revisions"}],"predecessor-version":[{"id":14302,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/9314\/revisions\/14302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/10291"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=9314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=9314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=9314"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=9314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}