{"id":9381,"date":"2023-02-13T09:00:33","date_gmt":"2023-02-13T09:00:33","guid":{"rendered":"https:\/\/www.samenhaus.de\/gartenblog\/?p=9381"},"modified":"2023-08-16T10:32:04","modified_gmt":"2023-08-16T10:32:04","slug":"erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden","status":"publish","type":"post","link":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden","title":{"rendered":"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden"},"content":{"rendered":"<p>Tomaten und andere Gem\u00fcsepflanzen, aber auch Blumen werden mitunter in K\u00fcbeln oder Balkonk\u00e4sten angebaut. Die Erde m\u00fcssen Sie nicht entsorgen, auch wenn ihr viele N\u00e4hrstoffe entzogen wurden. Es gibt mehrere M\u00f6glichkeiten, die Erde noch zu verwenden und mit N\u00e4hrstoffen anzureichern.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Bei_der_Verwendung_von_Erde_beachten_Durchwurzelung_und_Struktur\"><\/span>Bei der Verwendung von Erde beachten: Durchwurzelung und Struktur<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9723 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_101522230-300x199.jpeg\" alt=\"K\u00fcbelerde verwenden\" width=\"300\" height=\"199\" \/>Es ist ein Trugschluss, dass Erde aus K\u00fcbeln oder Balkonk\u00e4sten, in der Sie in der vergangenen Saison Tomaten oder andere Gem\u00fcsepflanzen, aber auch Blumen oder Kr\u00e4uter angebaut haben, mit Krankheitserregern oder Sch\u00e4dlingen kontaminiert ist. Sie m\u00fcssen die Erde daher nicht im M\u00fcll entsorgen.<\/p>\n<p>Der Erde wurden N\u00e4hrstoffe entzogen, was auch zu einer geringeren Stabilit\u00e4t f\u00fchrt. Sie vern\u00e4sst schneller. Es ist daher wichtig, dass Sie die Erde nicht in unver\u00e4nderter Form wiederverwenden und gleich in der n\u00e4chsten Saison wieder Pflanzen darin anbauen. Bei der Wiederverwendung der Erde sollten Sie einiges beachten:<\/p>\n<ul>\n<li>Die Erde muss aufbereitet werden, um wieder mit N\u00e4hrstoffen angereichert zu werden.<\/li>\n<li>Auf keinen Fall d\u00fcrfen dieselben Pflanzen wie im Vorjahr darin kultiviert werden, denn auch in den Beeten im Garten achten Sie auf die Fruchtfolge.<\/li>\n<li>Ist die Erde stark durchwurzelt, kann sie immer noch kompostiert werden.<\/li>\n<li>Achten Sie auf die Beschaffenheit der Erde und entscheiden Sie dann \u00fcber die weitere Verwendung.<\/li>\n<\/ul>\n<p>Lediglich dann, wenn die Erde von Sch\u00e4dlingen oder Krankheiten befallen ist, muss sie entsorgt werden und geh\u00f6rt dann auch nicht mehr auf den Kompost. Die Sch\u00e4dlinge oder Krankheiten k\u00f6nnten sich \u00fcber den Kompost in die Beete ausbreiten. Das ist vor allem bei Pflanzenkrankheiten wie Kohlhernie oder Braunf\u00e4ule bei Tomaten der Fall.<\/p>\n<p><strong>Tipp:<\/strong> Auch wenn Sie die Erde aufbereiten und mit N\u00e4hrstoffen anreichern, sollten Sie in der kommenden Saison nicht die gleichen Pflanzen wie in der vorherigen Saison darin anbauen. Schnell k\u00f6nnten sich spezifische Pflanzenkrankheiten ausbreiten oder die Pflanzen unter Mangelerscheinungen leiden.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Erde_mit_Naehrstoffen_anreichern_Kompost_oder_Hornspaene\"><\/span>Erde mit N\u00e4hrstoffen anreichern: Kompost oder Hornsp\u00e4ne<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Geben Sie die Erde aus K\u00fcbeln oder Blumenk\u00e4sten in ein gro\u00dfes Gef\u00e4\u00df, beispielsweise in einen Maurerk\u00fcbel, einen Kessel oder eine Wanne. Lockern Sie sie mit einer Grabegabel gut auf. So k\u00f6nnen Sie auch noch verbliebene Wurzeln aus der Erde entfernen. Gut geeignet ist ein Sieb, beispielsweise ein Kiessieb, durch das Sie die Erde in das gro\u00dfe Gef\u00e4\u00df sieben. So wird die Erde bereits locker und kr\u00fcmelig. Wurzeln und Steine verbleiben auf dem Sieb.<\/p>\n<p>Die Erde k\u00f6nnen Sie mit Kompost mischen, um sie wieder mit N\u00e4hrstoffen anzureichern. Mischen Sie drei Teile Erde mit ungef\u00e4hr einem Teil Kompost. Gut geeignet ist auch Humus aus der Wurmkiste. Haben Sie einen Bokashi-Eimer, mischen Sie die Fl\u00fcssigkeit unter die Erde, um ihr mehr N\u00e4hrstoffe zuzuf\u00fcgen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Hornspaene_und_Urgesteinsmehl_organischer_Duenger_und_Mineralien\"><\/span>Hornsp\u00e4ne und Urgesteinsmehl: organischer D\u00fcnger und Mineralien<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9722 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_83070159-300x200.jpeg\" alt=\"K\u00fcbelerde Hornsp\u00e4ne\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_83070159-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_83070159-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_83070159-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_83070159-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_83070159-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_83070159-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Um der Erde aus K\u00fcbeln oder Blumenk\u00e4sten wieder N\u00e4hrstoffe zuzuf\u00fcgen, eignen sich auch Hornsp\u00e4ne und Urgesteinsmehl. Hornsp\u00e4ne verwenden Sie, wenn Sie die Erde f\u00fcr den Anbau von Starkzehrern nutzen m\u00f6chten. Sie sind ein organischer D\u00fcnger und verf\u00fcgen \u00fcber einen hohen Gehalt an Stickstoff. Hornsp\u00e4ne sind ein hervorragender Langzeitd\u00fcnger, der den Stickstoff nur langsam abgibt. Urgesteinsmehl reichert die Erde mit Mineralstoffen und Spurenelementen an. Es erh\u00f6ht die Widerstandskraft der Pflanzen gegen Krankheiten und f\u00f6rdert das Wachstum von Mikroorganismen.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Mehr_Struktur_fuer_die_aufbereitete_Erde_Tongranulat_oder_Perlite\"><\/span>Mehr Struktur f\u00fcr die aufbereitete Erde: Tongranulat oder Perlite<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die aufbereitete Erde hat wieder N\u00e4hrstoffe bekommen, doch mangelt es ihr noch an Struktur. Sie speichert das Wasser nicht gut und sackt schnell zusammen. Damit die Erde eine bessere Struktur bekommt und das Wasser besser speichern kann, mischen Sie sie mit frischer Erde. Durchl\u00e4ssiger wird die Erde, wenn Sie Sand unterarbeiten. Eine bessere Speicherf\u00e4higkeit bekommt die Erde mit Tongranulat oder Perlite, das Sie einarbeiten.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Verwendung_der_aufbereiteten_Erde_fuer_Beete_und_Kuebel\"><\/span>Verwendung der aufbereiteten Erde: f\u00fcr Beete und K\u00fcbel<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9724 alignright\" src=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_405521121-300x200.jpeg\" alt=\"Verwendung aufbereitete K\u00fcbelerde\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_405521121-300x200.jpeg 300w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_405521121-2048x1365.jpeg 2048w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_405521121-600x400.jpeg 600w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_405521121-768x512.jpeg 768w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_405521121-1024x683.jpeg 1024w, https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_405521121-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Die aufbereitete Erde ist f\u00fcr Beete im Garten, aber auch f\u00fcr K\u00fcbel geeignet. Sie hat wieder N\u00e4hrstoffe und eine verbesserte Struktur bekommen. Im Garten k\u00f6nnen Sie die Erde in die Beete einarbeiten, aber auch direkt auf die Beete auftragen. Die Erde kann aber auch wieder f\u00fcr K\u00fcbel verwendet werden. Sie eignet sich allein, aber auch gemischt mit frischer Erde.<\/p>\n<p>Je nachdem, was Sie anbauen m\u00f6chten, m\u00fcssen Sie die Erde zus\u00e4tzlich mit Kompost oder mit einem organischen D\u00fcnger anreichern. Bringen Sie die Erde ins Beet, ist ein Gr\u00fcnd\u00fcnger geeignet, den Sie eins\u00e4en und dann unterarbeiten. Um einen Gr\u00fcnd\u00fcnger zu s\u00e4en, m\u00fcssen Sie die Erde bereits im Herbst aufbereiten und ins Beet bringen. Der Gr\u00fcnd\u00fcnger wird im Anschluss daran ausges\u00e4t. Im Fr\u00fchjahr wird er unter die Erde gearbeitet, um die Pflanzen mit N\u00e4hrstoffen anzureichern.<\/p>\n<h2 class=\"western\"><span class=\"ez-toc-section\" id=\"Verbrauchte_Erde_verwenden_Kompostieren_oder_als_Mulch\"><\/span>Verbrauchte Erde verwenden: Kompostieren oder als Mulch<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ist die Erde stark verbraucht und verklumpt, l\u00e4sst sie sich oft nicht mehr aufbereiten. Trotzdem muss sie nicht entsorgt werden, da sie noch kompostiert werden kann. Bringen Sie die Erde als Zwischenschicht auf den Kompost und geben Sie dann gr\u00fcnes Material wie Rasenschnitt oder Obst- und Gem\u00fcseschalen darauf. Die Erde wird zu Kompost und bekommt beim Kompostieren wieder N\u00e4hrstoffe. Alternativ dazu k\u00f6nnen Sie die Erde auch als Mulch f\u00fcr Ihre Beete und empfindlichen Pflanzen verwenden. Sie sch\u00fctzt im Winter vor Frostsch\u00e4den und verhindert, dass der Boden zu stark austrocknet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tomaten und andere Gem\u00fcsepflanzen, aber auch Blumen werden mitunter in K\u00fcbeln oder Balkonk\u00e4sten angebaut. Die Erde m\u00fcssen Sie nicht entsorgen, auch wenn ihr viele N\u00e4hrstoffe entzogen wurden. Es gibt mehrere M\u00f6glichkeiten, die Erde noch zu verwenden und mit N\u00e4hrstoffen anzureichern. Bei der Verwendung von Erde beachten: Durchwurzelung und Struktur Es ist ein Trugschluss, dass Erde aus K\u00fcbeln oder Balkonk\u00e4sten, in der Sie in der vergangenen Saison Tomaten oder andere Gem\u00fcsepflanzen, aber auch Blumen oder Kr\u00e4uter angebaut haben, mit Krankheitserregern oder Sch\u00e4dlingen kontaminiert ist. Sie m\u00fcssen die Erde daher nicht im M\u00fcll entsorgen. Der Erde wurden N\u00e4hrstoffe entzogen, was auch zu einer geringeren Stabilit\u00e4t f\u00fchrt. Sie vern\u00e4sst schneller. Es ist daher wichtig, dass Sie die Erde nicht in unver\u00e4nderter Form wiederverwenden und gleich in der n\u00e4chsten Saison wieder Pflanzen darin anbauen. Bei der Wiederverwendung der Erde sollten Sie einiges beachten: Die Erde muss aufbereitet werden, um wieder mit N\u00e4hrstoffen angereichert zu werden. Auf keinen Fall d\u00fcrfen dieselben Pflanzen wie im Vorjahr darin kultiviert werden, denn auch in den Beeten im Garten achten Sie auf die Fruchtfolge. Ist die Erde stark durchwurzelt, kann sie immer noch kompostiert werden. Achten Sie auf die Beschaffenheit der Erde und entscheiden Sie dann \u00fcber die weitere [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":9725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"hersteller":[],"class_list":["post-9381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gartentipps"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden - Samenhaus Gartenblog<\/title>\n<meta name=\"description\" content=\"Nach dem Umtopfen bleibt Erde \u00fcbrig, aber was macht man damit? Mit der richtigen Aufarbeitung kann die Erde wiederverwendet werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden - Samenhaus Gartenblog\" \/>\n<meta property=\"og:description\" content=\"Nach dem Umtopfen bleibt Erde \u00fcbrig, aber was macht man damit? Mit der richtigen Aufarbeitung kann die Erde wiederverwendet werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden\" \/>\n<meta property=\"og:site_name\" content=\"Samenhaus Gartenblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/samenhaus\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-13T09:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-16T10:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:site\" content=\"@samenhaus\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden\"},\"author\":{\"name\":\"Sabine\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\"},\"headline\":\"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden\",\"datePublished\":\"2023-02-13T09:00:33+00:00\",\"dateModified\":\"2023-08-16T10:32:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden\"},\"wordCount\":917,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg\",\"articleSection\":[\"Gartentipps\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden\",\"name\":\"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden - Samenhaus Gartenblog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg\",\"datePublished\":\"2023-02-13T09:00:33+00:00\",\"dateModified\":\"2023-08-16T10:32:04+00:00\",\"description\":\"Nach dem Umtopfen bleibt Erde \u00fcbrig, aber was macht man damit? Mit der richtigen Aufarbeitung kann die Erde wiederverwendet werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg\",\"width\":2560,\"height\":1706,\"caption\":\"K\u00fcbelerde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#website\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"name\":\"Samenhaus Gartenblog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#organization\",\"name\":\"Samenhaus.de Gartenblog\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Samenhaus.de Gartenblog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/samenhaus\",\"https:\\\/\\\/x.com\\\/samenhaus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/#\\\/schema\\\/person\\\/e4c837ea32ec74c39497c1e69976fed5\",\"name\":\"Sabine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sabine-150x150.png\",\"caption\":\"Sabine\"},\"description\":\"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.\",\"url\":\"https:\\\/\\\/www.samenhaus.de\\\/gartenblog\\\/author\\\/sabine\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden - Samenhaus Gartenblog","description":"Nach dem Umtopfen bleibt Erde \u00fcbrig, aber was macht man damit? Mit der richtigen Aufarbeitung kann die Erde wiederverwendet werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden","og_locale":"de_DE","og_type":"article","og_title":"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden - Samenhaus Gartenblog","og_description":"Nach dem Umtopfen bleibt Erde \u00fcbrig, aber was macht man damit? Mit der richtigen Aufarbeitung kann die Erde wiederverwendet werden.","og_url":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden","og_site_name":"Samenhaus Gartenblog","article_publisher":"https:\/\/de-de.facebook.com\/samenhaus","article_published_time":"2023-02-13T09:00:33+00:00","article_modified_time":"2023-08-16T10:32:04+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg","type":"image\/jpeg"}],"author":"Sabine","twitter_card":"summary_large_image","twitter_creator":"@samenhaus","twitter_site":"@samenhaus","twitter_misc":{"Verfasst von":"Sabine","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#article","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden"},"author":{"name":"Sabine","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5"},"headline":"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden","datePublished":"2023-02-13T09:00:33+00:00","dateModified":"2023-08-16T10:32:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden"},"wordCount":917,"commentCount":0,"publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg","articleSection":["Gartentipps"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden","url":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden","name":"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden - Samenhaus Gartenblog","isPartOf":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage"},"thumbnailUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg","datePublished":"2023-02-13T09:00:33+00:00","dateModified":"2023-08-16T10:32:04+00:00","description":"Nach dem Umtopfen bleibt Erde \u00fcbrig, aber was macht man damit? Mit der richtigen Aufarbeitung kann die Erde wiederverwendet werden.","breadcrumb":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#primaryimage","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2023\/02\/Kuebelerde-wiederverwenden_484336636-scaled.jpeg","width":2560,"height":1706,"caption":"K\u00fcbelerde"},{"@type":"BreadcrumbList","@id":"https:\/\/www.samenhaus.de\/gartenblog\/erde-in-kuebeln-moeglichkeiten-sie-wiederzuverwenden#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.samenhaus.de\/gartenblog\/"},{"@type":"ListItem","position":2,"name":"Erde in K\u00fcbeln: M\u00f6glichkeiten, sie wiederzuverwenden"}]},{"@type":"WebSite","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#website","url":"https:\/\/www.samenhaus.de\/gartenblog\/","name":"Samenhaus Gartenblog","description":"","publisher":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.samenhaus.de\/gartenblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#organization","name":"Samenhaus.de Gartenblog","url":"https:\/\/www.samenhaus.de\/gartenblog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2020\/11\/logo.svg","width":1,"height":1,"caption":"Samenhaus.de Gartenblog"},"image":{"@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/samenhaus","https:\/\/x.com\/samenhaus"]},{"@type":"Person","@id":"https:\/\/www.samenhaus.de\/gartenblog\/#\/schema\/person\/e4c837ea32ec74c39497c1e69976fed5","name":"Sabine","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","url":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","contentUrl":"https:\/\/www.samenhaus.de\/gartenblog\/wp-content\/uploads\/2026\/03\/sabine-150x150.png","caption":"Sabine"},"description":"Sabine schreibt am liebsten \u00fcber Themen rund um den Selbstversorgergarten. Ob Gem\u00fcseanbau, Obstgarten, H\u00fchnerhaltung oder Konservierung und Verarbeitung, sie hat jede Menge eigene Erfahrung beizusteuern. Sie liebt es, den Blick \u00fcber die ersten zarten Pflanzen des Jahres schweifen zu lassen oder die gewaltige Ernte im Sommer und Herbst zu b\u00e4ndigen.","url":"https:\/\/www.samenhaus.de\/gartenblog\/author\/sabine"}]}},"wp-worthy-pixel":{"ignored":false,"public":"ef24badccb9842c3a55ce0797eceb40c","server":"vg07.met.vgwort.de","url":"https:\/\/vg07.met.vgwort.de\/na\/ef24badccb9842c3a55ce0797eceb40c"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/9381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/comments?post=9381"}],"version-history":[{"count":6,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/9381\/revisions"}],"predecessor-version":[{"id":13090,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/posts\/9381\/revisions\/13090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media\/9725"}],"wp:attachment":[{"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/media?parent=9381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/categories?post=9381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/tags?post=9381"},{"taxonomy":"hersteller","embeddable":true,"href":"https:\/\/www.samenhaus.de\/gartenblog\/wp-json\/wp\/v2\/hersteller?post=9381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}